{"id":19,"date":"2023-12-28T04:48:16","date_gmt":"2023-12-28T04:48:16","guid":{"rendered":"https:\/\/staging.accordglobaltrade.com\/?page_id=19"},"modified":"2024-09-05T04:14:14","modified_gmt":"2024-09-05T04:14:14","slug":"home","status":"publish","type":"page","link":"https:\/\/staging.accordglobaltrade.com\/tr\/","title":{"rendered":"Ev"},"content":{"rendered":"\n<div class=\"wp-block-uagb-container uagb-block-41abe729 alignfull uagb-is-root-container\">\n\t\t\t\t<p class=\"rs-p-wp-fix\"><\/p>\n\t\t\t\t<sr7-module data-alias=\"pathfinder\" data-id=\"1\" id=\"SR7_1_1\" data-version=\"6.7.58\">\n\t\t\t\t\t<sr7-adjuster><\/sr7-adjuster>\n\t\t\t\t\t<sr7-content>\n\t\t\t\t\t\t<sr7-slide id=\"SR7_1_1-1\" data-key=\"1\">\n\t\t\t\t\t\t\t<sr7-bg id=\"SR7_1_1-1-slidebg\" class=\"sr7-layer\"><noscript><img decoding=\"async\" src=\"https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/revslider\/pathfinder\/banner-home-1-mask.jpg\" alt=\"\" title=\"banner-home-1-mask.jpg\"><\/noscript><\/sr7-bg>\n\t\t\t\t\t\t\t<sr7-txt id=\"SR7_1_1-1-9\" class=\"sr7-layer\">We provide businesses with proven expertise, tailored solutions, and services to help make <br \/>\nbetter trade decisions that minimize foreign trade risks by safely and reliably <br \/>\nexporting and importing commodities & products on a global scale.<\/sr7-txt>\n\t\t\t\t\t\t\t<sr7-txt id=\"SR7_1_1-1-10\" class=\"sr7-layer\">Learn More<\/sr7-txt>\n\t\t\t\t\t\t\t<sr7-txt id=\"SR7_1_1-1-13\" class=\"sr7-layer\">Facilitating<br \/>\nInternational Trade<\/sr7-txt>\n\t\t\t\t\t\t<\/sr7-slide>\n\t\t\t\t\t\t<sr7-slide id=\"SR7_1_1-2\" data-key=\"2\">\n\t\t\t\t\t\t\t<sr7-bg id=\"SR7_1_1-2-slidebg\" class=\"sr7-layer\"><noscript><img decoding=\"async\" src=\"https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/revslider\/pathfinder\/slide2-min-mask.jpg\" alt=\"\" title=\"slide2-min-mask.jpg\"><\/noscript><\/sr7-bg>\n\t\t\t\t\t\t\t<sr7-txt id=\"SR7_1_1-2-4\" class=\"sr7-layer\">Gain a competitive edge and create sustainable growth by exporting <br \/>\nyour commodities, products, or excess production inventory <br \/>\nto new markets worldwide.<\/sr7-txt>\n\t\t\t\t\t\t\t<sr7-txt id=\"SR7_1_1-2-10\" class=\"sr7-layer\">Learn More<\/sr7-txt>\n\t\t\t\t\t\t\t<sr7-txt id=\"SR7_1_1-2-13\" class=\"sr7-layer\">Exporting Goods<\/sr7-txt>\n\t\t\t\t\t\t<\/sr7-slide>\n\t\t\t\t\t\t<sr7-slide id=\"SR7_1_1-3\" data-key=\"3\">\n\t\t\t\t\t\t\t<sr7-bg id=\"SR7_1_1-3-slidebg\" class=\"sr7-layer\"><noscript><img decoding=\"async\" src=\"https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/revslider\/pathfinder\/Depositphotos_361319978_L-1-minim.jpg\" alt=\"\" title=\"Depositphotos_361319978_L-1-minim.jpg\"><\/noscript><\/sr7-bg>\n\t\t\t\t\t\t\t<sr7-txt id=\"SR7_1_1-3-5\" class=\"sr7-layer\">Grew your trade business and increase your buying power with revenue from new sales <br \/>\nby importing commodities &amp; products from global markets.<\/sr7-txt>\n\t\t\t\t\t\t\t<sr7-txt id=\"SR7_1_1-3-10\" class=\"sr7-layer\">Learn More<\/sr7-txt>\n\t\t\t\t\t\t\t<sr7-txt id=\"SR7_1_1-3-13\" class=\"sr7-layer\">Importing Goods<\/sr7-txt>\n\t\t\t\t\t\t<\/sr7-slide>\n\t\t\t\t\t\t<sr7-slide id=\"SR7_1_1-6\" data-key=\"6\">\n\t\t\t\t\t\t<\/sr7-slide>\n\t\t\t\t\t<\/sr7-content>\n\t\t\t\t<\/sr7-module>\n\t\t\t\t<script>\n\t\t\t\t\twindow.SR7 ??={};SR7.PMH ??={}; SR7.PMH[\"SR7_1_1\"] = {cn:100,state:false,fn: function() { if (window._tpt!==undefined && window._tpt.prepareModuleHeight !== undefined) {  _tpt.prepareModuleHeight({id:\"SR7_1_1\",el:[810,649.988,479.988,479.988],type:'standard',shdw:'0',gh:[810,650,480,480],gw:[1920,1440,778,480],vpt:['-200px'],size:{fullWidth:true, fullHeight:true},offsetContainer:'',offset:'',mh:'0',onh:0,onw:0,bg:{color:'transparent'}});   SR7.PMH[\"SR7_1_1\"].state=true;} else if(SR7.PMH[\"SR7_1_1\"].cn-->0)\tsetTimeout( SR7.PMH[\"SR7_1_1\"].fn,19);}};SR7.PMH[\"SR7_1_1\" ].fn();\n\t\t\t\t<\/script>\n\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container ic-markets-wrapper uagb-block-44572301 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-d969377a\"><h2 class=\"uagb-heading-text\">Entrepreneurs in Emerging Markets<\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-c204dab9\"><p class=\"uagb-heading-text\">We are Buyers and Sellers of Exportable &amp; Importable Goods and Experts in Managing International Trade Risks. We help exporters gain access to new foreign markets and importers to locate sought-after commodities &amp; products.<\/p><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container ic-export-import-wrapper uagb-block-1fa6aee9 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-0cd02049\"><h2 class=\"uagb-heading-text\">Exporting &amp; Importing<\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-15f800a4\"><p class=\"uagb-heading-text\">We specialize in providing solutions &amp; services to both exporters and importers, connecting our clients with global markets.<\/p><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-2709eace wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column has-background is-layout-flow wp-block-column-is-layout-flow\" style=\"background-color:#ffffff00;padding-top:0;padding-right:0;padding-bottom:0;padding-left:0\">\n<div class=\"wp-block-cover\" style=\"border-radius:15px;min-height:280px;aspect-ratio:unset;\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-0 has-background-dim\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"2160\" height=\"1064\" class=\"wp-block-cover__image-background wp-image-296\" alt=\"\" src=\"https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2024\/01\/competitive-advantages-banner.jpg\" data-object-fit=\"cover\" srcset=\"https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2024\/01\/competitive-advantages-banner.jpg 2160w, https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2024\/01\/competitive-advantages-banner-300x148.jpg 300w, https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2024\/01\/competitive-advantages-banner-1024x504.jpg 1024w, https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2024\/01\/competitive-advantages-banner-768x378.jpg 768w, https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2024\/01\/competitive-advantages-banner-1536x757.jpg 1536w, https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2024\/01\/competitive-advantages-banner-2048x1009.jpg 2048w, https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2024\/01\/competitive-advantages-banner-18x9.jpg 18w\" sizes=\"auto, (max-width: 2160px) 100vw, 2160px\" \/><div class=\"wp-block-cover__inner-container is-layout-constrained wp-block-cover-is-layout-constrained\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-12a8fe6e\"><h2 class=\"uagb-heading-text\">Exporting Goods<\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-529bed5b\"><h2 class=\"uagb-heading-text\">If you are an Exporter (Ultimate Supplier) looking to export your commodities or products<\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-b5f3efe9\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-4eb9cfab wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"https:\/\/staging.accordglobaltrade.com\/exporting-goods\/\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">Start Exporting Today<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column has-background is-layout-flow wp-block-column-is-layout-flow\" style=\"background-color:#ffffff00;padding-top:0;padding-right:0;padding-bottom:0;padding-left:0\">\n<div class=\"wp-block-cover\" style=\"border-radius:15px;min-height:280px;aspect-ratio:unset;\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"600\" class=\"wp-block-cover__image-background wp-image-170\" alt=\"\" src=\"https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2023\/12\/import-trade.jpg\" data-object-fit=\"cover\" srcset=\"https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2023\/12\/import-trade.jpg 960w, https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2023\/12\/import-trade-300x188.jpg 300w, https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2023\/12\/import-trade-768x480.jpg 768w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><div class=\"wp-block-cover__inner-container is-layout-constrained wp-block-cover-is-layout-constrained\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-37120996\"><h2 class=\"uagb-heading-text\">Importing Goods<\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3fa33b75\"><h2 class=\"uagb-heading-text\">If you are an Importer (Ultimate Buyer) looking to import commodities or products<\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-3114da5a\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-e63aabc4 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"https:\/\/staging.accordglobaltrade.com\/importing-goods\/\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">Start Importing Today<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container ic-nation-trade-services uagb-block-71fce647 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-9e753b84\"><h2 class=\"uagb-heading-text\">International Trade Services<\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-c8928e78\"><p class=\"uagb-heading-text\">Specializing in international trade consulting, trade agency representation, supply chain management, and trade regulatory compliance.<\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-0a1b82a2\">\n<div class=\"wp-block-uagb-container ic-trade-service-item uagb-block-7f6d21c2\">\n<div class=\"wp-block-uagb-image aligncenter uagb-block-ee3fc18b wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-center\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" src=\"https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2024\/02\/consulting-300x300-3.png\" alt=\"\" class=\"uag-image-1104\" width=\"63\" height=\"63\" title=\"\" loading=\"lazy\" role=\"img\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-1469f899\"><h2 class=\"uagb-heading-text\">International Trade Consulting<\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-a1ec0e75\"><p class=\"uagb-heading-text\">Import and export consulting services to guide you through the entire trade process.<\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-f07ced51\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-786b5a71 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">Learn More<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<a class=\"spectra-container-link-overlay\" rel=\"noopener\" href=\"https:\/\/staging.accordglobaltrade.com\/international-trade-consulting\/\"> <\/a><\/div>\n\n\n\n<div class=\"wp-block-uagb-container ic-trade-service-item uagb-block-7459a9cf\">\n<div class=\"wp-block-uagb-image aligncenter uagb-block-141f4801 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-center\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" src=\"https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2024\/02\/consulting-300x300-1.png\" alt=\"\" class=\"uag-image-1116\" width=\"63\" height=\"63\" title=\"\" loading=\"lazy\" role=\"img\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-f0579925\"><h2 class=\"uagb-heading-text\">Trade Agency Representation<\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-80ef0c69\"><p class=\"uagb-heading-text\">Representation for producers, suppliers, manufacturers, and end buyers in the international marketplace.<\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-062a311b\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-0b9255f8 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">Learn More<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<a class=\"spectra-container-link-overlay\" rel=\"noopener\" href=\"https:\/\/staging.accordglobaltrade.com\/trade-agency-representation\/\"> <\/a><\/div>\n\n\n\n<div class=\"wp-block-uagb-container ic-trade-service-item uagb-block-3e0ad83d\">\n<div class=\"wp-block-uagb-image aligncenter uagb-block-4788ca6b wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-center\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" src=\"https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2024\/02\/consulting-300x300-2.png\" alt=\"\" class=\"uag-image-1117\" width=\"63\" height=\"63\" title=\"\" loading=\"lazy\" role=\"img\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-1ae13353\"><h2 class=\"uagb-heading-text\">Supply Chain Management<\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-c184aee7\"><p class=\"uagb-heading-text\">Supply chain solutions designed to optimize efficiency, while managing associated costs.<\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-c8d0d2a3\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-0ad08212 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">Learn More<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<a class=\"spectra-container-link-overlay\" rel=\"noopener\" href=\"https:\/\/staging.accordglobaltrade.com\/supply-chain-management\/\"> <\/a><\/div>\n\n\n\n<div class=\"wp-block-uagb-container ic-trade-service-item uagb-block-e99beffd\">\n<div class=\"wp-block-uagb-image aligncenter uagb-block-b488c6c6 wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-center\"><figure class=\"wp-block-uagb-image__figure\"><img decoding=\"async\" src=\"https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2024\/02\/consulting-300x300-3-1.png\" alt=\"\" class=\"uag-image-1118\" width=\"63\" height=\"63\" title=\"\" loading=\"lazy\" role=\"img\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-fa6b4846\"><h2 class=\"uagb-heading-text\">Trade Regulatory Compliance<\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-2d72864e\"><p class=\"uagb-heading-text\">Compliance with customs clearance and any applicable international rules and regulations.<\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-5b55a0a4\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap \">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-5ac5155c wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"#\" rel=\"follow noopener\" target=\"_self\" role=\"button\"><div class=\"uagb-button__link\">Learn More<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<a class=\"spectra-container-link-overlay\" rel=\"noopener\" href=\"https:\/\/staging.accordglobaltrade.com\/trade-regulatory-compliance\/\"> <\/a><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container ic-trade-blog uagb-block-c31d078c alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-159ab93a\"><h2 class=\"uagb-heading-text\">International Trade Blog<\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-027d72db\"><p class=\"uagb-heading-text\">Insights, Tips, News &amp; Events<\/p><\/div>\n\n\n\n\t\t\t<div class=\"wp-block-uagb-post-grid uagb-post-grid  uagb-post__image-position-top uagb-post__image-enabled uagb-block-e81fa8c9     uagb-post__items uagb-post__columns-3 is-grid uagb-post__columns-tablet-2 uagb-post__columns-mobile-1 uagb-post__equal-height\" data-total=\"1\" style=\"\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<article class=\"uagb-post__inner-wrap\">\t\t\t\t\t\t\t\t<div class='uagb-post__image'>\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/staging.accordglobaltrade.com\/tr\/international-trade-and-commodity-exchanges\/\" target=\"_self\" rel=\"bookmark noopener noreferrer\" class='uagb-image-ratio-2-3'><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2023\/12\/trade-services.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2023\/12\/trade-services.jpg 1024w, https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2023\/12\/trade-services-300x200.jpg 300w, https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2023\/12\/trade-services-768x512.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<h4 class=\"uagb-post__title uagb-post__text\">\n\t\t\t\t<a href=\"https:\/\/staging.accordglobaltrade.com\/tr\/international-trade-and-commodity-exchanges\/\" target=\"_self\" rel=\"bookmark noopener noreferrer\">International Trade and Commodity Exchanges<\/a>\n\t\t\t<\/h4>\n\t\t\t\t\t\t<div class='uagb-post__text uagb-post-grid-byline'>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class='uagb-post__text uagb-post__excerpt'>\n\t\t\t\t\tWhen buying or selling goods internationally, both importers and exporters should be familiar with a commodities exchange. A commodities exchange&#8230;\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"uagb-post__text uagb-post__cta wp-block-button\">\n\t\t\t\t<a class=\"wp-block-button__link uagb-text-link\" style=\"\" href=\"https:\/\/staging.accordglobaltrade.com\/tr\/international-trade-and-commodity-exchanges\/\" target=\"_self\" rel=\"bookmark noopener noreferrer\">Read More<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t\t\t\t<\/article>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<article class=\"uagb-post__inner-wrap\">\t\t\t\t\t\t\t\t<div class='uagb-post__image'>\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/staging.accordglobaltrade.com\/tr\/lowering-supply-chain-costs-with-operational-efficiency\/\" target=\"_self\" rel=\"bookmark noopener noreferrer\" class='uagb-image-ratio-2-3'><img loading=\"lazy\" decoding=\"async\" width=\"1170\" height=\"659\" src=\"https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2023\/12\/supply-chain-content-2-1170x659-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2023\/12\/supply-chain-content-2-1170x659-1.jpg 1170w, https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2023\/12\/supply-chain-content-2-1170x659-1-300x169.jpg 300w, https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2023\/12\/supply-chain-content-2-1170x659-1-1024x577.jpg 1024w, https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2023\/12\/supply-chain-content-2-1170x659-1-768x433.jpg 768w\" sizes=\"auto, (max-width: 1170px) 100vw, 1170px\" \/>\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<h4 class=\"uagb-post__title uagb-post__text\">\n\t\t\t\t<a href=\"https:\/\/staging.accordglobaltrade.com\/tr\/lowering-supply-chain-costs-with-operational-efficiency\/\" target=\"_self\" rel=\"bookmark noopener noreferrer\">Lowering Supply Chain Costs with Operational Efficiency<\/a>\n\t\t\t<\/h4>\n\t\t\t\t\t\t<div class='uagb-post__text uagb-post-grid-byline'>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class='uagb-post__text uagb-post__excerpt'>\n\t\t\t\t\tWhen creating the supply chain and operational logistics involved with international trade, costs can skyrocket when interruptions to the supply&#8230;\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"uagb-post__text uagb-post__cta wp-block-button\">\n\t\t\t\t<a class=\"wp-block-button__link uagb-text-link\" style=\"\" href=\"https:\/\/staging.accordglobaltrade.com\/tr\/lowering-supply-chain-costs-with-operational-efficiency\/\" target=\"_self\" rel=\"bookmark noopener noreferrer\">Read More<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t\t\t\t<\/article>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<article class=\"uagb-post__inner-wrap\">\t\t\t\t\t\t\t\t<div class='uagb-post__image'>\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/staging.accordglobaltrade.com\/tr\/a-guide-for-import-regulations-in-the-middle-east\/\" target=\"_self\" rel=\"bookmark noopener noreferrer\" class='uagb-image-ratio-2-3'><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2023\/12\/import-trading-content-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2023\/12\/import-trading-content-2.jpg 1024w, https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2023\/12\/import-trading-content-2-300x200.jpg 300w, https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2023\/12\/import-trading-content-2-768x512.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<h4 class=\"uagb-post__title uagb-post__text\">\n\t\t\t\t<a href=\"https:\/\/staging.accordglobaltrade.com\/tr\/a-guide-for-import-regulations-in-the-middle-east\/\" target=\"_self\" rel=\"bookmark noopener noreferrer\">A Guide for Import Regulations in te Middle East<\/a>\n\t\t\t<\/h4>\n\t\t\t\t\t\t<div class='uagb-post__text uagb-post-grid-byline'>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class='uagb-post__text uagb-post__excerpt'>\n\t\t\t\t\tInterested in the import \/ export regulations of the Middle East? We have put together a brief guide to help you understand the basics of&#8230;\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"uagb-post__text uagb-post__cta wp-block-button\">\n\t\t\t\t<a class=\"wp-block-button__link uagb-text-link\" style=\"\" href=\"https:\/\/staging.accordglobaltrade.com\/tr\/a-guide-for-import-regulations-in-the-middle-east\/\" target=\"_self\" rel=\"bookmark noopener noreferrer\">Read More<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t\t\t\t<\/article>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Entrepreneurs in Emerging Markets We are Buyers and Sellers of Exportable &amp; Importable Goods and Experts in Managing International Trade Risks. We help exporters gain access to new foreign markets and importers to locate sought-after commodities &amp; products. Exporting &amp; Importing We specialize in providing solutions &amp; services to both exporters and importers, connecting our [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-19","page","type-page","status-publish","hentry"],"spectra_custom_meta":{"_edit_lock":["1725512898:1"],"_edit_last":["1"],"footnotes":[""],"_uagb_previous_block_counts":["a:90:{s:21:\"uagb\/advanced-heading\";i:20;s:15:\"uagb\/blockquote\";i:0;s:12:\"uagb\/buttons\";i:6;s:18:\"uagb\/buttons-child\";i:6;s:19:\"uagb\/call-to-action\";i:0;s:15:\"uagb\/cf7-styler\";i:0;s:11:\"uagb\/column\";i:0;s:12:\"uagb\/columns\";i:0;s:14:\"uagb\/container\";i:10;s:21:\"uagb\/content-timeline\";i:0;s:27:\"uagb\/content-timeline-child\";i:0;s:14:\"uagb\/countdown\";i:0;s:12:\"uagb\/counter\";i:0;s:8:\"uagb\/faq\";i:0;s:14:\"uagb\/faq-child\";i:0;s:10:\"uagb\/forms\";i:0;s:17:\"uagb\/forms-accept\";i:0;s:19:\"uagb\/forms-checkbox\";i:0;s:15:\"uagb\/forms-date\";i:0;s:16:\"uagb\/forms-email\";i:0;s:17:\"uagb\/forms-hidden\";i:0;s:15:\"uagb\/forms-name\";i:0;s:16:\"uagb\/forms-phone\";i:0;s:16:\"uagb\/forms-radio\";i:0;s:17:\"uagb\/forms-select\";i:0;s:19:\"uagb\/forms-textarea\";i:0;s:17:\"uagb\/forms-toggle\";i:0;s:14:\"uagb\/forms-url\";i:0;s:14:\"uagb\/gf-styler\";i:0;s:15:\"uagb\/google-map\";i:0;s:11:\"uagb\/how-to\";i:0;s:16:\"uagb\/how-to-step\";i:0;s:9:\"uagb\/icon\";i:0;s:14:\"uagb\/icon-list\";i:0;s:20:\"uagb\/icon-list-child\";i:0;s:10:\"uagb\/image\";i:4;s:18:\"uagb\/image-gallery\";i:0;s:13:\"uagb\/info-box\";i:0;s:18:\"uagb\/inline-notice\";i:0;s:11:\"uagb\/lottie\";i:0;s:21:\"uagb\/marketing-button\";i:0;s:10:\"uagb\/modal\";i:0;s:18:\"uagb\/popup-builder\";i:0;s:16:\"uagb\/post-button\";i:0;s:18:\"uagb\/post-carousel\";i:0;s:17:\"uagb\/post-excerpt\";i:0;s:14:\"uagb\/post-grid\";i:1;s:15:\"uagb\/post-image\";i:0;s:17:\"uagb\/post-masonry\";i:0;s:14:\"uagb\/post-meta\";i:0;s:18:\"uagb\/post-taxonomy\";i:0;s:18:\"uagb\/post-timeline\";i:0;s:15:\"uagb\/post-title\";i:0;s:20:\"uagb\/restaurant-menu\";i:0;s:26:\"uagb\/restaurant-menu-child\";i:0;s:11:\"uagb\/review\";i:0;s:12:\"uagb\/section\";i:0;s:14:\"uagb\/separator\";i:0;s:11:\"uagb\/slider\";i:0;s:17:\"uagb\/slider-child\";i:0;s:17:\"uagb\/social-share\";i:0;s:23:\"uagb\/social-share-child\";i:0;s:16:\"uagb\/star-rating\";i:0;s:23:\"uagb\/sure-cart-checkout\";i:0;s:22:\"uagb\/sure-cart-product\";i:0;s:15:\"uagb\/sure-forms\";i:0;s:22:\"uagb\/table-of-contents\";i:0;s:9:\"uagb\/tabs\";i:0;s:15:\"uagb\/tabs-child\";i:0;s:18:\"uagb\/taxonomy-list\";i:0;s:9:\"uagb\/team\";i:0;s:16:\"uagb\/testimonial\";i:0;s:14:\"uagb\/wp-search\";i:0;s:19:\"uagb\/instagram-feed\";i:0;s:10:\"uagb\/login\";i:0;s:17:\"uagb\/loop-builder\";i:0;s:18:\"uagb\/loop-category\";i:0;s:20:\"uagb\/loop-pagination\";i:0;s:15:\"uagb\/loop-reset\";i:0;s:16:\"uagb\/loop-search\";i:0;s:14:\"uagb\/loop-sort\";i:0;s:17:\"uagb\/loop-wrapper\";i:0;s:13:\"uagb\/register\";i:0;s:19:\"uagb\/register-email\";i:0;s:24:\"uagb\/register-first-name\";i:0;s:23:\"uagb\/register-last-name\";i:0;s:22:\"uagb\/register-password\";i:0;s:30:\"uagb\/register-reenter-password\";i:0;s:19:\"uagb\/register-terms\";i:0;s:22:\"uagb\/register-username\";i:0;}"],"_uag_css_file_name":["uag-css-19.css"],"_uag_js_file_name":["uag-js-19.js"],"_uagb_last_spectra_edit":["1776993643"],"_uag_page_assets":["a:9:{s:3:\"css\";s:131342:\".wp-block-uagb-container{display:flex;position:relative;box-sizing:border-box;transition-property:box-shadow;transition-duration:.2s;transition-timing-function:ease}.wp-block-uagb-container .spectra-container-link-overlay{bottom:0;left:0;position:absolute;right:0;top:0;z-index:10}.wp-block-uagb-container.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:flex;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}.wp-block-uagb-container .wp-block-uagb-blockquote,.wp-block-uagb-container .wp-block-spectra-pro-login,.wp-block-uagb-container .wp-block-spectra-pro-register{margin:unset}.wp-block-uagb-container .uagb-container__video-wrap{height:100%;width:100%;top:0;left:0;position:absolute;overflow:hidden;-webkit-transition:opacity 1s;-o-transition:opacity 1s;transition:opacity 1s}.wp-block-uagb-container .uagb-container__video-wrap video{max-width:100%;width:100%;height:100%;margin:0;line-height:1;border:none;display:inline-block;vertical-align:baseline;-o-object-fit:cover;object-fit:cover;background-size:cover}.wp-block-uagb-container.uagb-layout-grid{display:grid;width:100%}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap{display:inherit;width:inherit}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.alignwide.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:inherit;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-info-box),body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap,body .wp-block-uagb-container>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-container-link-overlay):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-faq__outer-wrap){min-width:unset !important;width:100%;position:relative}body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container ol,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap ol{max-width:-webkit-fill-available;margin-block-start:0;margin-block-end:0;margin-left:20px}.ast-plain-container .editor-styles-wrapper .block-editor-block-list__layout.is-root-container .uagb-is-root-container.wp-block-uagb-container.alignwide{margin-left:auto;margin-right:auto}.uagb-container__shape{overflow:hidden;position:absolute;left:0;width:100%;line-height:0;direction:ltr}.uagb-container__shape-top{top:-3px}.uagb-container__shape-bottom{bottom:-3px}.uagb-container__shape.uagb-container__invert.uagb-container__shape-bottom,.uagb-container__shape.uagb-container__invert.uagb-container__shape-top{-webkit-transform:rotate(180deg);-ms-transform:rotate(180deg);transform:rotate(180deg)}.uagb-container__shape.uagb-container__shape-flip svg{transform:translateX(-50%) rotateY(180deg)}.uagb-container__shape svg{display:block;width:-webkit-calc(100% + 1.3px);width:calc(100% + 1.3px);position:relative;left:50%;-webkit-transform:translateX(-50%);-ms-transform:translateX(-50%);transform:translateX(-50%)}.uagb-container__shape .uagb-container__shape-fill{-webkit-transform-origin:center;-ms-transform-origin:center;transform-origin:center;-webkit-transform:rotateY(0deg);transform:rotateY(0deg)}.uagb-container__shape.uagb-container__shape-above-content{z-index:9;pointer-events:none}.nv-single-page-wrap .nv-content-wrap.entry-content .wp-block-uagb-container.alignfull{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw)}@media only screen and (max-width: 767px){.wp-block-uagb-container .wp-block-uagb-advanced-heading{width:-webkit-fill-available}}.wp-block-uagb-image--align-none{justify-content:center}.wp-block-uagb-advanced-heading h1,.wp-block-uagb-advanced-heading h2,.wp-block-uagb-advanced-heading h3,.wp-block-uagb-advanced-heading h4,.wp-block-uagb-advanced-heading h5,.wp-block-uagb-advanced-heading h6,.wp-block-uagb-advanced-heading p,.wp-block-uagb-advanced-heading div{word-break:break-word}.wp-block-uagb-advanced-heading .uagb-heading-text{margin:0}.wp-block-uagb-advanced-heading .uagb-desc-text{margin:0}.wp-block-uagb-advanced-heading .uagb-separator{font-size:0;border-top-style:solid;display:inline-block;margin:0 0 10px 0}.wp-block-uagb-advanced-heading .uagb-highlight{color:#f78a0c;border:0;transition:all .3s ease}.uag-highlight-toolbar{border-left:0;border-top:0;border-bottom:0;border-radius:0;border-right-color:#1e1e1e}.uag-highlight-toolbar .components-button{border-radius:0;outline:none}.uag-highlight-toolbar .components-button.is-primary{color:#fff}.uagb-buttons__outer-wrap .uagb-buttons__wrap{display:inline-flex;width:100%}.uagb-buttons__outer-wrap.uagb-btn__small-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__small-btn .uagb-buttons-repeater.ast-outline-button{padding:5px 10px}.uagb-buttons__outer-wrap.uagb-btn__medium-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__medium-btn .uagb-buttons-repeater.ast-outline-button{padding:12px 24px}.uagb-buttons__outer-wrap.uagb-btn__large-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__large-btn .uagb-buttons-repeater.ast-outline-button{padding:20px 30px}.uagb-buttons__outer-wrap.uagb-btn__extralarge-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__extralarge-btn .uagb-buttons-repeater.ast-outline-button{padding:30px 65px}@media(max-width: 976px){.uagb-buttons__outer-wrap.uagb-btn-tablet__small-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__small-btn .uagb-buttons-repeater.ast-outline-button{padding:5px 10px}.uagb-buttons__outer-wrap.uagb-btn-tablet__medium-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__medium-btn .uagb-buttons-repeater.ast-outline-button{padding:12px 24px}.uagb-buttons__outer-wrap.uagb-btn-tablet__large-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__large-btn .uagb-buttons-repeater.ast-outline-button{padding:20px 30px}.uagb-buttons__outer-wrap.uagb-btn-tablet__extralarge-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__extralarge-btn .uagb-buttons-repeater.ast-outline-button{padding:30px 65px}}@media(max-width: 767px){.uagb-buttons__outer-wrap.uagb-btn-mobile__small-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__small-btn .uagb-buttons-repeater.ast-outline-button{padding:5px 10px}.uagb-buttons__outer-wrap.uagb-btn-mobile__medium-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__medium-btn .uagb-buttons-repeater.ast-outline-button{padding:12px 24px}.uagb-buttons__outer-wrap.uagb-btn-mobile__large-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__large-btn .uagb-buttons-repeater.ast-outline-button{padding:20px 30px}.uagb-buttons__outer-wrap.uagb-btn-mobile__extralarge-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__extralarge-btn .uagb-buttons-repeater.ast-outline-button{padding:30px 65px}}.uagb-buttons__outer-wrap .uagb-buttons-repeater{display:flex;justify-content:center;align-items:center;transition:box-shadow .2s ease}.uagb-buttons__outer-wrap .uagb-buttons-repeater a.uagb-button__link{display:flex;justify-content:center}.uagb-buttons__outer-wrap .uagb-buttons-repeater .uagb-button__icon{font-size:inherit;display:flex;align-items:center}.uagb-buttons__outer-wrap .uagb-buttons-repeater .uagb-button__icon svg{fill:currentColor;width:inherit;height:inherit}.wp-block-uagb-image{display:flex}.wp-block-uagb-image__figure{position:relative;display:flex;flex-direction:column;max-width:100%;height:auto;margin:0}.wp-block-uagb-image__figure img{height:auto;display:flex;max-width:100%;transition:box-shadow .2s ease}.wp-block-uagb-image__figure>a{display:inline-block}.wp-block-uagb-image__figure figcaption{text-align:center;margin-top:.5em;margin-bottom:1em}.wp-block-uagb-image .components-placeholder.block-editor-media-placeholder .components-placeholder__instructions{align-self:center}.wp-block-uagb-image--align-left{text-align:left}.wp-block-uagb-image--align-right{text-align:right}.wp-block-uagb-image--align-center{text-align:center}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw);max-width:100vw;width:100vw;height:auto}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure img{height:auto;width:100% !important}.wp-block-uagb-image--align-wide .wp-block-uagb-image__figure img{height:auto;width:100%}.wp-block-uagb-image--layout-overlay__color-wrapper{position:absolute;left:0;top:0;right:0;bottom:0;opacity:.2;background:rgba(0,0,0,.5);transition:opacity .35s ease-in-out}.wp-block-uagb-image--layout-overlay-link{position:absolute;left:0;right:0;bottom:0;top:0}.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity:1}.wp-block-uagb-image--layout-overlay__inner{position:absolute;left:15px;right:15px;bottom:15px;top:15px;display:flex;align-items:center;justify-content:center;flex-direction:column;border-color:#fff;transition:.35s ease-in-out}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.top-center,.wp-block-uagb-image--layout-overlay__inner.top-right{justify-content:flex-start}.wp-block-uagb-image--layout-overlay__inner.bottom-left,.wp-block-uagb-image--layout-overlay__inner.bottom-center,.wp-block-uagb-image--layout-overlay__inner.bottom-right{justify-content:flex-end}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.center-left,.wp-block-uagb-image--layout-overlay__inner.bottom-left{align-items:flex-start}.wp-block-uagb-image--layout-overlay__inner.top-right,.wp-block-uagb-image--layout-overlay__inner.center-right,.wp-block-uagb-image--layout-overlay__inner.bottom-right{align-items:flex-end}.wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{color:#fff;transition:transform .35s,opacity .35s ease-in-out;transform:translate3d(0, 24px, 0);margin:0;line-height:1em}.wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width:30%;border-top-width:2px;border-top-color:#fff;border-top-style:solid;margin-bottom:10px;opacity:0;transition:transform .4s,opacity .4s ease-in-out;transform:translate3d(0, 30px, 0)}.wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity:0;overflow:visible;color:#fff;transition:transform .45s,opacity .45s ease-in-out;transform:translate3d(0, 35px, 0)}.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-heading,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-separator,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-caption{opacity:1;transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1.05)}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{width:calc(100% + 40px) !important;max-width:none !important;transform:translate3d(-40px, 0, 0);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-grayscale img{filter:grayscale(0%);transition:.35s ease-in-out}.wp-block-uagb-image--effect-grayscale:hover img{filter:grayscale(100%)}.wp-block-uagb-image--effect-blur img{filter:blur(0);transition:.35s ease-in-out}.wp-block-uagb-image--effect-blur:hover img{filter:blur(3px)}\ufeff.uagb-post-grid{margin:0 auto;position:relative}.uagb-post-grid:not(.is-grid) .uagb-post__inner-wrap{background-clip:content-box !important}.uagb-post-grid .uagb-post__inner-wrap{transition:box-shadow .2s ease;overflow:hidden}.uagb-post-grid .uagb-post__inner-wrap .uagb-post__taxonomy{display:inline-block}.uagb-post-grid .uagb-post__inner-wrap .uagb-post__taxonomy.default{margin:5px 5px 5px 0}.uagb-post-grid .uagb-post__inner-wrap .uagb-post__taxonomy.highlighted{background:#444;color:#fff;border-radius:2px;flex-direction:row;align-items:flex-end;padding:6px 8px;line-height:1;margin-right:5px;margin-bottom:20px}.uagb-post-grid .uagb-post__inner-wrap .uagb-post__taxonomy.highlighted a{color:#fff}.uagb-post-grid .uagb-post__inner-wrap .uagb-post__taxonomy a{text-decoration:none;color:inherit}.uagb-post-grid .uagb-post__inner-wrap .uagb-post__image .uagb-post__image-equal-height{display:block;height:0;padding-bottom:66.67%;overflow:hidden}.uagb-post-grid .uagb-post__load-more-wrap{width:100%;position:absolute;bottom:-30px}.uagb-post-grid .uagb-post__load-more-wrap .uagb-post-pagination-button{cursor:pointer}.uagb-post-grid .uagb-post__load-more-wrap a{color:inherit}.uagb-post-grid.is-grid article{float:left;display:inline-block}.uagb-post-grid.is-grid.uagb-equal_height_inline-read-more-buttons.uagb-post__image-position-top .uagb-post__text:nth-last-child(2){padding-bottom:100px}.uagb-post-grid.is-grid.uagb-equal_height_inline-read-more-buttons.uagb-post__image-position-top .uagb-post__text:last-child{position:absolute;bottom:20px}.uagb-post-grid.is-grid.uagb-equal_height_inline-read-more-buttons.uagb-post__image-position-background .uagb-post__text:nth-last-child(3){padding-bottom:100px}.uagb-post-grid.is-grid.uagb-equal_height_inline-read-more-buttons.uagb-post__image-position-background .uagb-post__text:nth-last-child(2){position:absolute;bottom:20px}.uagb-post-grid.is-grid.uagb-equal_height_inline-read-more-buttons.uagb-post__image-position-top .uagb-post__inner-wrap,.uagb-post-grid.is-grid.uagb-equal_height_inline-read-more-buttons.uagb-post__image-position-background .uagb-post__inner-wrap{position:relative}.uagb-post-grid.is-grid.uagb-post__image-position-top .uagb-post__image a{display:block;height:0;overflow:hidden;position:relative}.uagb-post-grid.is-grid.uagb-post__image-position-top .uagb-post__image a.uagb-image-ratio-2-3{padding-bottom:66%}.uagb-post-grid.is-grid.uagb-post__image-position-top .uagb-post__image a.uagb-image-ratio-9-16{padding-bottom:56.25%}.uagb-post-grid.is-grid.uagb-post__image-position-top .uagb-post__image a.uagb-image-ratio-1-2{padding-bottom:50%}.uagb-post-grid.is-grid.uagb-post__image-position-top .uagb-post__image a.uagb-image-ratio-1-1{padding-bottom:67%}.uagb-post-grid.is-grid.uagb-post__image-position-top .uagb-post__image a.uagb-image-ratio-inherit{padding-bottom:0;height:auto}.uagb-post-grid.is-grid.uagb-post__image-position-top .uagb-post__image a.uagb-image-ratio-inherit img{position:unset !important}.uagb-post-grid.is-grid.uagb-post__image-position-top .uagb-post__image a[class^=uagb-image-ratio-]>img{position:absolute;height:100%}.uagb-post-grid.uagb-post__items.is-masonry{display:flex;-ms-flex-wrap:wrap;-webkit-flex-wrap:wrap;flex-wrap:wrap}.uagb-post-grid.uagb-post__items.is-carousel{display:flex;-ms-flex-wrap:wrap;-webkit-flex-wrap:wrap;flex-wrap:wrap;width:100%;visibility:hidden}.uagb-post-grid.is-grid .uagb-post__inner-wrap{height:max-content}.uagb-post-grid.is-grid.uagb-post__equal-height .uagb-post__inner-wrap{height:auto}.uagb-post-grid.is-masonry .uagb-post__inner-wrap{height:auto}.uagb-post-grid .uagb-post__author span,.uagb-post-grid .uagb-post__comment span,.uagb-post-grid .uagb-post__taxonomy span,.uagb-post-grid .uagb-post__date span{font-size:inherit;line-height:inherit;width:inherit;height:inherit;margin-right:4px;vertical-align:bottom}.uagb-post-grid.uagb-post__columns-8:not(.is-grid) article{width:12.5%}.uagb-post-grid.uagb-post__columns-7:not(.is-grid) article{width:14.28%}.uagb-post-grid.uagb-post__columns-6:not(.is-grid) article{width:16.66%}.uagb-post-grid.uagb-post__columns-5:not(.is-grid) article{width:20%}.uagb-post-grid.uagb-post__columns-4:not(.is-grid) article{width:25%}.uagb-post-grid.uagb-post__columns-3:not(.is-grid) article{width:33.33%}.uagb-post-grid.uagb-post__columns-2:not(.is-grid) article{width:50%}.uagb-post-grid.uagb-post__columns-1:not(.is-grid) article{width:100%}@media only screen and (max-width: 600px){.uagb-post-grid div[class*=columns].is-grid{grid-template-columns:1fr}}.uagb-post-grid .uagb-post__image img{display:block;width:100%;height:auto;max-width:100%}.uagb-post-grid .uagb-post__title{margin-top:0;margin-bottom:0;word-break:break-word}.uagb-post-grid .uagb-post__title a{color:inherit;box-shadow:none;transition:.3s ease;text-decoration:none}.uagb-post-grid .uagb-post__title a:hover{text-decoration:none}.uagb-post-grid .uagb-post__title a:focus{text-decoration:none}.uagb-post-grid .uagb-post__title a:active{text-decoration:none}.uagb-post-grid .uagb-post-grid-byline>*{margin-right:10px}.uagb-post-grid .uagb-post-grid-byline,.uagb-post-grid .uagb-post__taxonomy{text-transform:capitalize;font-size:14px;font-weight:500;line-height:23px;text-decoration:none}.uagb-post-grid .uagb-post-grid-byline a,.uagb-post-grid .uagb-post-grid-byline a:focus,.uagb-post-grid .uagb-post-grid-byline a:active{color:inherit;font-size:inherit;text-decoration:none}.uagb-post-grid .uagb-post__title a,.uagb-post-grid .uagb-post__title a:focus,.uagb-post-grid .uagb-post__title a:active{color:inherit;font-size:inherit}.uagb-post-grid .uagb-post__author,.uagb-post-grid .uagb-post__date,.uagb-post-grid .uagb-post__comment{display:inline-block;word-break:break-all}.uagb-post-grid .uagb-post__author:not(:last-child)::after,.uagb-post-grid .uagb-post__date:not(:last-child)::after,.uagb-post-grid .uagb-post__comment:not(:last-child)::after{content:\"\u00b7\";vertical-align:middle;align-self:center;margin:0 5px;line-height:1}.uagb-post-grid .uagb-post__comment,.uagb-post-grid .uagb-post__taxonomy{display:inline-block}.uagb-post-grid .uagb-post__author a{box-shadow:none}.uagb-post-grid .uagb-post__author a:hover{color:inherit;box-shadow:0 -1px 0 inset}.uagb-post-grid .uagb-post__excerpt{word-break:break-word}.uagb-post-grid .uagb-post__inner-wrap p:last-of-type{margin-bottom:0}.uagb-post-grid .uagb-post__cta{border:none;display:inline-block;background:none}.uagb-post-grid .uagb-post__cta .ast-outline-button{display:inline-flex}.uagb-post-grid .uagb-post__excerpt p{color:inherit}.is-grid.uagb-post__items{display:grid}.wp-block-uagb-post-grid .uagb-post-pagination-wrap{grid-column:1\/-1}.uagb-post__image-position-background .uagb-post__link-complete-box{position:absolute;top:0;left:0;width:100%;height:100%;z-index:11}.uagb-post__image-position-background.uagb-post__image-enabled .uagb-post__text{color:#fff}.uagb-post__image-position-background .uagb-post__text{opacity:1;position:relative;z-index:10;overflow:hidden}.uagb-post__image-position-background .uagb-post__inner-wrap{position:relative;width:100%}.uagb-post__image-position-background .uagb-post__inner-wrap .uagb-post__taxonomy.highlighted,.uagb-post__image-position-background .uagb-post__inner-wrap .uagb-post__taxonomy.default{position:relative;z-index:999}.uagb-post__image-position-background .uagb-post__image img{position:absolute;width:auto;height:auto;min-width:100%;max-width:none;left:50%;top:50%;transform:translate(-50%, -50%);min-height:100%}.uagb-post__image-position-background .uagb-post__image{background-size:cover;background-repeat:no-repeat;background-position:center;overflow:hidden;text-align:center;position:absolute;left:0;top:0;width:100%;height:100%;z-index:2}.uagb-post__image-position-background .uagb-post__image::before{content:\"\";position:absolute;left:0;top:0;width:100%;height:100%;z-index:1;background-color:hsla(0,0%,100%,.5)}.uagb-slick-carousel .is-carousel{padding:0}.uagb-slick-carousel ul.slick-dots{transform:unset;position:relative;padding:unset}.uagb-slick-carousel .slick-prev:not(:hover):not(:active):not(.has-background),.uagb-slick-carousel .slick-next:not(:hover):not(:active):not(.has-background),.uagb-slick-carousel ul.slick-dots li button:not(:hover):not(:active):not(.has-background){background-color:unset}.uagb-post-grid[data-equal-height=yes] .uagb-post__inner-wrap{display:inline-block;height:100%}.uagb-post__arrow-outside.uagb-post-grid .slick-prev{left:-45px;z-index:1}[dir=rtl] .uagb-post__arrow-outside.uagb-post-grid .slick-prev{left:-45px;right:auto}.uagb-post__arrow-outside.uagb-post-grid .slick-next{right:-45px}[dir=rtl] .uagb-post__arrow-outside.uagb-post-grid .slick-next{left:auto;right:-45px}.uagb-post__arrow-inside.uagb-post-grid .slick-prev{left:25px;z-index:1}[dir=rtl] .uagb-post__arrow-inside.uagb-post-grid .slick-prev{left:auto;right:25px}.uagb-post__arrow-inside.uagb-post-grid .slick-next{right:25px}[dir=rtl] .uagb-post__arrow-inside.uagb-post-grid .slick-next{left:25px;right:auto}.uagb-post-grid.is-grid article,.uagb-post-grid.is-masonry article,.uagb-post-grid.is-carousel article{box-sizing:border-box}@media(max-width: 976px){.uagb-post__arrow-outside.uagb-post-grid .slick-prev{left:15px;z-index:1}[dir=rtl] .uagb-post__arrow-outside.uagb-post-grid .slick-prev{left:auto;right:15px}.uagb-post__arrow-outside.uagb-post-grid .slick-next{right:15px}[dir=rtl] .uagb-post__arrow-outside.uagb-post-grid .slick-next{left:15px;right:auto}:not(.is-grid).uagb-post-grid.uagb-post__columns-tablet-1 article{width:100%}:not(.is-grid).uagb-post-grid.uagb-post__columns-tablet-2 article{width:50%}:not(.is-grid).uagb-post-grid.uagb-post__columns-tablet-3 article{width:33.33%}:not(.is-grid).uagb-post-grid.uagb-post__columns-tablet-4 article{width:25%}:not(.is-grid).uagb-post-grid.uagb-post__columns-tablet-5 article{width:20%}:not(.is-grid).uagb-post-grid.uagb-post__columns-tablet-6 article{width:16.66%}:not(.is-grid).uagb-post-grid.uagb-post__columns-tablet-7 article{width:14.28%}:not(.is-grid).uagb-post-grid.uagb-post__columns-tablet-8 article{width:12.5%}}@media(max-width: 767px){:not(.is-grid).uagb-post-grid.uagb-post__columns-mobile-1 article{width:100%}:not(.is-grid).uagb-post-grid.uagb-post__columns-mobile-2 article{width:50%}:not(.is-grid).uagb-post-grid.uagb-post__columns-mobile-3 article{width:33.33%}:not(.is-grid).uagb-post-grid.uagb-post__columns-mobile-4 article{width:25%}:not(.is-grid).uagb-post-grid.uagb-post__columns-mobile-5 article{width:20%}:not(.is-grid).uagb-post-grid.uagb-post__columns-mobile-6 article{width:16.66%}:not(.is-grid).uagb-post-grid.uagb-post__columns-mobile-7 article{width:14.28%}:not(.is-grid).uagb-post-grid.uagb-post__columns-mobile-8 article{width:12.5%}}.entry .entry-content .uagb-post-grid a{text-decoration:none}.uagb-post-pagination-wrap{display:flex;width:100%;flex-wrap:wrap}.uagb-post-pagination-wrap a.page-numbers,.uagb-post-pagination-wrap span.page-numbers.current{padding:5px 10px;margin:0;display:flex;margin-right:4px;margin-bottom:5px}.uagb-post-grid .uagb-post-inf-loader{margin:0 auto;min-height:58px;line-height:58px;width:160px;text-align:center}.uagb-post-grid .uagb-post-inf-loader div{width:18px;height:18px;background-color:#0085ba;-webkit-border-radius:100%;border-radius:100%;display:inline-block;-webkit-animation:sk-bouncedelay 1.4s infinite ease-in-out both;animation:sk-bouncedelay 1.4s infinite ease-in-out both}.uagb-post-grid .uagb-post-inf-loader .uagb-post-loader-1{-webkit-animation-delay:-0.32s;animation-delay:-0.32s}.uagb-post-grid .uagb-post-inf-loader .uagb-post-loader-2{-webkit-animation-delay:-0.16s;animation-delay:-0.16s}.wp-site-blocks .uagb-post__arrow-outside.uagb-post-grid .slick-next{right:0}.wp-site-blocks .uagb-post__arrow-outside.uagb-post-grid .slick-prev{left:0}@-webkit-keyframes sk-bouncedelay{0%,80%,100%{-webkit-transform:scale(0);transform:scale(0)}40%{-webkit-transform:scale(1);transform:scale(1)}}@keyframes sk-bouncedelay{0%,80%,100%{-webkit-transform:scale(0);transform:scale(0)}40%{-webkit-transform:scale(1);transform:scale(1)}}.wp-block-uagb-container.uagb-block-41abe729 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-41abe729 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-41abe729 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-41abe729 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-41abe729 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-41abe729{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-41abe729{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-44572301 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-44572301 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-44572301 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-44572301 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-44572301 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-44572301{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-44572301 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1170px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: flex-start;justify-content: flex-start;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-44572301{min-height: 0px;box-shadow: 0px 0px   #00000070 ;padding-top: 107px;padding-bottom: 107px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: var(--ast-global-color-1);row-gap: 0px;column-gap: 0px;}.wp-block-uagb-advanced-heading.uagb-block-d969377a.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-2);}.wp-block-uagb-advanced-heading.uagb-block-d969377a.wp-block-uagb-advanced-heading {text-align: center;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-d969377a.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-d969377a.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-d969377a.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-d969377a.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-d969377a .uagb-heading-text{font-family: \"Poppins\";font-weight: 300;font-size: 40px;line-height: 48px;}.wp-block-uagb-advanced-heading.uagb-block-c204dab9.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-3);}.wp-block-uagb-advanced-heading.uagb-block-c204dab9.wp-block-uagb-advanced-heading {text-align: center;margin-top: 25px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 0%;padding-right: 6%;padding-bottom: 0%;padding-left: 6%;}.wp-block-uagb-advanced-heading.uagb-block-c204dab9.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-c204dab9.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-c204dab9.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-c204dab9.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-c204dab9 .uagb-heading-text{font-family: \"Poppins\";font-weight: 400;font-size: 19px;line-height: 32px;}.wp-block-uagb-container.uagb-block-1fa6aee9 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-1fa6aee9 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-1fa6aee9 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-1fa6aee9 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-1fa6aee9 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1fa6aee9{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1fa6aee9 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1170px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-1fa6aee9{box-shadow: 0px 0px   #00000070 ;padding-top: 85px;padding-bottom: 100px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: #f2f2f2;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-advanced-heading.uagb-block-0cd02049.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-2);}.wp-block-uagb-advanced-heading.uagb-block-0cd02049.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-0cd02049.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-0cd02049.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-0cd02049.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-0cd02049.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-0cd02049 .uagb-heading-text{font-family: \"Poppins\";font-weight: 500;font-size: 32px;line-height: 42px;}.wp-block-uagb-advanced-heading.uagb-block-15f800a4.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-3);}.wp-block-uagb-advanced-heading.uagb-block-15f800a4.wp-block-uagb-advanced-heading {text-align: center;margin-top: 30px;margin-right: 0px;margin-bottom: 45px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-15f800a4.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-15f800a4.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-15f800a4.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-15f800a4.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-15f800a4 .uagb-heading-text{font-family: \"Poppins\";font-weight: 400;font-size: 14px;line-height: 26px;}.wp-block-uagb-advanced-heading.uagb-block-12a8fe6e.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-1);}.wp-block-uagb-advanced-heading.uagb-block-12a8fe6e.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-12a8fe6e.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-12a8fe6e.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-12a8fe6e.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-12a8fe6e.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-12a8fe6e .uagb-heading-text{font-family: \"Poppins\";font-weight: 500;font-size: 32px;line-height: 42px;}.wp-block-uagb-advanced-heading.uagb-block-529bed5b.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-1);}.wp-block-uagb-advanced-heading.uagb-block-529bed5b.wp-block-uagb-advanced-heading {text-align: center;margin-top: 0.75em;margin-right: 0em;margin-bottom: 1.75em;margin-left: 0em;padding-top: 0px;padding-right: 40px;padding-bottom: 0px;padding-left: 40px;}.wp-block-uagb-advanced-heading.uagb-block-529bed5b.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-529bed5b.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-529bed5b.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-529bed5b.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-529bed5b .uagb-heading-text{font-family: \"Poppins\";font-weight: 400;font-size: 14px;line-height: 26px;}.uagb-block-b5f3efe9.wp-block-uagb-buttons.uagb-buttons__outer-wrap .uagb-buttons__wrap {gap: 10px;}.uagb-block-b5f3efe9.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-b5f3efe9 .uagb-buttons-repeater:not(.wp-block-button__link){padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;}.uagb-block-b5f3efe9 .uagb-button__wrapper .uagb-buttons-repeater.wp-block-button__link{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;}.uagb-block-b5f3efe9 .uagb-button__wrapper .uagb-buttons-repeater.ast-outline-button{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;}.uagb-block-b5f3efe9 .uagb-button__wrapper{margin-top: 0px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;}.wp-block-uagb-buttons .uagb-block-4eb9cfab .wp-block-button__link:hover{background: var(--ast-global-color-4);}.wp-block-uagb-buttons .uagb-block-4eb9cfab .wp-block-button__link:focus{background: var(--ast-global-color-4);}.wp-block-uagb-buttons .uagb-block-4eb9cfab .uagb-button__wrapper .uagb-buttons-repeater{font-family: \"Poppins\";font-size: 14px;padding-top: 18px;padding-bottom: 18px;padding-left: 20px;padding-right: 20px;color: var(--ast-global-color-1);margin-top: 0px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;}.wp-block-uagb-buttons .uagb-block-4eb9cfab .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link{margin-top: 0px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-4eb9cfab .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link:hover{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-4eb9cfab .uagb-buttons-repeater.wp-block-button__link{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-color: #333;border-style: solid;}.wp-block-uagb-buttons .uagb-block-4eb9cfab .uagb-buttons-repeater.wp-block-button__link:hover{border-color: var(--ast-global-color-4);}.wp-block-uagb-buttons .uagb-block-4eb9cfab .uagb-buttons-repeater.wp-block-button__link:focus{border-color: var(--ast-global-color-4);}.wp-block-uagb-buttons .uagb-block-4eb9cfab.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-color: #333;border-style: solid;}.wp-block-uagb-buttons .uagb-block-4eb9cfab.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater:hover{border-color: var(--ast-global-color-4);}.wp-block-uagb-buttons .uagb-block-4eb9cfab .uagb-buttons-repeater .uagb-button__link{color: var(--ast-global-color-1);font-family: \"Poppins\";font-size: 14px;}.wp-block-uagb-buttons .uagb-block-4eb9cfab .uagb-buttons-repeater .uagb-button__icon > svg{width: 15px;height: 15px;fill: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-4eb9cfab .uagb-buttons-repeater .uagb-button__icon-position-after{margin-left: 8px;}.wp-block-uagb-buttons .uagb-block-4eb9cfab .uagb-buttons-repeater .uagb-button__icon-position-before{margin-right: 8px;}.wp-block-uagb-buttons .uagb-block-4eb9cfab .uagb-button__link{font-family: \"Poppins\";text-transform: normal;text-decoration: none;}.wp-block-uagb-advanced-heading.uagb-block-37120996.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-1);}.wp-block-uagb-advanced-heading.uagb-block-37120996.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-37120996.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-37120996.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-37120996.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-37120996.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-37120996 .uagb-heading-text{font-family: \"Poppins\";font-weight: 500;font-size: 32px;line-height: 42px;}.wp-block-uagb-advanced-heading.uagb-block-3fa33b75.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-1);}.wp-block-uagb-advanced-heading.uagb-block-3fa33b75.wp-block-uagb-advanced-heading {text-align: center;margin-top: 0.75em;margin-right: 0em;margin-bottom: 1.75em;margin-left: 0em;padding-top: 0px;padding-right: 40px;padding-bottom: 0px;padding-left: 40px;}.wp-block-uagb-advanced-heading.uagb-block-3fa33b75.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-3fa33b75.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-3fa33b75.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-3fa33b75.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-3fa33b75 .uagb-heading-text{font-family: \"Poppins\";font-weight: 400;font-size: 14px;line-height: 26px;}.uagb-block-3114da5a.wp-block-uagb-buttons.uagb-buttons__outer-wrap .uagb-buttons__wrap {gap: 10px;}.uagb-block-3114da5a.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-3114da5a .uagb-buttons-repeater:not(.wp-block-button__link){padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;}.uagb-block-3114da5a .uagb-button__wrapper .uagb-buttons-repeater.wp-block-button__link{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;}.uagb-block-3114da5a .uagb-button__wrapper .uagb-buttons-repeater.ast-outline-button{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;}.uagb-block-3114da5a .uagb-button__wrapper{margin-top: 0px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;}.wp-block-uagb-buttons .uagb-block-e63aabc4 .wp-block-button__link:hover{background: var(--ast-global-color-4);}.wp-block-uagb-buttons .uagb-block-e63aabc4 .wp-block-button__link:focus{background: var(--ast-global-color-4);}.wp-block-uagb-buttons .uagb-block-e63aabc4 .uagb-button__wrapper .uagb-buttons-repeater{font-family: \"Poppins\";font-size: 14px;padding-top: 18px;padding-bottom: 18px;padding-left: 20px;padding-right: 20px;color: var(--ast-global-color-1);margin-top: 0px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;}.wp-block-uagb-buttons .uagb-block-e63aabc4 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link{margin-top: 0px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-e63aabc4 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link:hover{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-e63aabc4 .uagb-buttons-repeater.wp-block-button__link{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-color: #333;border-style: solid;}.wp-block-uagb-buttons .uagb-block-e63aabc4 .uagb-buttons-repeater.wp-block-button__link:hover{border-color: var(--ast-global-color-4);}.wp-block-uagb-buttons .uagb-block-e63aabc4 .uagb-buttons-repeater.wp-block-button__link:focus{border-color: var(--ast-global-color-4);}.wp-block-uagb-buttons .uagb-block-e63aabc4.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-color: #333;border-style: solid;}.wp-block-uagb-buttons .uagb-block-e63aabc4.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater:hover{border-color: var(--ast-global-color-4);}.wp-block-uagb-buttons .uagb-block-e63aabc4 .uagb-buttons-repeater .uagb-button__link{color: var(--ast-global-color-1);font-family: \"Poppins\";font-size: 14px;}.wp-block-uagb-buttons .uagb-block-e63aabc4 .uagb-buttons-repeater .uagb-button__icon > svg{width: 15px;height: 15px;fill: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-e63aabc4 .uagb-buttons-repeater .uagb-button__icon-position-after{margin-left: 8px;}.wp-block-uagb-buttons .uagb-block-e63aabc4 .uagb-buttons-repeater .uagb-button__icon-position-before{margin-right: 8px;}.wp-block-uagb-buttons .uagb-block-e63aabc4 .uagb-button__link{font-family: \"Poppins\";text-transform: normal;text-decoration: none;}.wp-block-uagb-container.uagb-block-71fce647 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-71fce647 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-71fce647 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-71fce647 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-71fce647 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-71fce647{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-71fce647 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1170px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-71fce647{box-shadow: 0px 0px   #00000070 ;padding-top: 80px;padding-bottom: 80px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: var(--ast-global-color-1);row-gap: 0px;column-gap: 0px;}.wp-block-uagb-advanced-heading.uagb-block-9e753b84.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-2);}.wp-block-uagb-advanced-heading.uagb-block-9e753b84.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-9e753b84.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-9e753b84.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-9e753b84.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-9e753b84.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-9e753b84 .uagb-heading-text{font-family: \"Poppins\";font-weight: 500;font-size: 32px;line-height: 42px;}.wp-block-uagb-advanced-heading.uagb-block-c8928e78.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-3);}.wp-block-uagb-advanced-heading.uagb-block-c8928e78.wp-block-uagb-advanced-heading {text-align: center;margin-top: 16px;margin-right: 0px;margin-bottom: 50px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-c8928e78.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-c8928e78.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-c8928e78.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-c8928e78.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-c8928e78 .uagb-heading-text{font-family: \"Poppins\";font-weight: 400;font-size: 14px;line-height: 26px;}.wp-block-uagb-container.uagb-block-0a1b82a2 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-0a1b82a2 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-0a1b82a2 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-0a1b82a2 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-0a1b82a2 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-0a1b82a2{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-0a1b82a2 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1170px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: stretch;justify-content: flex-end;flex-wrap: nowrap;row-gap: 30px;column-gap: 30px;}.wp-block-uagb-container.uagb-block-0a1b82a2{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: row;align-items: stretch;justify-content: flex-end;flex-wrap: nowrap;row-gap: 30px;column-gap: 30px;}.wp-block-uagb-container.uagb-block-7f6d21c2 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-7f6d21c2 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-7f6d21c2 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-7f6d21c2 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-7f6d21c2 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7f6d21c2{max-width: 25%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7f6d21c2 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1170px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-7f6d21c2{box-shadow: 0px 0px   #00000070 ;padding-top: 30px;padding-bottom: 30px;padding-left: 25px;padding-right: 25px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 12px;border-top-right-radius: 12px;border-bottom-left-radius: 12px;border-bottom-right-radius: 12px;border-style: solid;border-color: #d6dae1;background-color: #f2f2f2;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.uagb-block-ee3fc18b.wp-block-uagb-image{text-align: center;justify-content: center;align-self: center;}.uagb-block-ee3fc18b .wp-block-uagb-image__figure{align-items: center;}.uagb-block-ee3fc18b.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-ee3fc18b.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-ee3fc18b.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-ee3fc18b.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-ee3fc18b.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-ee3fc18b.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-ee3fc18b.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-ee3fc18b.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-ee3fc18b.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-ee3fc18b.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-ee3fc18b.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-ee3fc18b.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-ee3fc18b.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-ee3fc18b.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-ee3fc18b.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-advanced-heading.uagb-block-1469f899.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-2);}.wp-block-uagb-advanced-heading.uagb-block-1469f899.wp-block-uagb-advanced-heading {text-align: center;padding-top: 20px;padding-right: 0px;padding-bottom: 14px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-1469f899.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-1469f899.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-1469f899.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-1469f899.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-1469f899 .uagb-heading-text{font-family: \"Poppins\";font-weight: 600;font-size: 22px;line-height: 31px;}.wp-block-uagb-advanced-heading.uagb-block-a1ec0e75.wp-block-uagb-advanced-heading .uagb-heading-text{color: #222326;}.wp-block-uagb-advanced-heading.uagb-block-a1ec0e75.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-a1ec0e75.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-a1ec0e75.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a1ec0e75.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a1ec0e75.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a1ec0e75 .uagb-heading-text{font-weight: 400;font-size: 14px;line-height: 22px;}.uagb-block-f07ced51.wp-block-uagb-buttons.uagb-buttons__outer-wrap .uagb-buttons__wrap {gap: 10px;}.uagb-block-f07ced51.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.wp-block-uagb-buttons .uagb-block-786b5a71.wp-block-uagb-buttons-child .uagb-buttons-repeater{background: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-786b5a71 .wp-block-button__link{background: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-786b5a71 .wp-block-button__link:hover{background: #b8a65f;}.wp-block-uagb-buttons .uagb-block-786b5a71 .wp-block-button__link:focus{background: #b8a65f;}.wp-block-uagb-buttons .uagb-block-786b5a71 .uagb-button__wrapper .uagb-buttons-repeater{padding-top: 13px;padding-bottom: 13px;padding-left: 24px;padding-right: 24px;color: #222326;margin-top: 14px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;}.wp-block-uagb-buttons .uagb-block-786b5a71 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link{margin-top: 14px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-786b5a71 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link:hover{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-786b5a71 .uagb-buttons-repeater.wp-block-button__link{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-color: var(--ast-global-color-1);border-style: solid;}.wp-block-uagb-buttons .uagb-block-786b5a71 .uagb-buttons-repeater.wp-block-button__link:hover{border-color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-786b5a71 .uagb-buttons-repeater.wp-block-button__link:focus{border-color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-786b5a71.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-color: var(--ast-global-color-1);border-style: solid;}.wp-block-uagb-buttons .uagb-block-786b5a71.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater:hover{border-color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-786b5a71 .uagb-buttons-repeater .uagb-button__link{color: #222326;}.wp-block-uagb-buttons .uagb-block-786b5a71 .uagb-buttons-repeater .uagb-button__icon > svg{width: 15px;height: 15px;fill: #222326;}.wp-block-uagb-buttons .uagb-block-786b5a71 .uagb-buttons-repeater .uagb-button__icon-position-after{margin-left: 8px;}.wp-block-uagb-buttons .uagb-block-786b5a71 .uagb-buttons-repeater .uagb-button__icon-position-before{margin-right: 8px;}.wp-block-uagb-buttons .uagb-block-786b5a71 .uagb-button__link{text-transform: normal;text-decoration: none;}.wp-block-uagb-container.uagb-block-7459a9cf .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-7459a9cf .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-7459a9cf .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-7459a9cf .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-7459a9cf .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7459a9cf{max-width: 25%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7459a9cf > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1170px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-7459a9cf{box-shadow: 0px 0px   #00000070 ;padding-top: 30px;padding-bottom: 30px;padding-left: 25px;padding-right: 25px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 12px;border-top-right-radius: 12px;border-bottom-left-radius: 12px;border-bottom-right-radius: 12px;border-style: solid;border-color: #d6dae1;background-color: #f2f2f2;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.uagb-block-141f4801.wp-block-uagb-image{text-align: center;justify-content: center;align-self: center;}.uagb-block-141f4801 .wp-block-uagb-image__figure{align-items: center;}.uagb-block-141f4801.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-141f4801.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-141f4801.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-141f4801.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-141f4801.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-141f4801.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-141f4801.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-141f4801.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-141f4801.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-141f4801.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-141f4801.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-141f4801.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-141f4801.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-141f4801.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-141f4801.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-advanced-heading.uagb-block-f0579925.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-2);}.wp-block-uagb-advanced-heading.uagb-block-f0579925.wp-block-uagb-advanced-heading {text-align: center;padding-top: 20px;padding-right: 0px;padding-bottom: 14px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-f0579925.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-f0579925.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-f0579925.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-f0579925.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-f0579925 .uagb-heading-text{font-family: \"Poppins\";font-weight: 600;font-size: 22px;line-height: 31px;}.wp-block-uagb-advanced-heading.uagb-block-80ef0c69.wp-block-uagb-advanced-heading .uagb-heading-text{color: #222326;}.wp-block-uagb-advanced-heading.uagb-block-80ef0c69.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-80ef0c69.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-80ef0c69.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-80ef0c69.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-80ef0c69.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-80ef0c69 .uagb-heading-text{font-weight: 400;font-size: 14px;line-height: 22px;}.uagb-block-062a311b.wp-block-uagb-buttons.uagb-buttons__outer-wrap .uagb-buttons__wrap {gap: 10px;}.uagb-block-062a311b.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.wp-block-uagb-buttons .uagb-block-0b9255f8.wp-block-uagb-buttons-child .uagb-buttons-repeater{background: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-0b9255f8 .wp-block-button__link{background: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-0b9255f8 .wp-block-button__link:hover{background: #b8a65f;}.wp-block-uagb-buttons .uagb-block-0b9255f8 .wp-block-button__link:focus{background: #b8a65f;}.wp-block-uagb-buttons .uagb-block-0b9255f8 .uagb-button__wrapper .uagb-buttons-repeater{padding-top: 13px;padding-bottom: 13px;padding-left: 24px;padding-right: 24px;color: #222326;margin-top: 14px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;}.wp-block-uagb-buttons .uagb-block-0b9255f8 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link{margin-top: 14px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-0b9255f8 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link:hover{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-0b9255f8 .uagb-buttons-repeater.wp-block-button__link{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-color: var(--ast-global-color-1);border-style: solid;}.wp-block-uagb-buttons .uagb-block-0b9255f8 .uagb-buttons-repeater.wp-block-button__link:hover{border-color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-0b9255f8 .uagb-buttons-repeater.wp-block-button__link:focus{border-color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-0b9255f8.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-color: var(--ast-global-color-1);border-style: solid;}.wp-block-uagb-buttons .uagb-block-0b9255f8.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater:hover{border-color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-0b9255f8 .uagb-buttons-repeater .uagb-button__link{color: #222326;}.wp-block-uagb-buttons .uagb-block-0b9255f8 .uagb-buttons-repeater .uagb-button__icon > svg{width: 15px;height: 15px;fill: #222326;}.wp-block-uagb-buttons .uagb-block-0b9255f8 .uagb-buttons-repeater .uagb-button__icon-position-after{margin-left: 8px;}.wp-block-uagb-buttons .uagb-block-0b9255f8 .uagb-buttons-repeater .uagb-button__icon-position-before{margin-right: 8px;}.wp-block-uagb-buttons .uagb-block-0b9255f8 .uagb-button__link{text-transform: normal;text-decoration: none;}.wp-block-uagb-container.uagb-block-3e0ad83d .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-3e0ad83d .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-3e0ad83d .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-3e0ad83d .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-3e0ad83d .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3e0ad83d{max-width: 25%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3e0ad83d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1170px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-3e0ad83d{box-shadow: 0px 0px   #00000070 ;padding-top: 30px;padding-bottom: 30px;padding-left: 25px;padding-right: 25px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 12px;border-top-right-radius: 12px;border-bottom-left-radius: 12px;border-bottom-right-radius: 12px;border-style: solid;border-color: #d6dae1;background-color: #f2f2f2;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.uagb-block-4788ca6b.wp-block-uagb-image{text-align: center;justify-content: center;align-self: center;}.uagb-block-4788ca6b .wp-block-uagb-image__figure{align-items: center;}.uagb-block-4788ca6b.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-4788ca6b.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-4788ca6b.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-4788ca6b.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-4788ca6b.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-4788ca6b.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-4788ca6b.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-4788ca6b.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-4788ca6b.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-4788ca6b.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-4788ca6b.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-4788ca6b.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-4788ca6b.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-4788ca6b.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-4788ca6b.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-advanced-heading.uagb-block-1ae13353.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-2);}.wp-block-uagb-advanced-heading.uagb-block-1ae13353.wp-block-uagb-advanced-heading {text-align: center;padding-top: 20px;padding-right: 0px;padding-bottom: 14px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-1ae13353.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-1ae13353.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-1ae13353.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-1ae13353.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-1ae13353 .uagb-heading-text{font-family: \"Poppins\";font-weight: 600;font-size: 22px;line-height: 31px;}.wp-block-uagb-advanced-heading.uagb-block-c184aee7.wp-block-uagb-advanced-heading .uagb-heading-text{color: #222326;}.wp-block-uagb-advanced-heading.uagb-block-c184aee7.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-c184aee7.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-c184aee7.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-c184aee7.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-c184aee7.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-c184aee7 .uagb-heading-text{font-weight: 400;font-size: 14px;line-height: 22px;}.uagb-block-c8d0d2a3.wp-block-uagb-buttons.uagb-buttons__outer-wrap .uagb-buttons__wrap {gap: 10px;}.uagb-block-c8d0d2a3.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.wp-block-uagb-buttons .uagb-block-0ad08212.wp-block-uagb-buttons-child .uagb-buttons-repeater{background: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-0ad08212 .wp-block-button__link{background: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-0ad08212 .wp-block-button__link:hover{background: #b8a65f;}.wp-block-uagb-buttons .uagb-block-0ad08212 .wp-block-button__link:focus{background: #b8a65f;}.wp-block-uagb-buttons .uagb-block-0ad08212 .uagb-button__wrapper .uagb-buttons-repeater{padding-top: 13px;padding-bottom: 13px;padding-left: 24px;padding-right: 24px;color: #222326;margin-top: 14px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;}.wp-block-uagb-buttons .uagb-block-0ad08212 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link{margin-top: 14px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-0ad08212 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link:hover{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-0ad08212 .uagb-buttons-repeater.wp-block-button__link{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-color: var(--ast-global-color-1);border-style: solid;}.wp-block-uagb-buttons .uagb-block-0ad08212 .uagb-buttons-repeater.wp-block-button__link:hover{border-color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-0ad08212 .uagb-buttons-repeater.wp-block-button__link:focus{border-color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-0ad08212.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-color: var(--ast-global-color-1);border-style: solid;}.wp-block-uagb-buttons .uagb-block-0ad08212.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater:hover{border-color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-0ad08212 .uagb-buttons-repeater .uagb-button__link{color: #222326;}.wp-block-uagb-buttons .uagb-block-0ad08212 .uagb-buttons-repeater .uagb-button__icon > svg{width: 15px;height: 15px;fill: #222326;}.wp-block-uagb-buttons .uagb-block-0ad08212 .uagb-buttons-repeater .uagb-button__icon-position-after{margin-left: 8px;}.wp-block-uagb-buttons .uagb-block-0ad08212 .uagb-buttons-repeater .uagb-button__icon-position-before{margin-right: 8px;}.wp-block-uagb-buttons .uagb-block-0ad08212 .uagb-button__link{text-transform: normal;text-decoration: none;}.wp-block-uagb-container.uagb-block-e99beffd .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-e99beffd .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-e99beffd .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-e99beffd .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-e99beffd .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e99beffd{max-width: 25%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e99beffd > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1170px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-e99beffd{box-shadow: 0px 0px   #00000070 ;padding-top: 30px;padding-bottom: 30px;padding-left: 25px;padding-right: 25px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-top-left-radius: 12px;border-top-right-radius: 12px;border-bottom-left-radius: 12px;border-bottom-right-radius: 12px;border-style: solid;border-color: #d6dae1;background-color: #f2f2f2;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.uagb-block-b488c6c6.wp-block-uagb-image{text-align: center;justify-content: center;align-self: center;}.uagb-block-b488c6c6 .wp-block-uagb-image__figure{align-items: center;}.uagb-block-b488c6c6.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-b488c6c6.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-b488c6c6.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-b488c6c6.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-b488c6c6.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-b488c6c6.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-b488c6c6.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-b488c6c6.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-b488c6c6.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-b488c6c6.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-b488c6c6.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-b488c6c6.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-b488c6c6.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-b488c6c6.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-b488c6c6.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}.wp-block-uagb-advanced-heading.uagb-block-fa6b4846.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-2);}.wp-block-uagb-advanced-heading.uagb-block-fa6b4846.wp-block-uagb-advanced-heading {text-align: center;padding-top: 20px;padding-right: 0px;padding-bottom: 14px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-fa6b4846.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-fa6b4846.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-fa6b4846.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-fa6b4846.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-fa6b4846 .uagb-heading-text{font-family: \"Poppins\";font-weight: 600;font-size: 22px;line-height: 31px;}.wp-block-uagb-advanced-heading.uagb-block-2d72864e.wp-block-uagb-advanced-heading .uagb-heading-text{color: #222326;}.wp-block-uagb-advanced-heading.uagb-block-2d72864e.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-2d72864e.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-2d72864e.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-2d72864e.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-2d72864e.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-2d72864e .uagb-heading-text{font-weight: 400;font-size: 14px;line-height: 22px;}.uagb-block-5b55a0a4.wp-block-uagb-buttons.uagb-buttons__outer-wrap .uagb-buttons__wrap {gap: 10px;}.uagb-block-5b55a0a4.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.wp-block-uagb-buttons .uagb-block-5ac5155c.wp-block-uagb-buttons-child .uagb-buttons-repeater{background: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-5ac5155c .wp-block-button__link{background: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-5ac5155c .wp-block-button__link:hover{background: #b8a65f;}.wp-block-uagb-buttons .uagb-block-5ac5155c .wp-block-button__link:focus{background: #b8a65f;}.wp-block-uagb-buttons .uagb-block-5ac5155c .uagb-button__wrapper .uagb-buttons-repeater{padding-top: 13px;padding-bottom: 13px;padding-left: 24px;padding-right: 24px;color: #222326;margin-top: 14px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;}.wp-block-uagb-buttons .uagb-block-5ac5155c .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link{margin-top: 14px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-5ac5155c .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link:hover{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-5ac5155c .uagb-buttons-repeater.wp-block-button__link{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-color: var(--ast-global-color-1);border-style: solid;}.wp-block-uagb-buttons .uagb-block-5ac5155c .uagb-buttons-repeater.wp-block-button__link:hover{border-color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-5ac5155c .uagb-buttons-repeater.wp-block-button__link:focus{border-color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-5ac5155c.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-top-width: 1px;border-left-width: 1px;border-right-width: 1px;border-bottom-width: 1px;border-color: var(--ast-global-color-1);border-style: solid;}.wp-block-uagb-buttons .uagb-block-5ac5155c.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater:hover{border-color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-5ac5155c .uagb-buttons-repeater .uagb-button__link{color: #222326;}.wp-block-uagb-buttons .uagb-block-5ac5155c .uagb-buttons-repeater .uagb-button__icon > svg{width: 15px;height: 15px;fill: #222326;}.wp-block-uagb-buttons .uagb-block-5ac5155c .uagb-buttons-repeater .uagb-button__icon-position-after{margin-left: 8px;}.wp-block-uagb-buttons .uagb-block-5ac5155c .uagb-buttons-repeater .uagb-button__icon-position-before{margin-right: 8px;}.wp-block-uagb-buttons .uagb-block-5ac5155c .uagb-button__link{text-transform: normal;text-decoration: none;}.wp-block-uagb-container.uagb-block-c31d078c .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-c31d078c .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-c31d078c .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-c31d078c .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-c31d078c .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c31d078c{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c31d078c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1170px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-c31d078c{box-shadow: 0px 0px   #00000070 ;padding-top: 85px;padding-bottom: 68px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: #ededed;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-advanced-heading.uagb-block-159ab93a.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-2);}.wp-block-uagb-advanced-heading.uagb-block-159ab93a.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-159ab93a.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-159ab93a.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-159ab93a.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-159ab93a.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-159ab93a .uagb-heading-text{font-family: \"Poppins\";font-weight: 500;font-size: 32px;line-height: 42px;}.wp-block-uagb-advanced-heading.uagb-block-027d72db.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-3);}.wp-block-uagb-advanced-heading.uagb-block-027d72db.wp-block-uagb-advanced-heading {text-align: center;margin-top: 30px;margin-right: 0px;margin-bottom: 45px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-027d72db.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-027d72db.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-027d72db.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-027d72db.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-027d72db .uagb-heading-text{font-family: \"Poppins\";font-weight: 400;font-size: 14px;line-height: 26px;}.uagb-block-e81fa8c9.is-grid .uagb-post__inner-wrap{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;box-shadow: 0px 0px 0 #00000070;}.uagb-block-e81fa8c9.is-grid .uagb-post__inner-wrap .uagb-post__image:first-child{margin-left: 0px;margin-right: 0px;margin-top: 0px;}.uagb-block-e81fa8c9:not(.is-grid) .uagb-post__inner-wrap > .uagb-post__text:last-child{margin-bottom: 0px;}.uagb-block-e81fa8c9:not(.is-grid) .uagb-post__inner-wrap > .uagb-post__text:first-child{margin-top: 0px;}.uagb-block-e81fa8c9:not(.is-grid).uagb-post__image-position-background .uagb-post__inner-wrap .uagb-post__text:nth-last-child(2) {margin-bottom: 0px;}.uagb-block-e81fa8c9:not(.wp-block-uagb-post-carousel):not(.is-grid).uagb-post__items{margin-right: -15px;margin-left: -15px;}.uagb-block-e81fa8c9:not(.is-grid).uagb-post__items article{padding-right: 15px;padding-left: 15px;margin-bottom: 30px;}.uagb-block-e81fa8c9:not(.is-grid) .uagb-post__inner-wrap > .uagb-post__text{margin-left: 0px;margin-right: 0px;}.uagb-block-e81fa8c9 .uagb-post__inner-wrap{background: #f5f5f500;text-align: center;}.uagb-block-e81fa8c9 .uagb-post__inner-wrap .uagb-post__cta{padding-bottom: 0px;}.uagb-block-e81fa8c9 .uagb-post__image {padding-bottom: 26px;}.uagb-block-e81fa8c9 .uagb-post__title{padding-bottom: 10px;}.uagb-block-e81fa8c9 .uagb-post-grid-byline{padding-bottom: 15px;}.uagb-block-e81fa8c9 .uagb-post__excerpt{padding-bottom: 30px;}.uagb-block-e81fa8c9 .uagb-post__image:before{background-color: #000000;opacity: 0.5;}.uagb-block-e81fa8c9.is-grid.uagb-post__items{row-gap: 30px;column-gap: 30px;}.uagb-block-e81fa8c9.wp-block-uagb-post-grid.is-grid{grid-template-columns: repeat(3 , minmax(0, 1fr));}.uagb-block-e81fa8c9.is-grid .uagb-post__inner-wrap:hover{box-shadow: 0px 0px 0 #00000070;}.uagb-block-e81fa8c9 .uagb-post__text.uagb-post__title{font-family: \"Poppins\";font-weight: 500;font-size: 17px;line-height: 25px;color: var(--ast-global-color-2);}.uagb-block-e81fa8c9 .uagb-post__text.uagb-post__title a{font-family: \"Poppins\";font-weight: 500;font-size: 17px;line-height: 25px;color: var(--ast-global-color-2);}.uagb-block-e81fa8c9 .uagb-post__inner-wrap .uagb-post__taxonomy.highlighted{color: #fff;background: #3182ce;}.uagb-block-e81fa8c9 .uagb-post__inner-wrap .uagb-post__taxonomy.highlighted a{color: #fff;}.uagb-block-e81fa8c9 .uagb-post__text.uagb-post__excerpt{font-family: \"Poppins\";font-weight: 400;font-size: 14px;line-height: 26px;color: var(--ast-global-color-3);}.uagb-block-e81fa8c9.uagb-post-grid .wp-block-button.uagb-post__text.uagb-post__cta .uagb-text-link.wp-block-button__link {color: var(--ast-global-color-0);background: transparent;0: ;0: ;0: ;0: ;0: 30px;0: 30px;0: 30px;0: 30px;0: ;0: none;border-top-left-radius: 30px;border-top-right-radius: 30px;border-bottom-left-radius: 30px;border-bottom-right-radius: 30px;border-style: none;}.uagb-block-e81fa8c9.uagb-post-grid .uagb-post__inner-wrap .wp-block-button.uagb-post__text.uagb-post__cta a{color: var(--ast-global-color-0);padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;}.uagb-block-e81fa8c9.uagb-post-grid .wp-block-button.uagb-post__text.uagb-post__cta:hover .uagb-text-link.wp-block-button__link{color: var(--ast-global-color-4);background: transparent;}.uagb-block-e81fa8c9 .uagb-post__text.uagb-post__cta:hover a.uagb-text-link{color: var(--ast-global-color-4);}.uagb-block-e81fa8c9 .uagb-post__text.uagb-post__cta a.uagb-text-link:focus{color: var(--ast-global-color-4);background: transparent;}.uagb-block-e81fa8c9 .uagb-post-pagination-wrap{margin-top: 0px;justify-content: left;margin-left: 10px;}.uagb-block-e81fa8c9 .uagb-post-pagination-wrap .page-numbers.current{background-color: #e4e4e4;color: #333333;}.uagb-block-e81fa8c9 .uagb-post-pagination-wrap a{background-color: #e4e4e4;color: #777777;}.uagb-block-e81fa8c9.uagb-equal_height_inline-read-more-buttons .uagb-post__inner-wrap .uagb-post__text:last-child{left: 0px;right: 0px;}.uagb-block-e81fa8c9.wp-block-uagb-post-grid .uag-post-grid-wrapper{padding-right: 20px;padding-left: 20px;width: 100%;display: flex;flex-direction: column;justify-content: center;}.uagb-block-e81fa8c9 .uagb-post__text.uagb-post__cta{font-family: \"Poppins\";font-weight: 600;font-size: 13px;line-height: 26px;letter-spacing: 0.1em;}.uagb-block-e81fa8c9 .uagb-post__text.uagb-post__cta a{font-family: \"Poppins\";font-weight: 600;font-size: 13px;line-height: 26px;letter-spacing: 0.1em;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-41abe729{width: 100%;}.wp-block-uagb-container.uagb-block-41abe729{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-44572301{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-44572301 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-44572301{padding-top: 60px;padding-bottom: 60px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: var(--ast-global-color-1);}.wp-block-uagb-advanced-heading.uagb-block-d969377a .uagb-heading-text{font-size: 24px;line-height: 31px;}.wp-block-uagb-advanced-heading.uagb-block-c204dab9 .uagb-heading-text{font-size: 15px;line-height: 28px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1fa6aee9{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1fa6aee9 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-1fa6aee9{padding-top: 60px;padding-bottom: 60px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #f2f2f2;}.wp-block-uagb-advanced-heading.uagb-block-0cd02049 .uagb-heading-text{font-size: 24px;line-height: 30px;}.wp-block-uagb-advanced-heading.uagb-block-15f800a4.wp-block-uagb-advanced-heading {padding-top: 20px;padding-right: 0px;padding-bottom: 30px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-15f800a4 .uagb-heading-text{font-size: 15px;line-height: 28px;}.wp-block-uagb-advanced-heading.uagb-block-12a8fe6e .uagb-heading-text{font-size: 24px;line-height: 30px;}.wp-block-uagb-advanced-heading.uagb-block-529bed5b.wp-block-uagb-advanced-heading {padding-top: 0px;padding-right: 15px;padding-bottom: 0px;padding-left: 15px;margin-top: 15px;margin-right: 0px;margin-bottom: 30px;margin-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-529bed5b .uagb-heading-text{font-size: 15px;line-height: 28px;}.uagb-block-b5f3efe9.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-b5f3efe9.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-4eb9cfab.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: solid;border-color: #333;}.wp-block-uagb-buttons .uagb-block-4eb9cfab .uagb-buttons-repeater.wp-block-button__link{border-style: solid;border-color: #333;}.wp-block-uagb-advanced-heading.uagb-block-37120996 .uagb-heading-text{font-size: 24px;line-height: 30px;}.wp-block-uagb-advanced-heading.uagb-block-3fa33b75.wp-block-uagb-advanced-heading {padding-top: 0px;padding-right: 15px;padding-bottom: 0px;padding-left: 15px;margin-top: 15px;margin-right: 0px;margin-bottom: 30px;margin-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-3fa33b75 .uagb-heading-text{font-size: 15px;line-height: 28px;}.uagb-block-3114da5a.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-3114da5a.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-e63aabc4.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: solid;border-color: #333;}.wp-block-uagb-buttons .uagb-block-e63aabc4 .uagb-buttons-repeater.wp-block-button__link{border-style: solid;border-color: #333;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-71fce647{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-71fce647 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-71fce647{padding-top: 60px;padding-bottom: 60px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: var(--ast-global-color-1);}.wp-block-uagb-advanced-heading.uagb-block-9e753b84 .uagb-heading-text{font-size: 24px;line-height: 30px;}.wp-block-uagb-advanced-heading.uagb-block-c8928e78.wp-block-uagb-advanced-heading {padding-top: 20px;padding-right: 0px;padding-bottom: 30px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-c8928e78 .uagb-heading-text{font-size: 15px;line-height: 28px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-0a1b82a2{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-0a1b82a2 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: stretch;justify-content: flex-start;flex-wrap: wrap;align-content: center;row-gap: 30px;column-gap: 29px;}.wp-block-uagb-container.uagb-block-0a1b82a2{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-direction: row;align-items: stretch;justify-content: flex-start;flex-wrap: wrap;align-content: center;row-gap: 30px;column-gap: 29px;}.wp-block-uagb-container.uagb-block-0a1b82a2.wp-block-uagb-container > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not( .spectra-container-link-overlay ):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-container-inner-blocks-wrap){width: 100%;}.wp-block-uagb-container.uagb-block-0a1b82a2.wp-block-uagb-container > .uagb-container-inner-blocks-wrap > *:not( .wp-block-uagb-column ):not( .wp-block-uagb-section ):not( .uagb-container__shape ):not( .uagb-container__video-wrap ):not( .uagb-slider-container ):not(.spectra-image-gallery__control-lightbox){width: 100%;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7f6d21c2{max-width: 48%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7f6d21c2 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-7f6d21c2{padding-top: 30px;padding-bottom: 30px;padding-left: 25px;padding-right: 25px;margin-top:  !important;margin-bottom:  !important;order: initial;border-style: solid;border-color: #d6dae1;background-color: #f2f2f2;}.uagb-block-ee3fc18b.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-advanced-heading.uagb-block-1469f899 .uagb-heading-text{font-size: 20px;}.uagb-block-f07ced51.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-f07ced51.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-786b5a71.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: solid;border-color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-786b5a71 .uagb-buttons-repeater.wp-block-button__link{border-style: solid;border-color: var(--ast-global-color-1);}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7459a9cf{max-width: 48%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7459a9cf > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-7459a9cf{padding-top: 30px;padding-bottom: 30px;padding-left: 25px;padding-right: 25px;margin-top:  !important;margin-bottom:  !important;order: initial;border-style: solid;border-color: #d6dae1;background-color: #f2f2f2;}.uagb-block-141f4801.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-advanced-heading.uagb-block-f0579925 .uagb-heading-text{font-size: 20px;}.uagb-block-062a311b.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-062a311b.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-0b9255f8.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: solid;border-color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-0b9255f8 .uagb-buttons-repeater.wp-block-button__link{border-style: solid;border-color: var(--ast-global-color-1);}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3e0ad83d{max-width: 48%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3e0ad83d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-3e0ad83d{padding-top: 30px;padding-bottom: 30px;padding-left: 25px;padding-right: 25px;margin-top:  !important;margin-bottom:  !important;order: initial;border-style: solid;border-color: #d6dae1;background-color: #f2f2f2;}.uagb-block-4788ca6b.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-advanced-heading.uagb-block-1ae13353 .uagb-heading-text{font-size: 20px;}.uagb-block-c8d0d2a3.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-c8d0d2a3.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-0ad08212.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: solid;border-color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-0ad08212 .uagb-buttons-repeater.wp-block-button__link{border-style: solid;border-color: var(--ast-global-color-1);}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e99beffd{max-width: 48%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e99beffd > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-e99beffd{padding-top: 30px;padding-bottom: 30px;padding-left: 25px;padding-right: 25px;margin-top:  !important;margin-bottom:  !important;order: initial;border-style: solid;border-color: #d6dae1;background-color: #f2f2f2;}.uagb-block-b488c6c6.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-advanced-heading.uagb-block-fa6b4846 .uagb-heading-text{font-size: 20px;}.uagb-block-5b55a0a4.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-5b55a0a4.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-5ac5155c.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: solid;border-color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-5ac5155c .uagb-buttons-repeater.wp-block-button__link{border-style: solid;border-color: var(--ast-global-color-1);}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c31d078c{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c31d078c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-c31d078c{padding-top: 60px;padding-bottom: 60px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #ededed;}.wp-block-uagb-advanced-heading.uagb-block-159ab93a .uagb-heading-text{font-size: 24px;line-height: 30px;}.wp-block-uagb-advanced-heading.uagb-block-027d72db.wp-block-uagb-advanced-heading {padding-top: 20px;padding-right: 0px;padding-bottom: 30px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-027d72db .uagb-heading-text{font-size: 15px;line-height: 28px;}.uagb-block-e81fa8c9.wp-block-uagb-post-grid.is-grid{grid-template-columns: repeat(2 , minmax(0, 1fr));}.uagb-block-e81fa8c9.is-grid.uagb-post__items{row-gap: 30px;column-gap: 30px;}.uagb-block-e81fa8c9:not(.is-grid).uagb-post__items article{padding-right: 15px;padding-left: 15px;margin-bottom: 30px;}.uagb-block-e81fa8c9:not(.is-grid).uagb-post__items{margin-right: -15px;margin-left: -15px;}.uagb-block-e81fa8c9.is-grid .uagb-post__inner-wrap .uagb-post__image:first-child{margin-left: 0px;margin-right: 0px;margin-top: 0px;}.uagb-block-e81fa8c9.uagb-post-grid .wp-block-button.uagb-post__text.uagb-post__cta .uagb-text-link.wp-block-button__link {border-style: none;}.uagb-block-e81fa8c9 .uagb-post__cta a{border-style: none;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-41abe729{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-block-41abe729{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-44572301{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-44572301 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-44572301{padding-top: 100px;padding-bottom: 90px;padding-left: 20px;padding-right: 20px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: var(--ast-global-color-1);}.wp-block-uagb-advanced-heading.uagb-block-d969377a.wp-block-uagb-advanced-heading {padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-d969377a .uagb-heading-text{font-size: 30px;line-height: 36px;}.wp-block-uagb-advanced-heading.uagb-block-c204dab9.wp-block-uagb-advanced-heading {padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 20px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-c204dab9 .uagb-heading-text{font-size: 14px;line-height: 26px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1fa6aee9{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1fa6aee9 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-1fa6aee9{padding-top: 50px;padding-bottom: 65px;padding-left: 20px;padding-right: 20px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: #f2f2f2;}.wp-block-uagb-advanced-heading.uagb-block-0cd02049 .uagb-heading-text{font-size: 22px;line-height: 30px;}.wp-block-uagb-advanced-heading.uagb-block-15f800a4.wp-block-uagb-advanced-heading {margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-15f800a4 .uagb-heading-text{font-size: 14px;line-height: 26px;}.wp-block-uagb-advanced-heading.uagb-block-12a8fe6e .uagb-heading-text{font-size: 22px;line-height: 30px;}.wp-block-uagb-advanced-heading.uagb-block-529bed5b.wp-block-uagb-advanced-heading {padding-top: 0px;padding-right: 10px;padding-bottom: 0px;padding-left: 10px;margin-top: 10px;margin-right: 0px;margin-bottom: 20px;margin-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-529bed5b .uagb-heading-text{font-size: 14px;line-height: 26px;}.uagb-block-b5f3efe9.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-b5f3efe9.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-4eb9cfab.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: solid;border-color: #333;}.wp-block-uagb-buttons .uagb-block-4eb9cfab .uagb-buttons-repeater.wp-block-button__link{border-style: solid;border-color: #333;}.wp-block-uagb-advanced-heading.uagb-block-37120996 .uagb-heading-text{font-size: 22px;line-height: 30px;}.wp-block-uagb-advanced-heading.uagb-block-3fa33b75.wp-block-uagb-advanced-heading {padding-top: 0px;padding-right: 10px;padding-bottom: 0px;padding-left: 10px;margin-top: 10px;margin-right: 0px;margin-bottom: 20px;margin-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-3fa33b75 .uagb-heading-text{font-size: 14px;line-height: 26px;}.uagb-block-3114da5a.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-3114da5a.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-e63aabc4.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: solid;border-color: #333;}.wp-block-uagb-buttons .uagb-block-e63aabc4 .uagb-buttons-repeater.wp-block-button__link{border-style: solid;border-color: #333;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-71fce647{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-71fce647 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-71fce647{padding-top: 40px;padding-bottom: 40px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: var(--ast-global-color-1);}.wp-block-uagb-advanced-heading.uagb-block-9e753b84 .uagb-heading-text{font-size: 22px;line-height: 30px;}.wp-block-uagb-advanced-heading.uagb-block-c8928e78.wp-block-uagb-advanced-heading {padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 20px;margin-right: 0px;margin-bottom: 30px;margin-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-c8928e78 .uagb-heading-text{font-size: 14px;line-height: 26px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-0a1b82a2{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-0a1b82a2 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;align-items: stretch;flex-wrap: wrap;row-gap: 20px;}.wp-block-uagb-container.uagb-block-0a1b82a2{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;row-gap: 20px;order: initial;align-items: stretch;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7f6d21c2{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7f6d21c2 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-7f6d21c2{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;order: initial;border-style: solid;border-color: #d6dae1;background-color: #f2f2f2;flex-wrap: wrap;}.uagb-block-ee3fc18b.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-advanced-heading.uagb-block-1469f899.wp-block-uagb-advanced-heading {padding-top: 14px;padding-right: 0px;padding-bottom: 14px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-1469f899 .uagb-heading-text{font-size: 18px;}.uagb-block-f07ced51.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-f07ced51.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-786b5a71.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: solid;border-color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-786b5a71 .uagb-buttons-repeater.wp-block-button__link{border-style: solid;border-color: var(--ast-global-color-1);}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7459a9cf{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7459a9cf > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-7459a9cf{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;order: initial;border-style: solid;border-color: #d6dae1;background-color: #f2f2f2;flex-wrap: wrap;}.uagb-block-141f4801.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-advanced-heading.uagb-block-f0579925.wp-block-uagb-advanced-heading {padding-top: 14px;padding-right: 0px;padding-bottom: 14px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-f0579925 .uagb-heading-text{font-size: 18px;}.uagb-block-062a311b.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-062a311b.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-0b9255f8.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: solid;border-color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-0b9255f8 .uagb-buttons-repeater.wp-block-button__link{border-style: solid;border-color: var(--ast-global-color-1);}.wp-block-uagb-container.uagb-is-root-container .uagb-block-3e0ad83d{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-3e0ad83d > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-3e0ad83d{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;order: initial;border-style: solid;border-color: #d6dae1;background-color: #f2f2f2;flex-wrap: wrap;}.uagb-block-4788ca6b.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-advanced-heading.uagb-block-1ae13353.wp-block-uagb-advanced-heading {padding-top: 14px;padding-right: 0px;padding-bottom: 14px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-1ae13353 .uagb-heading-text{font-size: 18px;}.uagb-block-c8d0d2a3.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-c8d0d2a3.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-0ad08212.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: solid;border-color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-0ad08212 .uagb-buttons-repeater.wp-block-button__link{border-style: solid;border-color: var(--ast-global-color-1);}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e99beffd{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e99beffd > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-e99beffd{padding-top: 20px;padding-bottom: 20px;padding-left: 20px;padding-right: 20px;margin-top:  !important;margin-bottom:  !important;order: initial;border-style: solid;border-color: #d6dae1;background-color: #f2f2f2;flex-wrap: wrap;}.uagb-block-b488c6c6.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.wp-block-uagb-advanced-heading.uagb-block-fa6b4846.wp-block-uagb-advanced-heading {padding-top: 14px;padding-right: 0px;padding-bottom: 14px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-fa6b4846 .uagb-heading-text{font-size: 18px;}.uagb-block-5b55a0a4.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-5b55a0a4.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-buttons .uagb-block-5ac5155c.wp-block-button.is-style-outline .uagb-button__wrapper .wp-block-button__link.uagb-buttons-repeater{border-style: solid;border-color: var(--ast-global-color-1);}.wp-block-uagb-buttons .uagb-block-5ac5155c .uagb-buttons-repeater.wp-block-button__link{border-style: solid;border-color: var(--ast-global-color-1);}.wp-block-uagb-container.uagb-is-root-container .uagb-block-c31d078c{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-c31d078c > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-c31d078c{padding-top: 40px;padding-bottom: 40px;padding-left: 20px;padding-right: 20px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: #ededed;}.wp-block-uagb-advanced-heading.uagb-block-159ab93a .uagb-heading-text{font-size: 22px;line-height: 30px;}.wp-block-uagb-advanced-heading.uagb-block-027d72db.wp-block-uagb-advanced-heading {padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 20px;margin-right: 0px;margin-bottom: 30px;margin-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-027d72db .uagb-heading-text{font-size: 14px;line-height: 26px;}.uagb-block-e81fa8c9.wp-block-uagb-post-grid.is-grid{grid-template-columns: repeat(1 , minmax(0, 1fr));}.uagb-block-e81fa8c9 .uagb-post__inner-wrap .uagb-post-grid-byline{padding-bottom: 0px;}.uagb-block-e81fa8c9 .uagb-post__inner-wrap .uagb-post__excerpt{padding-bottom: 10px;}.uagb-block-e81fa8c9.is-grid.uagb-post__items{row-gap: 30px;column-gap: 30px;}.uagb-block-e81fa8c9:not(.is-grid).uagb-post__items article{padding-right: 15px;padding-left: 15px;margin-bottom: 30px;}.uagb-block-e81fa8c9:not(.is-grid).uagb-post__items{margin-right: -15px;margin-left: -15px;}.uagb-block-e81fa8c9.is-grid .uagb-post__inner-wrap .uagb-post__image:first-child{margin-left: 0px;margin-right: 0px;margin-top: 0px;}.uagb-block-e81fa8c9.uagb-post-grid .wp-block-button.uagb-post__text.uagb-post__cta .uagb-text-link.wp-block-button__link {border-style: none;}.uagb-block-e81fa8c9.wp-block-uagb-post-grid .uag-post-grid-wrapper{width: unset;}.uagb-block-e81fa8c9 .uagb-post__text.uagb-post__title{font-size: 16px;}.uagb-block-e81fa8c9 .uagb-post__text.uagb-post__title a{font-size: 16px;}.uagb-block-e81fa8c9 .uagb-post__text.uagb-post__excerpt{font-size: 14px;line-height: 26px;}}.uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media(max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media(max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}.uagb-block-8ddb406d.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-8ddb406d.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-8ddb406d.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-8ddb406d.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-8ddb406d.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-8ddb406d.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-8ddb406d.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-8ddb406d.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-8ddb406d.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-8ddb406d.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-8ddb406d.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-8ddb406d.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-8ddb406d.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-8ddb406d.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-8ddb406d.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}@media only screen and (max-width: 976px) {.uagb-block-8ddb406d.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}@media only screen and (max-width: 767px) {.uagb-block-8ddb406d.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}.wp-block-uagb-advanced-heading.uagb-block-35454055.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-35454055.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-35454055.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-35454055.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-1bc1662a.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-1bc1662a.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-1bc1662a.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-1bc1662a.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-86fe7c65.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-86fe7c65.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-86fe7c65.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-86fe7c65.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.uagb-block-5eb5d2b8.wp-block-uagb-image{text-align: center;justify-content: center;align-self: center;}.uagb-block-5eb5d2b8 .wp-block-uagb-image__figure{align-items: center;}.uagb-block-5eb5d2b8.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-5eb5d2b8.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-5eb5d2b8.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-5eb5d2b8.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-5eb5d2b8.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-5eb5d2b8.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-5eb5d2b8.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-5eb5d2b8.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-5eb5d2b8.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-5eb5d2b8.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-5eb5d2b8.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 150px;height: auto;}.uagb-block-5eb5d2b8.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-5eb5d2b8.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-5eb5d2b8.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-5eb5d2b8.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}@media only screen and (max-width: 976px) {.uagb-block-5eb5d2b8.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 150px;height: auto;}}@media only screen and (max-width: 767px) {.uagb-block-5eb5d2b8.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 150px;height: auto;}}.uagb-block-02bc7fcb.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-02bc7fcb.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-02bc7fcb.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-02bc7fcb.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-02bc7fcb.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-02bc7fcb.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-02bc7fcb.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-02bc7fcb.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-02bc7fcb.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-02bc7fcb.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-02bc7fcb.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-02bc7fcb.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-02bc7fcb.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-02bc7fcb.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-02bc7fcb.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}@media only screen and (max-width: 976px) {.uagb-block-02bc7fcb.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}@media only screen and (max-width: 767px) {.uagb-block-02bc7fcb.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}\";s:2:\"js\";s:656:\"document.addEventListener(\"DOMContentLoaded\", function(){ window.addEventListener( 'load', function() {\n\tUAGBButtonChild.init( '.uagb-block-4eb9cfab' );\n});\nwindow.addEventListener( 'load', function() {\n\tUAGBButtonChild.init( '.uagb-block-e63aabc4' );\n});\nwindow.addEventListener( 'load', function() {\n\tUAGBButtonChild.init( '.uagb-block-786b5a71' );\n});\nwindow.addEventListener( 'load', function() {\n\tUAGBButtonChild.init( '.uagb-block-0b9255f8' );\n});\nwindow.addEventListener( 'load', function() {\n\tUAGBButtonChild.init( '.uagb-block-0ad08212' );\n});\nwindow.addEventListener( 'load', function() {\n\tUAGBButtonChild.init( '.uagb-block-5ac5155c' );\n});\n });\";s:18:\"current_block_list\";a:20:{i:0;s:14:\"uagb\/container\";i:1;s:14:\"core\/shortcode\";i:3;s:21:\"uagb\/advanced-heading\";i:4;s:12:\"core\/columns\";i:5;s:11:\"core\/column\";i:6;s:10:\"core\/cover\";i:7;s:12:\"uagb\/buttons\";i:8;s:18:\"uagb\/buttons-child\";i:11;s:10:\"uagb\/image\";i:12;s:14:\"uagb\/post-grid\";i:13;s:10:\"core\/group\";i:14;s:12:\"core\/heading\";i:15;s:15:\"core\/categories\";i:16;s:14:\"core\/paragraph\";i:17;s:17:\"core\/latest-posts\";i:18;s:17:\"core\/widget-group\";i:19;s:11:\"core\/search\";i:20;s:14:\"core\/tag-cloud\";i:21;s:17:\"core\/social-links\";i:22;s:16:\"core\/social-link\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";i:1788272747;s:6:\"gfonts\";a:1:{s:7:\"Poppins\";a:2:{s:10:\"fontfamily\";s:7:\"Poppins\";s:12:\"fontvariants\";a:4:{i:0;s:3:\"300\";i:1;s:3:\"400\";i:2;s:3:\"500\";i:3;s:3:\"600\";}}}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false,"ultp_layout_landscape_large":false,"ultp_layout_landscape":false,"ultp_layout_portrait":false,"ultp_layout_square":false},"uagb_author_info":{"display_name":"trades_admin","author_link":"https:\/\/staging.accordglobaltrade.com\/tr\/author\/trades_admin\/"},"uagb_comment_info":0,"uagb_excerpt":"Entrepreneurs in Emerging Markets We are Buyers and Sellers of Exportable &amp; Importable Goods and Experts in Managing International Trade Risks. We help exporters gain access to new foreign markets and importers to locate sought-after commodities &amp; products. Exporting &amp; Importing We specialize in providing solutions &amp; services to both exporters and importers, connecting our&hellip;","_links":{"self":[{"href":"https:\/\/staging.accordglobaltrade.com\/tr\/wp-json\/wp\/v2\/pages\/19","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.accordglobaltrade.com\/tr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/staging.accordglobaltrade.com\/tr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/staging.accordglobaltrade.com\/tr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.accordglobaltrade.com\/tr\/wp-json\/wp\/v2\/comments?post=19"}],"version-history":[{"count":123,"href":"https:\/\/staging.accordglobaltrade.com\/tr\/wp-json\/wp\/v2\/pages\/19\/revisions"}],"predecessor-version":[{"id":2314,"href":"https:\/\/staging.accordglobaltrade.com\/tr\/wp-json\/wp\/v2\/pages\/19\/revisions\/2314"}],"wp:attachment":[{"href":"https:\/\/staging.accordglobaltrade.com\/tr\/wp-json\/wp\/v2\/media?parent=19"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}