{"id":39,"date":"2023-12-28T04:53:30","date_gmt":"2023-12-28T04:53:30","guid":{"rendered":"https:\/\/staging.accordglobaltrade.com\/?page_id=39"},"modified":"2024-03-17T04:26:50","modified_gmt":"2024-03-17T04:26:50","slug":"trade-agency-representation","status":"publish","type":"page","link":"https:\/\/staging.accordglobaltrade.com\/tr\/trade-agency-representation\/","title":{"rendered":"Ticaret Ajans\u0131 Temsilcili\u011fi"},"content":{"rendered":"<div class=\"wp-block-uagb-container ic-arrow uagb-block-4511f953 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-20071865\"><h2 class=\"uagb-heading-text\">Ticaret Ajans\u0131 Temsilcili\u011fi<\/h2><\/div>\n\n\n<div class=\"breadcrumbs align ic-breadcrumb-wrapper wp-block-bcn-breadcrumb-trail has-text-color has-background\" vocab=\"https:\/\/schema.org\/\" typeof=\"BreadcrumbList\">\n\t<span><\/span>\n\t<span property=\"itemListElement\" typeof=\"ListItem\"><a property=\"item\" typeof=\"WebPage\" title=\"Accord Global Trade&#039;e gidin.\" href=\"https:\/\/staging.accordglobaltrade.com\/tr\" class=\"home\" aria-current=\"page\"><span property=\"name\">Ev<\/span><\/a><meta property=\"position\" content=\"1\"><\/span><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-7857a908 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-e6c4ffc9\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-9eff9916\"><h2 class=\"uagb-heading-text\">Acente &amp; Ticari Temsilcilik<\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-36ffe861\"><p class=\"uagb-heading-text\">Uluslararas\u0131 ithalat\/ihracat pazar\u0131nda \u00dcreticilere, Tedarik\u00e7ilere, \u0130malat\u00e7\u0131lara ve Son Al\u0131c\u0131lara Acentelik ve Ticari Temsilcilik hizmetleri sa\u011flama konusunda uzman\u0131z.<\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-a3509b53\"><p class=\"uagb-heading-text\">Hizmetlerimiz, uluslararas\u0131 ticarette ba\u015far\u0131l\u0131 olmak i\u00e7in benzersiz i\u015f gereksinimlerine uygun \u00f6zelle\u015ftirilmi\u015f hizmetler sa\u011flayarak yeni d\u0131\u015f pazarlara a\u00e7\u0131lmaya olanak verecek \u015fekilde tasarlanm\u0131\u015ft\u0131r. \u00dcr\u00fcnlerimiz, hizmetlerimiz ve \u00e7\u00f6z\u00fcmlerimiz d\u00fcnya \u00e7ap\u0131nda i\u015f ili\u015fkileri ve kilit stratejik ortaklar taraf\u0131ndan tam olarak desteklenmektedir.<\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-9fc3be8e\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"803\" src=\"https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2024\/01\/commercial-representation-content.jpg\" alt=\"\" class=\"wp-image-811\" srcset=\"https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2024\/01\/commercial-representation-content.jpg 1200w, https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2024\/01\/commercial-representation-content-300x201.jpg 300w, https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2024\/01\/commercial-representation-content-1024x685.jpg 1024w, https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2024\/01\/commercial-representation-content-768x514.jpg 768w, https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2024\/01\/commercial-representation-content-18x12.jpg 18w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/figure>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-52ad1add alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-36b4e363\"><h2 class=\"uagb-heading-text\">\u0130hracat \/ \u0130thalat Y\u00f6netim Hizmetleri<\/h2><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-b8fc6eb6 wp-block-columns-is-layout-flex\" style=\"padding-top:0;padding-right:0;padding-bottom:0;padding-left:0\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"156\" height=\"156\" src=\"https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2024\/01\/export-156x156-1.png\" alt=\"\" class=\"wp-image-789\" srcset=\"https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2024\/01\/export-156x156-1.png 156w, https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2024\/01\/export-156x156-1-150x150.png 150w, https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2024\/01\/export-156x156-1-12x12.png 12w\" sizes=\"auto, (max-width: 156px) 100vw, 156px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-f3e9723f\"><h2 class=\"uagb-heading-text\">\u0130hracat\u00e7\u0131lar (Nihai Tedarik\u00e7iler)<\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-eeb70224\"><p class=\"uagb-heading-text\">Yeni d\u0131\u015f pazarlara girmeye \u00e7al\u0131\u015fan yabanc\u0131 \u00fcreticilerin, tedarik\u00e7ilerin ve imalat\u00e7\u0131lar\u0131n ihtiya\u00e7lar\u0131n\u0131, kaliteli mallar\u0131n ve \u00fcr\u00fcnlerin nitelikli ithalat\u00e7\u0131lara bulunmas\u0131na, pazarlanmas\u0131na ve ihra\u00e7 edilmesine yard\u0131mc\u0131 olarak destekliyoruz. Bilinmeyen d\u0131\u015f pazarlardaki \u015firketler i\u00e7in bir ihracat departman\u0131, \u00f6zel distrib\u00fct\u00f6r, sat\u0131\u015f acentesi veya temsilci olarak hareket ediyoruz.<\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-69413768\"><p class=\"uagb-heading-text\">\u0130hracat\u00e7\u0131lar\u0131m\u0131z\u0131 potansiyel ithalat\u00e7\u0131lar\/da\u011f\u0131t\u0131c\u0131lar veya m\u00fc\u015fterilerimizin emtialar\u0131, \u00fcr\u00fcnleri ve hizmetleriyle ilgilenen yat\u0131r\u0131mc\u0131larla bulu\u015fturarak yeni pazarlara ad\u0131m att\u0131\u011f\u0131n\u0131zda sat\u0131\u015f kanallar\u0131n\u0131 g\u00fcvenle a\u00e7aca\u011f\u0131z. \u00d6nceli\u011fimiz, \u015firketinizin emtialar\u0131 veya \u00fcr\u00fcnleri i\u00e7in y\u00fcksek talep g\u00f6ren, kullan\u0131lmayan k\u00fcresel pazarlarda k\u00fcresel da\u011f\u0131t\u0131m elde ederek sat\u0131\u015flar\u0131 art\u0131rmak, i\u015finizin uzun \u00f6m\u00fcrl\u00fc olmas\u0131n\u0131 ve ekonomik b\u00fcy\u00fcmeyi sa\u011flamakt\u0131r.<\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"156\" height=\"156\" src=\"https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2024\/01\/import2-156x156-1.png\" alt=\"\" class=\"wp-image-823\" srcset=\"https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2024\/01\/import2-156x156-1.png 156w, https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2024\/01\/import2-156x156-1-150x150.png 150w, https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2024\/01\/import2-156x156-1-12x12.png 12w\" sizes=\"auto, (max-width: 156px) 100vw, 156px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-be809159\"><h2 class=\"uagb-heading-text\">\u0130thalat\u00e7\u0131lar (Nihai Al\u0131c\u0131lar)<\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-e82cc950\"><p class=\"uagb-heading-text\">S\u00f6zle\u015fme m\u00fczakereleri, hukuki dan\u0131\u015fmanl\u0131k, navlun, sigorta, finansman, risk analizi, g\u00fcmr\u00fck vergileri ve vergiler konusundaki uzmanl\u0131\u011f\u0131m\u0131z, \u015firketinizi uluslararas\u0131 ticaret s\u00fcrecinde s\u00fcrprizlerden korur. Sadece en iyi ko\u015fullar\u0131 arayarak emtia ve \u00fcr\u00fcn tedariki konusunda uzman\u0131z. Talep odakl\u0131 tedarik zinciri modeline dayal\u0131 olarak do\u011frudan \u00fcreticilerden, tedarik\u00e7ilerden ve imalat\u00e7\u0131lardan al\u0131mlar yap\u0131yoruz.<\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-d77251af\"><p class=\"uagb-heading-text\">\u0130htiya\u00e7lar\u0131n\u0131z analiz edildikten sonra, ticaret uzmanlar\u0131m\u0131z pazar ara\u015ft\u0131rmas\u0131 yapacak ve maliyetleri d\u00fc\u015f\u00fcr\u00fcrken, karl\u0131l\u0131\u011f\u0131 art\u0131r\u0131rken ve uygun fiyatl\u0131 tedarik\u00e7ilerle daha iyi kaliteyi se\u00e7erken ihtiya\u00e7lar\u0131n\u0131z\u0131 kar\u015f\u0131lamak i\u00e7in nitelikli \u00fcreticiler, tedarik\u00e7iler ve imalat\u00e7\u0131lar bulacakt\u0131r.<\/p><\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container ic-conditions-wrapper uagb-block-f2a0f024 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-e65df95c\"><h2 class=\"uagb-heading-text\">A\u015fa\u011f\u0131daki ko\u015fullar alt\u0131nda faaliyet g\u00f6steriyoruz:<\/h2><\/div>\n\n\n\n<ol class=\"wp-block-list\" style=\"margin-right:0%;margin-left:0%\">\n<li>\u0130ster tedarik\u00e7i ister nihai al\u0131c\u0131 olsun, if\u015fa edilen bir as\u0131l i\u00e7in ticari temsilci veya ticari vekil olarak hareket ederiz.<\/li>\n\n\n\n<li>Uluslararas\u0131 ticari acentelik s\u00f6zle\u015fmesi en az bir y\u0131ll\u0131k bir s\u00fcre i\u00e7in imzalan\u0131r.<\/li>\n\n\n\n<li>Bir randevunun niteli\u011fine ba\u011fl\u0131 olarak, acentelik hizmetleri komisyon veya avans esas\u0131na g\u00f6re sunulabilir.<\/li>\n<\/ol>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container ic-product-services-wrapper uagb-block-1fa6aee9 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-0cd02049\"><h2 class=\"uagb-heading-text\">Uluslararas\u0131 Ticareti Geni\u015fletme \u0130htiya\u00e7lar\u0131n\u0131z\u0131 G\u00f6r\u00fc\u015felim<\/h2><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-constrained wp-container-core-column-is-layout-95730b41 wp-block-column-is-layout-constrained\" style=\"padding-top:0;padding-bottom:0;flex-basis:100%\">\n<div class=\"wp-block-cover alignfull ic-help-wrapper\" style=\"min-height:405px;aspect-ratio:unset;\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-0 has-background-dim\" style=\"background-color:#2c3066\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"2160\" height=\"1064\" class=\"wp-block-cover__image-background wp-image-463\" alt=\"\" src=\"https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2024\/01\/competitive-advantages-banner-1.jpg\" data-object-fit=\"cover\" srcset=\"https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2024\/01\/competitive-advantages-banner-1.jpg 2160w, https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2024\/01\/competitive-advantages-banner-1-300x148.jpg 300w, https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2024\/01\/competitive-advantages-banner-1-1024x504.jpg 1024w, https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2024\/01\/competitive-advantages-banner-1-768x378.jpg 768w, https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2024\/01\/competitive-advantages-banner-1-1536x757.jpg 1536w, https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2024\/01\/competitive-advantages-banner-1-2048x1009.jpg 2048w, https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2024\/01\/competitive-advantages-banner-1-18x9.jpg 18w\" sizes=\"auto, (max-width: 2160px) 100vw, 2160px\" \/><div class=\"wp-block-cover__inner-container is-layout-constrained wp-container-core-cover-is-layout-db9edeb8 wp-block-cover-is-layout-constrained\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-94f42e7f\"><h2 class=\"uagb-heading-text\">Geni\u015flemeye Haz\u0131r m\u0131s\u0131n\u0131z <br>Uluslararas\u0131 m\u0131?<\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-62798e90 ic-shape\"><p class=\"uagb-heading-text\">Acente ve Ticari Temsilcilik i\u00e7in<\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-b44e2020\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap\">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-bdede035 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"https:\/\/staging.accordglobaltrade.com\/tr\/request-for-international-trade-services\/\" rel=\"follow noopener\" target=\"_self\"><div class=\"uagb-button__link\">\u015eimdi Bize Ula\u015f\u0131n<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Trade Agency Representation Agency &amp; Commercial Representation We specialize in providing Agency &amp; Commercial Representation services to Producers, Suppliers, Manufacturers and End Buyers in the international import\/export marketplace. Our services have been designed to allow expansions to new foreign markets by providing customized services that fit unique business requirements in order to succeed in international [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-39","page","type-page","status-publish","hentry"],"spectra_custom_meta":{"_edit_lock":["1710649611:1"],"_edit_last":["1"],"_uagb_previous_block_counts":["a:90:{s:21:\"uagb\/advanced-heading\";i:15;s:15:\"uagb\/blockquote\";i:0;s:12:\"uagb\/buttons\";i:1;s:18:\"uagb\/buttons-child\";i:1;s:19:\"uagb\/call-to-action\";i:0;s:15:\"uagb\/cf7-styler\";i:0;s:11:\"uagb\/column\";i:0;s:12:\"uagb\/columns\";i:0;s:14:\"uagb\/container\";i:7;s:21:\"uagb\/content-timeline\";i:0;s:27:\"uagb\/content-timeline-child\";i:0;s:14:\"uagb\/countdown\";i:0;s:12:\"uagb\/counter\";i:0;s:8:\"uagb\/faq\";i:0;s:14:\"uagb\/faq-child\";i:0;s:10:\"uagb\/forms\";i:0;s:17:\"uagb\/forms-accept\";i:0;s:19:\"uagb\/forms-checkbox\";i:0;s:15:\"uagb\/forms-date\";i:0;s:16:\"uagb\/forms-email\";i:0;s:17:\"uagb\/forms-hidden\";i:0;s:15:\"uagb\/forms-name\";i:0;s:16:\"uagb\/forms-phone\";i:0;s:16:\"uagb\/forms-radio\";i:0;s:17:\"uagb\/forms-select\";i:0;s:19:\"uagb\/forms-textarea\";i:0;s:17:\"uagb\/forms-toggle\";i:0;s:14:\"uagb\/forms-url\";i:0;s:14:\"uagb\/gf-styler\";i:0;s:15:\"uagb\/google-map\";i:0;s:11:\"uagb\/how-to\";i:0;s:16:\"uagb\/how-to-step\";i:0;s:9:\"uagb\/icon\";i:0;s:14:\"uagb\/icon-list\";i:0;s:20:\"uagb\/icon-list-child\";i:0;s:10:\"uagb\/image\";i:0;s:18:\"uagb\/image-gallery\";i:0;s:13:\"uagb\/info-box\";i:0;s:18:\"uagb\/inline-notice\";i:0;s:11:\"uagb\/lottie\";i:0;s:21:\"uagb\/marketing-button\";i:0;s:10:\"uagb\/modal\";i:0;s:18:\"uagb\/popup-builder\";i:0;s:16:\"uagb\/post-button\";i:0;s:18:\"uagb\/post-carousel\";i:0;s:17:\"uagb\/post-excerpt\";i:0;s:14:\"uagb\/post-grid\";i:0;s:15:\"uagb\/post-image\";i:0;s:17:\"uagb\/post-masonry\";i:0;s:14:\"uagb\/post-meta\";i:0;s:18:\"uagb\/post-taxonomy\";i:0;s:18:\"uagb\/post-timeline\";i:0;s:15:\"uagb\/post-title\";i:0;s:20:\"uagb\/restaurant-menu\";i:0;s:26:\"uagb\/restaurant-menu-child\";i:0;s:11:\"uagb\/review\";i:0;s:12:\"uagb\/section\";i:0;s:14:\"uagb\/separator\";i:0;s:11:\"uagb\/slider\";i:0;s:17:\"uagb\/slider-child\";i:0;s:17:\"uagb\/social-share\";i:0;s:23:\"uagb\/social-share-child\";i:0;s:16:\"uagb\/star-rating\";i:0;s:23:\"uagb\/sure-cart-checkout\";i:0;s:22:\"uagb\/sure-cart-product\";i:0;s:15:\"uagb\/sure-forms\";i:0;s:22:\"uagb\/table-of-contents\";i:0;s:9:\"uagb\/tabs\";i:0;s:15:\"uagb\/tabs-child\";i:0;s:18:\"uagb\/taxonomy-list\";i:0;s:9:\"uagb\/team\";i:0;s:16:\"uagb\/testimonial\";i:0;s:14:\"uagb\/wp-search\";i:0;s:19:\"uagb\/instagram-feed\";i:0;s:10:\"uagb\/login\";i:0;s:17:\"uagb\/loop-builder\";i:0;s:18:\"uagb\/loop-category\";i:0;s:20:\"uagb\/loop-pagination\";i:0;s:15:\"uagb\/loop-reset\";i:0;s:16:\"uagb\/loop-search\";i:0;s:14:\"uagb\/loop-sort\";i:0;s:17:\"uagb\/loop-wrapper\";i:0;s:13:\"uagb\/register\";i:0;s:19:\"uagb\/register-email\";i:0;s:24:\"uagb\/register-first-name\";i:0;s:23:\"uagb\/register-last-name\";i:0;s:22:\"uagb\/register-password\";i:0;s:30:\"uagb\/register-reenter-password\";i:0;s:19:\"uagb\/register-terms\";i:0;s:22:\"uagb\/register-username\";i:0;}"],"_uag_css_file_name":["uag-css-39.css"],"_uag_js_file_name":["uag-js-39.js"],"_uagb_last_spectra_edit":["1776993643"],"_uag_page_assets":["a:9:{s:3:\"css\";s:65440:\".wp-block-uagb-container{display:flex;position:relative;box-sizing:border-box;transition-property:box-shadow;transition-duration:.2s;transition-timing-function:ease}.wp-block-uagb-container .spectra-container-link-overlay{bottom:0;left:0;position:absolute;right:0;top:0;z-index:10}.wp-block-uagb-container.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:flex;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}.wp-block-uagb-container .wp-block-uagb-blockquote,.wp-block-uagb-container .wp-block-spectra-pro-login,.wp-block-uagb-container .wp-block-spectra-pro-register{margin:unset}.wp-block-uagb-container .uagb-container__video-wrap{height:100%;width:100%;top:0;left:0;position:absolute;overflow:hidden;-webkit-transition:opacity 1s;-o-transition:opacity 1s;transition:opacity 1s}.wp-block-uagb-container .uagb-container__video-wrap video{max-width:100%;width:100%;height:100%;margin:0;line-height:1;border:none;display:inline-block;vertical-align:baseline;-o-object-fit:cover;object-fit:cover;background-size:cover}.wp-block-uagb-container.uagb-layout-grid{display:grid;width:100%}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap{display:inherit;width:inherit}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.alignwide.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:inherit;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-info-box),body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap,body .wp-block-uagb-container>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-container-link-overlay):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-faq__outer-wrap){min-width:unset !important;width:100%;position:relative}body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container ol,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap ol{max-width:-webkit-fill-available;margin-block-start:0;margin-block-end:0;margin-left:20px}.ast-plain-container .editor-styles-wrapper .block-editor-block-list__layout.is-root-container .uagb-is-root-container.wp-block-uagb-container.alignwide{margin-left:auto;margin-right:auto}.uagb-container__shape{overflow:hidden;position:absolute;left:0;width:100%;line-height:0;direction:ltr}.uagb-container__shape-top{top:-3px}.uagb-container__shape-bottom{bottom:-3px}.uagb-container__shape.uagb-container__invert.uagb-container__shape-bottom,.uagb-container__shape.uagb-container__invert.uagb-container__shape-top{-webkit-transform:rotate(180deg);-ms-transform:rotate(180deg);transform:rotate(180deg)}.uagb-container__shape.uagb-container__shape-flip svg{transform:translateX(-50%) rotateY(180deg)}.uagb-container__shape svg{display:block;width:-webkit-calc(100% + 1.3px);width:calc(100% + 1.3px);position:relative;left:50%;-webkit-transform:translateX(-50%);-ms-transform:translateX(-50%);transform:translateX(-50%)}.uagb-container__shape .uagb-container__shape-fill{-webkit-transform-origin:center;-ms-transform-origin:center;transform-origin:center;-webkit-transform:rotateY(0deg);transform:rotateY(0deg)}.uagb-container__shape.uagb-container__shape-above-content{z-index:9;pointer-events:none}.nv-single-page-wrap .nv-content-wrap.entry-content .wp-block-uagb-container.alignfull{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw)}@media only screen and (max-width: 767px){.wp-block-uagb-container .wp-block-uagb-advanced-heading{width:-webkit-fill-available}}.wp-block-uagb-image--align-none{justify-content:center}.wp-block-uagb-advanced-heading h1,.wp-block-uagb-advanced-heading h2,.wp-block-uagb-advanced-heading h3,.wp-block-uagb-advanced-heading h4,.wp-block-uagb-advanced-heading h5,.wp-block-uagb-advanced-heading h6,.wp-block-uagb-advanced-heading p,.wp-block-uagb-advanced-heading div{word-break:break-word}.wp-block-uagb-advanced-heading .uagb-heading-text{margin:0}.wp-block-uagb-advanced-heading .uagb-desc-text{margin:0}.wp-block-uagb-advanced-heading .uagb-separator{font-size:0;border-top-style:solid;display:inline-block;margin:0 0 10px 0}.wp-block-uagb-advanced-heading .uagb-highlight{color:#f78a0c;border:0;transition:all .3s ease}.uag-highlight-toolbar{border-left:0;border-top:0;border-bottom:0;border-radius:0;border-right-color:#1e1e1e}.uag-highlight-toolbar .components-button{border-radius:0;outline:none}.uag-highlight-toolbar .components-button.is-primary{color:#fff}.uagb-buttons__outer-wrap .uagb-buttons__wrap{display:inline-flex;width:100%}.uagb-buttons__outer-wrap.uagb-btn__small-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__small-btn .uagb-buttons-repeater.ast-outline-button{padding:5px 10px}.uagb-buttons__outer-wrap.uagb-btn__medium-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__medium-btn .uagb-buttons-repeater.ast-outline-button{padding:12px 24px}.uagb-buttons__outer-wrap.uagb-btn__large-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__large-btn .uagb-buttons-repeater.ast-outline-button{padding:20px 30px}.uagb-buttons__outer-wrap.uagb-btn__extralarge-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__extralarge-btn .uagb-buttons-repeater.ast-outline-button{padding:30px 65px}@media(max-width: 976px){.uagb-buttons__outer-wrap.uagb-btn-tablet__small-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__small-btn .uagb-buttons-repeater.ast-outline-button{padding:5px 10px}.uagb-buttons__outer-wrap.uagb-btn-tablet__medium-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__medium-btn .uagb-buttons-repeater.ast-outline-button{padding:12px 24px}.uagb-buttons__outer-wrap.uagb-btn-tablet__large-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__large-btn .uagb-buttons-repeater.ast-outline-button{padding:20px 30px}.uagb-buttons__outer-wrap.uagb-btn-tablet__extralarge-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__extralarge-btn .uagb-buttons-repeater.ast-outline-button{padding:30px 65px}}@media(max-width: 767px){.uagb-buttons__outer-wrap.uagb-btn-mobile__small-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__small-btn .uagb-buttons-repeater.ast-outline-button{padding:5px 10px}.uagb-buttons__outer-wrap.uagb-btn-mobile__medium-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__medium-btn .uagb-buttons-repeater.ast-outline-button{padding:12px 24px}.uagb-buttons__outer-wrap.uagb-btn-mobile__large-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__large-btn .uagb-buttons-repeater.ast-outline-button{padding:20px 30px}.uagb-buttons__outer-wrap.uagb-btn-mobile__extralarge-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__extralarge-btn .uagb-buttons-repeater.ast-outline-button{padding:30px 65px}}.uagb-buttons__outer-wrap .uagb-buttons-repeater{display:flex;justify-content:center;align-items:center;transition:box-shadow .2s ease}.uagb-buttons__outer-wrap .uagb-buttons-repeater a.uagb-button__link{display:flex;justify-content:center}.uagb-buttons__outer-wrap .uagb-buttons-repeater .uagb-button__icon{font-size:inherit;display:flex;align-items:center}.uagb-buttons__outer-wrap .uagb-buttons-repeater .uagb-button__icon svg{fill:currentColor;width:inherit;height:inherit}.wp-block-uagb-container.uagb-block-4511f953 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-4511f953 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-4511f953 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-4511f953 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-4511f953 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-4511f953{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4511f953 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1170px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-4511f953{min-height: 476px;box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;background-repeat: no-repeat;background-position: 50% 50%;background-size: cover;background-attachment: scroll;background-image: url(https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2024\/01\/commercial-representation-header.jpg);background-clip: padding-box;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-advanced-heading.uagb-block-20071865.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-1);}.wp-block-uagb-advanced-heading.uagb-block-20071865.wp-block-uagb-advanced-heading {text-align: center;margin-top: 100px;margin-right: 0px;margin-bottom: 7px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-20071865.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-20071865.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-20071865.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-20071865.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-20071865 .uagb-heading-text{font-family: \"Poppins\";font-weight: 500;font-size: 45px;line-height: 58px;}.wp-block-uagb-container.uagb-block-7857a908 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-7857a908 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-7857a908 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-7857a908 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-7857a908 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7857a908{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7857a908 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1170px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 30px;}.wp-block-uagb-container.uagb-block-7857a908{box-shadow: 0px 0px   #00000070 ;padding-top: 100px;padding-bottom: 100px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: #fafafa;row-gap: 0px;column-gap: 30px;}.wp-block-uagb-container.uagb-block-e6c4ffc9 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-e6c4ffc9 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-e6c4ffc9 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-e6c4ffc9 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-e6c4ffc9 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e6c4ffc9{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e6c4ffc9 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1170px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-e6c4ffc9{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-advanced-heading.uagb-block-9eff9916.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-2);}.wp-block-uagb-advanced-heading.uagb-block-9eff9916.wp-block-uagb-advanced-heading {margin-top: 0px;margin-right: 0px;margin-bottom: 16px;margin-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-9eff9916.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-9eff9916.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-9eff9916.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-9eff9916.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-9eff9916 .uagb-heading-text{font-family: \"Poppins\";font-weight: 500;font-size: 32px;line-height: 42px;}.wp-block-uagb-advanced-heading.uagb-block-36ffe861.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-3);}.wp-block-uagb-advanced-heading.uagb-block-36ffe861.wp-block-uagb-advanced-heading {margin-top: 0em;margin-right: 0em;margin-bottom: 1.75em;margin-left: 0em;}.wp-block-uagb-advanced-heading.uagb-block-36ffe861.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-36ffe861.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-36ffe861.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-36ffe861.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-36ffe861 .uagb-heading-text{font-family: \"Poppins\";text-transform: none;font-weight: 400;font-size: 14px;line-height: 26px;}.wp-block-uagb-advanced-heading.uagb-block-a3509b53.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-3);}.wp-block-uagb-advanced-heading.uagb-block-a3509b53.wp-block-uagb-advanced-heading {margin-top: 0em;margin-right: 0em;margin-bottom: 1.75em;margin-left: 0em;}.wp-block-uagb-advanced-heading.uagb-block-a3509b53.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-a3509b53.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a3509b53.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a3509b53.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a3509b53 .uagb-heading-text{font-family: \"Poppins\";text-transform: none;font-weight: 400;font-size: 14px;line-height: 26px;}.wp-block-uagb-container.uagb-block-9fc3be8e .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-9fc3be8e .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-9fc3be8e .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-9fc3be8e .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-9fc3be8e .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9fc3be8e{max-width: 50%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9fc3be8e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1170px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-9fc3be8e{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-52ad1add .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-52ad1add .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-52ad1add .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-52ad1add .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-52ad1add .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-52ad1add{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-52ad1add > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1170px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: flex-end;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 70px;}.wp-block-uagb-container.uagb-block-52ad1add{box-shadow: 0px 0px   #00000070 ;padding-top: 100px;padding-bottom: 100px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: var(--ast-global-color-1);row-gap: 0px;column-gap: 70px;}.wp-block-uagb-advanced-heading.uagb-block-36b4e363.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-2);}.wp-block-uagb-advanced-heading.uagb-block-36b4e363.wp-block-uagb-advanced-heading {text-align: center;margin-top: 0px;margin-right: 0px;margin-bottom: 84px;margin-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-36b4e363.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-36b4e363.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-36b4e363.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-36b4e363.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-36b4e363 .uagb-heading-text{font-family: \"Poppins\";font-weight: 500;font-size: 32px;line-height: 42px;}.wp-block-uagb-advanced-heading.uagb-block-f3e9723f.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-2);}.wp-block-uagb-advanced-heading.uagb-block-f3e9723f.wp-block-uagb-advanced-heading {text-align: center;margin-top: 40px;margin-right: 0px;margin-bottom: 15px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-f3e9723f.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-f3e9723f.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-f3e9723f.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-f3e9723f.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-f3e9723f .uagb-heading-text{font-family: \"Poppins\";font-weight: 500;font-size: 26px;line-height: 34px;}.wp-block-uagb-advanced-heading.uagb-block-eeb70224.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-3);}.wp-block-uagb-advanced-heading.uagb-block-eeb70224.wp-block-uagb-advanced-heading {text-align: center;margin-top: 0em;margin-right: 0em;margin-bottom: 1.75em;margin-left: 0em;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-eeb70224.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-eeb70224.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-eeb70224.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-eeb70224.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-eeb70224 .uagb-heading-text{font-family: \"Poppins\";font-weight: 400;font-size: 14px;line-height: 26px;}.wp-block-uagb-advanced-heading.uagb-block-69413768.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-3);}.wp-block-uagb-advanced-heading.uagb-block-69413768.wp-block-uagb-advanced-heading {text-align: center;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-69413768.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-69413768.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-69413768.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-69413768.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-69413768 .uagb-heading-text{font-family: \"Poppins\";font-weight: 400;font-size: 14px;line-height: 26px;}.wp-block-uagb-advanced-heading.uagb-block-be809159.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-2);}.wp-block-uagb-advanced-heading.uagb-block-be809159.wp-block-uagb-advanced-heading {text-align: center;margin-top: 40px;margin-right: 0px;margin-bottom: 15px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-be809159.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-be809159.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-be809159.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-be809159.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-be809159 .uagb-heading-text{font-family: \"Poppins\";font-weight: 500;font-size: 26px;line-height: 34px;}.wp-block-uagb-advanced-heading.uagb-block-e82cc950.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-3);}.wp-block-uagb-advanced-heading.uagb-block-e82cc950.wp-block-uagb-advanced-heading {text-align: center;margin-top: 0em;margin-right: 0em;margin-bottom: 1.75em;margin-left: 0em;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-e82cc950.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-e82cc950.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-e82cc950.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-e82cc950.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-e82cc950 .uagb-heading-text{font-family: \"Poppins\";font-weight: 400;font-size: 14px;line-height: 26px;}.wp-block-uagb-advanced-heading.uagb-block-d77251af.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-3);}.wp-block-uagb-advanced-heading.uagb-block-d77251af.wp-block-uagb-advanced-heading {text-align: center;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-d77251af.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-d77251af.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-d77251af.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-d77251af.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-d77251af .uagb-heading-text{font-family: \"Poppins\";font-weight: 400;font-size: 14px;line-height: 26px;}.wp-block-uagb-container.uagb-block-f2a0f024 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-f2a0f024 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-f2a0f024 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-f2a0f024 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-f2a0f024 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f2a0f024{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f2a0f024 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 980px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 70px;}.wp-block-uagb-container.uagb-block-f2a0f024{box-shadow: 0px 0px   #00000070 ;padding-top: 85px;padding-bottom: 85px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: #fcfcfc;row-gap: 0px;column-gap: 70px;}.wp-block-uagb-advanced-heading.uagb-block-e65df95c.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-2);}.wp-block-uagb-advanced-heading.uagb-block-e65df95c.wp-block-uagb-advanced-heading {text-align: center;margin-top: 0px;margin-right: 0px;margin-bottom: 50px;margin-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-e65df95c.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-e65df95c.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-e65df95c.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-e65df95c.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-e65df95c .uagb-heading-text{font-family: \"Poppins\";font-weight: 500;font-size: 32px;line-height: 42px;}.wp-block-uagb-container.uagb-block-1fa6aee9 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-1fa6aee9 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-1fa6aee9 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-1fa6aee9 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-1fa6aee9 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1fa6aee9{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1fa6aee9 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1170px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-1fa6aee9{box-shadow: 0px 0px   #00000070 ;padding-top: 85px;padding-bottom: 65px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: #f2f2f2;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-advanced-heading.uagb-block-0cd02049.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-2);}.wp-block-uagb-advanced-heading.uagb-block-0cd02049.wp-block-uagb-advanced-heading {text-align: center;margin-top: 0px;margin-right: 0px;margin-bottom: 60px;margin-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-0cd02049.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-0cd02049.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-0cd02049.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-0cd02049.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-0cd02049 .uagb-heading-text{font-family: \"Poppins\";font-weight: 500;font-size: 32px;line-height: 42px;}.wp-block-uagb-advanced-heading.uagb-block-94f42e7f.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-1);}.wp-block-uagb-advanced-heading.uagb-block-94f42e7f.wp-block-uagb-advanced-heading {text-align: center;margin-top: 0em;margin-right: 0em;margin-bottom: 0.4em;margin-left: 0em;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-94f42e7f.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-94f42e7f.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-94f42e7f.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-94f42e7f.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-94f42e7f .uagb-heading-text{font-family: \"Poppins\";font-weight: 500;font-size: 32px;line-height: 42px;}.wp-block-uagb-advanced-heading.uagb-block-62798e90.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-1);}.wp-block-uagb-advanced-heading.uagb-block-62798e90.wp-block-uagb-advanced-heading {text-align: center;margin-top: 48px;margin-right: 0px;margin-bottom: 48px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-62798e90.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-62798e90.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-62798e90.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-62798e90.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-62798e90 .uagb-heading-text{font-family: \"Poppins\";font-weight: 500;font-size: 16px;line-height: 21px;}.uagb-block-b44e2020.wp-block-uagb-buttons.uagb-buttons__outer-wrap .uagb-buttons__wrap {gap: 10px;}.uagb-block-b44e2020.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-b44e2020 .uagb-buttons-repeater:not(.wp-block-button__link){font-family: \"Poppins\";font-weight: 500;font-size: 0.9em;line-height: 1.3em;letter-spacing: 0.1em;padding-top: 1.2em;padding-bottom: 1.2em;padding-left: 2.8em;padding-right: 2.8em;}.uagb-block-b44e2020 .uagb-button__wrapper .uagb-buttons-repeater.wp-block-button__link{font-family: \"Poppins\";font-weight: 500;font-size: 0.9em;line-height: 1.3em;letter-spacing: 0.1em;padding-top: 1.2em;padding-bottom: 1.2em;padding-left: 2.8em;padding-right: 2.8em;}.uagb-block-b44e2020 .uagb-button__wrapper .uagb-buttons-repeater.ast-outline-button{font-family: \"Poppins\";font-weight: 500;font-size: 0.9em;line-height: 1.3em;letter-spacing: 0.1em;padding-top: 1.2em;padding-bottom: 1.2em;padding-left: 2.8em;padding-right: 2.8em;}.wp-block-uagb-buttons .uagb-block-bdede035 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-bdede035 .uagb-buttons-repeater .uagb-button__icon > svg{width: 15px;height: 15px;}.wp-block-uagb-buttons .uagb-block-bdede035 .uagb-buttons-repeater .uagb-button__icon-position-after{margin-left: 8px;}.wp-block-uagb-buttons .uagb-block-bdede035 .uagb-buttons-repeater .uagb-button__icon-position-before{margin-right: 8px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-4511f953{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4511f953 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-4511f953{min-height: 350px;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-image: url(https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2024\/01\/commercial-representation-header.jpg);background-clip: padding-box;}.wp-block-uagb-advanced-heading.uagb-block-20071865 .uagb-heading-text{font-size: 25px;line-height: 35px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7857a908{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7857a908 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;column-gap: 30px;}.wp-block-uagb-container.uagb-block-7857a908{padding-top: 60px;padding-bottom: 60px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: #fafafa;column-gap: 30px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e6c4ffc9{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e6c4ffc9 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-e6c4ffc9{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-advanced-heading.uagb-block-9eff9916 .uagb-heading-text{font-size: 24px;line-height: 30px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9fc3be8e{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9fc3be8e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-9fc3be8e{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-52ad1add{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-52ad1add > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;column-gap: 30px;}.wp-block-uagb-container.uagb-block-52ad1add{padding-top: 60px;padding-bottom: 60px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: var(--ast-global-color-1);column-gap: 30px;}.wp-block-uagb-advanced-heading.uagb-block-36b4e363.wp-block-uagb-advanced-heading {margin-top: 0px;margin-right: 0px;margin-bottom: 50px;margin-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-36b4e363 .uagb-heading-text{font-size: 25px;line-height: 30px;}.wp-block-uagb-advanced-heading.uagb-block-f3e9723f .uagb-heading-text{font-size: 20px;line-height: 25px;}.wp-block-uagb-advanced-heading.uagb-block-be809159 .uagb-heading-text{font-size: 20px;line-height: 25px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f2a0f024{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f2a0f024 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;column-gap: 30px;}.wp-block-uagb-container.uagb-block-f2a0f024{padding-top: 60px;padding-bottom: 60px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: #fcfcfc;column-gap: 30px;}.wp-block-uagb-advanced-heading.uagb-block-e65df95c.wp-block-uagb-advanced-heading {margin-top: 0px;margin-right: 0px;margin-bottom: 50px;margin-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-e65df95c .uagb-heading-text{font-size: 24px;line-height: 30px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1fa6aee9{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1fa6aee9 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-1fa6aee9{padding-top: 60px;padding-bottom: 60px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: #f2f2f2;}.wp-block-uagb-advanced-heading.uagb-block-0cd02049.wp-block-uagb-advanced-heading {margin-top: 0px;margin-right: 0px;margin-bottom: 40px;margin-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-0cd02049 .uagb-heading-text{font-size: 24px;line-height: 30px;}.wp-block-uagb-advanced-heading.uagb-block-94f42e7f .uagb-heading-text{font-size: 24px;line-height: 30px;}.wp-block-uagb-advanced-heading.uagb-block-62798e90.wp-block-uagb-advanced-heading {margin-top: 30px;margin-right: 0px;margin-bottom: 35px;margin-left: 0px;}.uagb-block-b44e2020.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-b44e2020.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-4511f953{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-4511f953 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-4511f953{min-height: 320px;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-image: url(https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2024\/01\/commercial-representation-header.jpg);background-clip: padding-box;}.wp-block-uagb-advanced-heading.uagb-block-20071865 .uagb-heading-text{font-size: 20px;line-height: 25px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7857a908{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7857a908 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 30px;column-gap: 40px;}.wp-block-uagb-container.uagb-block-7857a908{padding-top: 40px;padding-bottom: 40px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 30px;column-gap: 40px;order: initial;background-color: #fafafa;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e6c4ffc9{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e6c4ffc9 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-e6c4ffc9{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;flex-wrap: wrap;}.wp-block-uagb-advanced-heading.uagb-block-9eff9916.wp-block-uagb-advanced-heading {padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 15px;margin-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-9eff9916 .uagb-heading-text{font-size: 22px;line-height: 30px;}.wp-block-uagb-advanced-heading.uagb-block-36ffe861.wp-block-uagb-advanced-heading {margin-top: 0px;margin-right: 0px;margin-bottom: 10px;margin-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-a3509b53.wp-block-uagb-advanced-heading {margin-top: 0px;margin-right: 0px;margin-bottom: 10px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9fc3be8e{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9fc3be8e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-9fc3be8e{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-52ad1add{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-52ad1add > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-52ad1add{padding-top: 40px;padding-bottom: 40px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 0px;column-gap: 0px;order: initial;background-color: var(--ast-global-color-1);}.wp-block-uagb-advanced-heading.uagb-block-36b4e363.wp-block-uagb-advanced-heading {margin-top: 0px;margin-right: 0px;margin-bottom: 40px;margin-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-36b4e363 .uagb-heading-text{font-size: 22px;line-height: 30px;}.wp-block-uagb-advanced-heading.uagb-block-f3e9723f .uagb-heading-text{font-size: 18px;line-height: 24px;}.wp-block-uagb-advanced-heading.uagb-block-be809159 .uagb-heading-text{font-size: 18px;line-height: 24px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-f2a0f024{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-f2a0f024 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-f2a0f024{padding-top: 40px;padding-bottom: 40px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 0px;column-gap: 0px;order: initial;background-color: #fcfcfc;}.wp-block-uagb-advanced-heading.uagb-block-e65df95c.wp-block-uagb-advanced-heading {margin-top: 0px;margin-right: 0px;margin-bottom: 40px;margin-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-e65df95c .uagb-heading-text{font-size: 22px;line-height: 30px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1fa6aee9{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1fa6aee9 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-1fa6aee9{padding-top: 40px;padding-bottom: 40px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: #f2f2f2;}.wp-block-uagb-advanced-heading.uagb-block-0cd02049.wp-block-uagb-advanced-heading {margin-top: 0px;margin-right: 0px;margin-bottom: 30px;margin-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-0cd02049 .uagb-heading-text{font-size: 22px;line-height: 30px;}.wp-block-uagb-advanced-heading.uagb-block-94f42e7f.wp-block-uagb-advanced-heading {padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-94f42e7f .uagb-heading-text{font-size: 22px;line-height: 31px;}.wp-block-uagb-advanced-heading.uagb-block-62798e90.wp-block-uagb-advanced-heading {margin-top: 30px;margin-right: 0px;margin-bottom: 30px;margin-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-62798e90 .uagb-heading-text{font-size: 16px;}.uagb-block-b44e2020.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-b44e2020.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.uagb-block-b44e2020 .uagb-buttons-repeater:not(.wp-block-button__link){font-size: 12px;}.uagb-block-b44e2020 .uagb-buttons-repeater.wp-block-button__link{font-size: 12px;}.uagb-block-b44e2020 .uagb-button__wrapper{margin-top: 0px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;}}.uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media(max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media(max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}.wp-block-uagb-image{display:flex}.wp-block-uagb-image__figure{position:relative;display:flex;flex-direction:column;max-width:100%;height:auto;margin:0}.wp-block-uagb-image__figure img{height:auto;display:flex;max-width:100%;transition:box-shadow .2s ease}.wp-block-uagb-image__figure>a{display:inline-block}.wp-block-uagb-image__figure figcaption{text-align:center;margin-top:.5em;margin-bottom:1em}.wp-block-uagb-image .components-placeholder.block-editor-media-placeholder .components-placeholder__instructions{align-self:center}.wp-block-uagb-image--align-left{text-align:left}.wp-block-uagb-image--align-right{text-align:right}.wp-block-uagb-image--align-center{text-align:center}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw);max-width:100vw;width:100vw;height:auto}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure img{height:auto;width:100% !important}.wp-block-uagb-image--align-wide .wp-block-uagb-image__figure img{height:auto;width:100%}.wp-block-uagb-image--layout-overlay__color-wrapper{position:absolute;left:0;top:0;right:0;bottom:0;opacity:.2;background:rgba(0,0,0,.5);transition:opacity .35s ease-in-out}.wp-block-uagb-image--layout-overlay-link{position:absolute;left:0;right:0;bottom:0;top:0}.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity:1}.wp-block-uagb-image--layout-overlay__inner{position:absolute;left:15px;right:15px;bottom:15px;top:15px;display:flex;align-items:center;justify-content:center;flex-direction:column;border-color:#fff;transition:.35s ease-in-out}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.top-center,.wp-block-uagb-image--layout-overlay__inner.top-right{justify-content:flex-start}.wp-block-uagb-image--layout-overlay__inner.bottom-left,.wp-block-uagb-image--layout-overlay__inner.bottom-center,.wp-block-uagb-image--layout-overlay__inner.bottom-right{justify-content:flex-end}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.center-left,.wp-block-uagb-image--layout-overlay__inner.bottom-left{align-items:flex-start}.wp-block-uagb-image--layout-overlay__inner.top-right,.wp-block-uagb-image--layout-overlay__inner.center-right,.wp-block-uagb-image--layout-overlay__inner.bottom-right{align-items:flex-end}.wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{color:#fff;transition:transform .35s,opacity .35s ease-in-out;transform:translate3d(0, 24px, 0);margin:0;line-height:1em}.wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width:30%;border-top-width:2px;border-top-color:#fff;border-top-style:solid;margin-bottom:10px;opacity:0;transition:transform .4s,opacity .4s ease-in-out;transform:translate3d(0, 30px, 0)}.wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity:0;overflow:visible;color:#fff;transition:transform .45s,opacity .45s ease-in-out;transform:translate3d(0, 35px, 0)}.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-heading,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-separator,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-caption{opacity:1;transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1.05)}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{width:calc(100% + 40px) !important;max-width:none !important;transform:translate3d(-40px, 0, 0);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-grayscale img{filter:grayscale(0%);transition:.35s ease-in-out}.wp-block-uagb-image--effect-grayscale:hover img{filter:grayscale(100%)}.wp-block-uagb-image--effect-blur img{filter:blur(0);transition:.35s ease-in-out}.wp-block-uagb-image--effect-blur:hover img{filter:blur(3px)}.uagb-block-8ddb406d.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-8ddb406d.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-8ddb406d.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-8ddb406d.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-8ddb406d.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-8ddb406d.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-8ddb406d.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-8ddb406d.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-8ddb406d.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-8ddb406d.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-8ddb406d.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-8ddb406d.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-8ddb406d.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-8ddb406d.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-8ddb406d.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}@media only screen and (max-width: 976px) {.uagb-block-8ddb406d.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}@media only screen and (max-width: 767px) {.uagb-block-8ddb406d.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}.wp-block-uagb-advanced-heading.uagb-block-35454055.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-35454055.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-35454055.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-35454055.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-1bc1662a.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-1bc1662a.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-1bc1662a.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-1bc1662a.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-86fe7c65.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-86fe7c65.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-86fe7c65.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-86fe7c65.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.uagb-block-5eb5d2b8.wp-block-uagb-image{text-align: center;justify-content: center;align-self: center;}.uagb-block-5eb5d2b8 .wp-block-uagb-image__figure{align-items: center;}.uagb-block-5eb5d2b8.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-5eb5d2b8.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-5eb5d2b8.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-5eb5d2b8.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-5eb5d2b8.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-5eb5d2b8.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-5eb5d2b8.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-5eb5d2b8.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-5eb5d2b8.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-5eb5d2b8.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-5eb5d2b8.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 150px;height: auto;}.uagb-block-5eb5d2b8.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-5eb5d2b8.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-5eb5d2b8.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-5eb5d2b8.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}@media only screen and (max-width: 976px) {.uagb-block-5eb5d2b8.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 150px;height: auto;}}@media only screen and (max-width: 767px) {.uagb-block-5eb5d2b8.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 150px;height: auto;}}.uagb-block-02bc7fcb.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-02bc7fcb.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-02bc7fcb.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-02bc7fcb.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-02bc7fcb.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-02bc7fcb.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-02bc7fcb.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-02bc7fcb.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-02bc7fcb.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-02bc7fcb.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-02bc7fcb.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-02bc7fcb.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-02bc7fcb.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-02bc7fcb.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-02bc7fcb.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}@media only screen and (max-width: 976px) {.uagb-block-02bc7fcb.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}@media only screen and (max-width: 767px) {.uagb-block-02bc7fcb.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}\";s:2:\"js\";s:161:\"document.addEventListener(\"DOMContentLoaded\", function(){ window.addEventListener( 'load', function() {\n\tUAGBButtonChild.init( '.uagb-block-bdede035' );\n});\n });\";s:18:\"current_block_list\";a:22:{i:0;s:14:\"uagb\/container\";i:1;s:21:\"uagb\/advanced-heading\";i:2;s:20:\"bcn\/breadcrumb-trail\";i:4;s:10:\"core\/image\";i:5;s:12:\"core\/columns\";i:6;s:11:\"core\/column\";i:7;s:9:\"core\/list\";i:8;s:14:\"core\/list-item\";i:11;s:10:\"core\/cover\";i:12;s:12:\"uagb\/buttons\";i:13;s:18:\"uagb\/buttons-child\";i:14;s:10:\"core\/group\";i:15;s:12:\"core\/heading\";i:16;s:15:\"core\/categories\";i:17;s:10:\"uagb\/image\";i:18;s:14:\"core\/paragraph\";i:19;s:17:\"core\/latest-posts\";i:20;s:17:\"core\/widget-group\";i:21;s:11:\"core\/search\";i:22;s:14:\"core\/tag-cloud\";i:23;s:17:\"core\/social-links\";i:24;s:16:\"core\/social-link\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";i:1788309950;s:6:\"gfonts\";a:1:{s:7:\"Poppins\";a:2:{s:10:\"fontfamily\";s:7:\"Poppins\";s:12:\"fontvariants\";a:2:{i:0;s:3:\"500\";i:1;s:3:\"400\";}}}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false,"ultp_layout_landscape_large":false,"ultp_layout_landscape":false,"ultp_layout_portrait":false,"ultp_layout_square":false},"uagb_author_info":{"display_name":"trades_admin","author_link":"https:\/\/staging.accordglobaltrade.com\/tr\/author\/trades_admin\/"},"uagb_comment_info":0,"uagb_excerpt":"Trade Agency Representation Agency &amp; Commercial Representation We specialize in providing Agency &amp; Commercial Representation services to Producers, Suppliers, Manufacturers and End Buyers in the international import\/export marketplace. Our services have been designed to allow expansions to new foreign markets by providing customized services that fit unique business requirements in order to succeed in international&hellip;","_links":{"self":[{"href":"https:\/\/staging.accordglobaltrade.com\/tr\/wp-json\/wp\/v2\/pages\/39","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.accordglobaltrade.com\/tr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/staging.accordglobaltrade.com\/tr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/staging.accordglobaltrade.com\/tr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.accordglobaltrade.com\/tr\/wp-json\/wp\/v2\/comments?post=39"}],"version-history":[{"count":29,"href":"https:\/\/staging.accordglobaltrade.com\/tr\/wp-json\/wp\/v2\/pages\/39\/revisions"}],"predecessor-version":[{"id":2157,"href":"https:\/\/staging.accordglobaltrade.com\/tr\/wp-json\/wp\/v2\/pages\/39\/revisions\/2157"}],"wp:attachment":[{"href":"https:\/\/staging.accordglobaltrade.com\/tr\/wp-json\/wp\/v2\/media?parent=39"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}