{"id":31,"date":"2023-12-28T04:50:36","date_gmt":"2023-12-28T04:50:36","guid":{"rendered":"https:\/\/staging.accordglobaltrade.com\/?page_id=31"},"modified":"2024-03-17T04:19:44","modified_gmt":"2024-03-17T04:19:44","slug":"competitive-advantages","status":"publish","type":"page","link":"https:\/\/staging.accordglobaltrade.com\/zh\/competitive-advantages\/","title":{"rendered":"\u7ade\u4e89\u4f18\u52bf"},"content":{"rendered":"<div class=\"wp-block-uagb-container ic-arrow uagb-block-a015d3fa alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-ee0f8e68\"><h2 class=\"uagb-heading-text\">\u7ade\u4e89\u4f18\u52bf<\/h2><\/div>\n\n\n<div class=\"breadcrumbs align ic-breadcrumb-wrapper wp-block-bcn-breadcrumb-trail has-text-color has-background\" vocab=\"https:\/\/schema.org\/\" typeof=\"BreadcrumbList\">\n\t<span><\/span>\n\t<span property=\"itemListElement\" typeof=\"ListItem\"><a property=\"item\" typeof=\"WebPage\" title=\"\u524d\u5f80\u96c5\u9601\u5168\u7403\u8d38\u6613\u516c\u53f8\u3002\" href=\"https:\/\/staging.accordglobaltrade.com\/zh\" class=\"home\" aria-current=\"page\"><span property=\"name\">\u9996\u9875<\/span><\/a><meta property=\"position\" content=\"1\"><\/span><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-7857a908 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-e6c4ffc9\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-9eff9916\"><h2 class=\"uagb-heading-text\">\u8fdb\u5165\u56fd\u9645\u5e02\u573a<\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-36ffe861\"><p class=\"uagb-heading-text\">Accord Global Trade \u662f\u4e3a\u6570\u4e0d\u591a\u7684\u4e3a\u51fa\u53e3\u5546\u548c\u8fdb\u53e3\u5546\u63d0\u4f9b\u7279\u6b8a\u5b9a\u5236\u89e3\u51b3\u65b9\u6848\u7684\u516c\u53f8\u4e4b\u4e00\uff0c\u4e0e\u5176\u4ed6\u516c\u53f8\u76f8\u6bd4\u5177\u6709\u7ade\u4e89\u4f18\u52bf\u3002\u6211\u4eec\u7684\u9ad8\u7d20\u8d28\u8d38\u6613\u548c\u6295\u8d44\u4e13\u5bb6\u53ef\u5728\u76d1\u7ba1\u3001\u81ea\u7136\u548c\u5730\u7f18\u653f\u6cbb\u53d8\u5316\u4ea7\u751f\u5373\u65f6\u5f71\u54cd\u7684\u4e16\u754c\u4e2d\u63d0\u4f9b\u5e02\u573a\u80fd\u89c1\u5ea6\u548c\u5546\u4e1a\u60c5\u62a5\u3002<\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-a3509b53\"><p class=\"uagb-heading-text\">\u6211\u4eec\u5728\u5317\u7f8e\u3001\u4e2d\u4e1c\u548c\u975e\u6d32 (MEA) \u8bbe\u6709\u529e\u4e8b\u5904\uff0c\u5728\u4e9a\u592a\u5730\u533a\u3001\u6b27\u6d32\u548c\u62c9\u4e01\u7f8e\u6d32\u4e5f\u6709\u5408\u4f5c\u4f19\u4f34\uff0c\u56e0\u6b64\u53ef\u4ee5\u63a5\u89e6\u5230\u4e16\u754c\u5404\u5730\u7684\u751f\u4ea7\u5546\u3001\u4f9b\u5e94\u5546\u3001\u5236\u9020\u5546\u3001\u8fdb\u53e3\u5546\u548c\u6295\u8d44\u8005\u3002<\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-6cfbd83f\"><p class=\"uagb-heading-text\">\u6211\u4eec\u7531\u9ad8\u7d20\u8d28\u7684\u4ea4\u6613\u5458\u63d0\u4f9b\u5353\u8d8a\u7684\u4ea4\u6613\u670d\u52a1\uff0c\u5728\u76d1\u7ba1\u3001\u81ea\u7136\u548c\u5730\u7f18\u653f\u6cbb\u53d8\u5316\u4ea7\u751f\u5373\u65f6\u5f71\u54cd\u7684\u4e16\u754c\u4e2d\uff0c\u4ed6\u4eec\u63d0\u4f9b\u5e02\u573a\u80fd\u89c1\u5ea6\u548c\u5546\u4e1a\u60c5\u62a5\u3002<\/p><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-9fc3be8e\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"638\" src=\"https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2024\/01\/competitive-advantages-AGT-1024x638-1.jpg\" alt=\"\" class=\"wp-image-436\" style=\"object-fit:cover\" srcset=\"https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2024\/01\/competitive-advantages-AGT-1024x638-1.jpg 1024w, https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2024\/01\/competitive-advantages-AGT-1024x638-1-300x187.jpg 300w, https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2024\/01\/competitive-advantages-AGT-1024x638-1-768x479.jpg 768w, https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2024\/01\/competitive-advantages-AGT-1024x638-1-18x12.jpg 18w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container ic-services-wrapper uagb-block-59342b4b alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-24abe809\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-0aa75fdc\"><h2 class=\"uagb-heading-text\">\u6211\u4eec\u7684\u670d\u52a1\u4f18\u52bf<\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-icon-list uagb-block-49bb9b74\"><div class=\"uagb-icon-list__wrap\">\n<div class=\"wp-block-uagb-icon-list-child uagb-block-c00bbf14\"><span class=\"uagb-icon-list__source-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M438.6 105.4C451.1 117.9 451.1 138.1 438.6 150.6L182.6 406.6C170.1 419.1 149.9 419.1 137.4 406.6L9.372 278.6C-3.124 266.1-3.124 245.9 9.372 233.4C21.87 220.9 42.13 220.9 54.63 233.4L159.1 338.7L393.4 105.4C405.9 92.88 426.1 92.88 438.6 105.4H438.6z\"><\/path><\/svg><\/span><span class=\"uagb-icon-list__label\">\u51ed\u501f\u6211\u4eec\u5728\u591a\u4e2a\u884c\u4e1a\u7684\u7ecf\u9a8c\uff0c\u6211\u4eec\u5df2\u5728\u8bb8\u591a\u884c\u4e1a\u5236\u5b9a\u5e76\u5b9e\u65bd\u4e86\u8d38\u6613\u4fc3\u8fdb\u6218\u7565\u3001\u4ef7\u503c\u4e3b\u5f20\u548c\u6f5c\u5728\u5ba2\u6237\u5f00\u53d1\u6d3b\u52a8\uff0c\u4ee5\u589e\u52a0\u51fa\u53e3\u548c\u8fdb\u53e3\uff0c\u5e76\u4f7f\u6f5c\u5728\u6295\u8d44\u8005\u5173\u6ce8\u6211\u4eec\u7684\u72ec\u5bb6\u8d38\u6613\u673a\u4f1a<\/span><\/div>\n\n\n\n<div class=\"wp-block-uagb-icon-list-child uagb-block-43b973c0\"><span class=\"uagb-icon-list__source-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M438.6 105.4C451.1 117.9 451.1 138.1 438.6 150.6L182.6 406.6C170.1 419.1 149.9 419.1 137.4 406.6L9.372 278.6C-3.124 266.1-3.124 245.9 9.372 233.4C21.87 220.9 42.13 220.9 54.63 233.4L159.1 338.7L393.4 105.4C405.9 92.88 426.1 92.88 438.6 105.4H438.6z\"><\/path><\/svg><\/span><span class=\"uagb-icon-list__label\">\u5b9a\u5236\u54a8\u8be2\u670d\u52a1\u3001\u6210\u719f\u7684\u65b0\u5174\u5e02\u573a\u8fdb\u5165\u6218\u7565\u3001\u8d38\u6613\u4fc3\u8fdb\u548c\u8425\u9500\u89e3\u51b3\u65b9\u6848\uff0c\u4ee5\u627e\u5230\u63a8\u5e7f\u5ba2\u6237\u5546\u54c1\u3001\u4ea7\u54c1\u6216\u670d\u52a1\u7684\u6700\u4f73\u65b9\u6cd5\uff0c\u5e76\u7b80\u5316\u5176\u4e1a\u52a1\u6e20\u9053<\/span><\/div>\n\n\n\n<div class=\"wp-block-uagb-icon-list-child uagb-block-718d1bc4\"><span class=\"uagb-icon-list__source-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M438.6 105.4C451.1 117.9 451.1 138.1 438.6 150.6L182.6 406.6C170.1 419.1 149.9 419.1 137.4 406.6L9.372 278.6C-3.124 266.1-3.124 245.9 9.372 233.4C21.87 220.9 42.13 220.9 54.63 233.4L159.1 338.7L393.4 105.4C405.9 92.88 426.1 92.88 438.6 105.4H438.6z\"><\/path><\/svg><\/span><span class=\"uagb-icon-list__label\">\u5229\u7528\u6211\u4eec\u7684\u5168\u7403\u5ba2\u6237\u7fa4\u548c\u5728\u91c7\u8d2d\u5546\u54c1\/\u4ea7\u54c1\u65b9\u9762\u7684\u4e30\u5bcc\u4e13\u4e1a\u77e5\u8bc6\uff0c\u63a5\u89e6\u7ecf\u8fc7\u9a8c\u8bc1\u7684\u771f\u6b63\u4f9b\u5e94\u5546\u548c\u6295\u8d44\u8005<\/span><\/div>\n\n\n\n<div class=\"wp-block-uagb-icon-list-child uagb-block-de00e7f3\"><span class=\"uagb-icon-list__source-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M438.6 105.4C451.1 117.9 451.1 138.1 438.6 150.6L182.6 406.6C170.1 419.1 149.9 419.1 137.4 406.6L9.372 278.6C-3.124 266.1-3.124 245.9 9.372 233.4C21.87 220.9 42.13 220.9 54.63 233.4L159.1 338.7L393.4 105.4C405.9 92.88 426.1 92.88 438.6 105.4H438.6z\"><\/path><\/svg><\/span><span class=\"uagb-icon-list__label\">\u6211\u4eec\u591a\u5143\u5316\u7684\u4e13\u4e1a\u77e5\u8bc6\u548c\u5168\u7403\u7f51\u7edc\u4f7f\u6211\u4eec\u80fd\u591f\u5728\u56fd\u9645\u8d38\u6613\u4e2d\u5feb\u901f\u627e\u5230\u7ecf\u8fc7\u9a8c\u8bc1\u7684\u771f\u6b63\u4f9b\u5e94\u5546\u548c\u6295\u8d44\u8005<\/span><\/div>\n\n\n\n<div class=\"wp-block-uagb-icon-list-child uagb-block-7927f8a6\"><span class=\"uagb-icon-list__source-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M438.6 105.4C451.1 117.9 451.1 138.1 438.6 150.6L182.6 406.6C170.1 419.1 149.9 419.1 137.4 406.6L9.372 278.6C-3.124 266.1-3.124 245.9 9.372 233.4C21.87 220.9 42.13 220.9 54.63 233.4L159.1 338.7L393.4 105.4C405.9 92.88 426.1 92.88 438.6 105.4H438.6z\"><\/path><\/svg><\/span><span class=\"uagb-icon-list__label\">\u786e\u5b9a\u65b0\u5174\u5e02\u573a\u548c\u6210\u719f\u5e02\u573a\u4e4b\u95f4\u7684\u8d38\u6613\u548c\u6295\u8d44\u673a\u4f1a\uff0c\u901a\u8fc7\u7ed3\u6784\u5316\u7684\u8d38\u6613\u548c\u7269\u6d41\u8fd0\u4f5c\uff0c\u8d2d\u4e70\u3001\u9500\u552e\u3001\u6295\u8d44\u548c\u5206\u9500\u5546\u54c1\u548c\u4ea7\u54c1\uff0c\u786e\u4fdd\u4ea4\u6613\u5177\u6709\u7ade\u4e89\u529b\u5e76\u6709\u5229\u53ef\u56fe<\/span><\/div>\n\n\n\n<div class=\"wp-block-uagb-icon-list-child uagb-block-2145a42c\"><span class=\"uagb-icon-list__source-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M438.6 105.4C451.1 117.9 451.1 138.1 438.6 150.6L182.6 406.6C170.1 419.1 149.9 419.1 137.4 406.6L9.372 278.6C-3.124 266.1-3.124 245.9 9.372 233.4C21.87 220.9 42.13 220.9 54.63 233.4L159.1 338.7L393.4 105.4C405.9 92.88 426.1 92.88 438.6 105.4H438.6z\"><\/path><\/svg><\/span><span class=\"uagb-icon-list__label\">\u901a\u8fc7\u786e\u4fdd\u5ba2\u6237\u7684\u5546\u54c1\u3001\u4ea7\u54c1\u6216\u670d\u52a1\u62e5\u6709\u5168\u7403\u4f9b\u5e94\u5e02\u573a\uff0c\u5ba2\u6237\u80fd\u591f\u63a5\u89e6\u5230\u56fd\u5916\u8fdb\u53e3\u5546\uff0c\u540c\u65f6\u63d0\u4f9b\u56fd\u9645\u4f9b\u5e94\u94fe\u7cfb\u7edf\uff0c\u4ece\u800c\u63a5\u89e6\u5e76\u66f4\u5feb\u5730\u8fdb\u5165\u56fd\u5916\u5e02\u573a<\/span><\/div>\n\n\n\n<div class=\"wp-block-uagb-icon-list-child uagb-block-1f396213\"><span class=\"uagb-icon-list__source-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M438.6 105.4C451.1 117.9 451.1 138.1 438.6 150.6L182.6 406.6C170.1 419.1 149.9 419.1 137.4 406.6L9.372 278.6C-3.124 266.1-3.124 245.9 9.372 233.4C21.87 220.9 42.13 220.9 54.63 233.4L159.1 338.7L393.4 105.4C405.9 92.88 426.1 92.88 438.6 105.4H438.6z\"><\/path><\/svg><\/span><span class=\"uagb-icon-list__label\">\u5229\u7528\u6211\u4eec\u7684\u5168\u7403\u5408\u4f5c\u4f19\u4f34\u5173\u7cfb\uff0c\u4fc3\u8fdb\u8fdb\u51fa\u53e3\u548c\u5168\u7403\u8d38\u6613\u3002\u6211\u4eec\u5c06\u7814\u7a76\u4e0e\u54a8\u8be2\u670d\u52a1\u76f8\u7ed3\u5408\uff0c\u4e3a\u5ba2\u6237\u5728\u73b0\u6709\u5e02\u573a\u548c\u65b0\u5e02\u573a\u7684\u6218\u7565\u548c\u4e1a\u52a1\u51b3\u7b56\u63d0\u4f9b\u72ec\u7279\u652f\u6301<\/span><\/div>\n\n\n\n<div class=\"wp-block-uagb-icon-list-child uagb-block-b5a69f0e\"><span class=\"uagb-icon-list__source-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M438.6 105.4C451.1 117.9 451.1 138.1 438.6 150.6L182.6 406.6C170.1 419.1 149.9 419.1 137.4 406.6L9.372 278.6C-3.124 266.1-3.124 245.9 9.372 233.4C21.87 220.9 42.13 220.9 54.63 233.4L159.1 338.7L393.4 105.4C405.9 92.88 426.1 92.88 438.6 105.4H438.6z\"><\/path><\/svg><\/span><span class=\"uagb-icon-list__label\">\u5927\u5e45\u964d\u4f4e\u51fa\u53e3\u542f\u52a8\u6210\u672c\u4ee5\u53ca\u5411\u672a\u77e5\u56fd\u9645\u5e02\u573a\u51fa\u53e3\u7684\u76f8\u5173\u98ce\u9669<\/span><\/div>\n\n\n\n<div class=\"wp-block-uagb-icon-list-child uagb-block-7f0ab4c8\"><span class=\"uagb-icon-list__source-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M438.6 105.4C451.1 117.9 451.1 138.1 438.6 150.6L182.6 406.6C170.1 419.1 149.9 419.1 137.4 406.6L9.372 278.6C-3.124 266.1-3.124 245.9 9.372 233.4C21.87 220.9 42.13 220.9 54.63 233.4L159.1 338.7L393.4 105.4C405.9 92.88 426.1 92.88 438.6 105.4H438.6z\"><\/path><\/svg><\/span><span class=\"uagb-icon-list__label\">\u5728\u8fdb\u51fa\u53e3\u8fc7\u7a0b\u4e2d\u63d0\u4f9b\u6307\u5bfc\uff0c\u8fd9\u5c06\u4e3a\u9a7e\u9a6d\u590d\u6742\u7684\u56fd\u9645\u8d38\u6613\u63d0\u4f9b\u6240\u9700\u7684\u6280\u80fd<\/span><\/div>\n\n\n\n<div class=\"wp-block-uagb-icon-list-child uagb-block-c0c764ee\"><span class=\"uagb-icon-list__source-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M438.6 105.4C451.1 117.9 451.1 138.1 438.6 150.6L182.6 406.6C170.1 419.1 149.9 419.1 137.4 406.6L9.372 278.6C-3.124 266.1-3.124 245.9 9.372 233.4C21.87 220.9 42.13 220.9 54.63 233.4L159.1 338.7L393.4 105.4C405.9 92.88 426.1 92.88 438.6 105.4H438.6z\"><\/path><\/svg><\/span><span class=\"uagb-icon-list__label\">\u8ba9\u5ba2\u6237\u4e13\u6ce8\u4e8e\u56fd\u5185\u8425\u9500\u548c\u9500\u552e\uff0c\u540c\u65f6\u5c06\u51fa\u53e3\u6216\u8fdb\u53e3\u4e1a\u52a1\u5916\u5305\u7ed9\u56fd\u9645\u8d38\u6613\u4e13\u5bb6<\/span><\/div>\n\n\n\n<div class=\"wp-block-uagb-icon-list-child uagb-block-afa76cb7\"><span class=\"uagb-icon-list__source-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M438.6 105.4C451.1 117.9 451.1 138.1 438.6 150.6L182.6 406.6C170.1 419.1 149.9 419.1 137.4 406.6L9.372 278.6C-3.124 266.1-3.124 245.9 9.372 233.4C21.87 220.9 42.13 220.9 54.63 233.4L159.1 338.7L393.4 105.4C405.9 92.88 426.1 92.88 438.6 105.4H438.6z\"><\/path><\/svg><\/span><span class=\"uagb-icon-list__label\">\u4e3a\u5ba2\u6237\u63d0\u4f9b\u76f4\u63a5\u548c\u95f4\u63a5\u8fd0\u8f93\u9009\u62e9\u4ee5\u53ca\u4f17\u591a\u56fd\u5185\u5916\u5206\u9500\u6e20\u9053<\/span><\/div>\n\n\n\n<div class=\"wp-block-uagb-icon-list-child uagb-block-553988af\"><span class=\"uagb-icon-list__source-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M438.6 105.4C451.1 117.9 451.1 138.1 438.6 150.6L182.6 406.6C170.1 419.1 149.9 419.1 137.4 406.6L9.372 278.6C-3.124 266.1-3.124 245.9 9.372 233.4C21.87 220.9 42.13 220.9 54.63 233.4L159.1 338.7L393.4 105.4C405.9 92.88 426.1 92.88 438.6 105.4H438.6z\"><\/path><\/svg><\/span><span class=\"uagb-icon-list__label\">\u901a\u8fc7\u7b80\u5316\u672c\u5730\u548c\u5168\u7403\u4f9b\u5e94\u94fe\u7ba1\u7406\uff0c\u589e\u52a0\u9500\u552e\u989d\u548c\u5229\u6da6<\/span><\/div>\n\n\n\n<div class=\"wp-block-uagb-icon-list-child uagb-block-32b44efe\"><span class=\"uagb-icon-list__source-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M438.6 105.4C451.1 117.9 451.1 138.1 438.6 150.6L182.6 406.6C170.1 419.1 149.9 419.1 137.4 406.6L9.372 278.6C-3.124 266.1-3.124 245.9 9.372 233.4C21.87 220.9 42.13 220.9 54.63 233.4L159.1 338.7L393.4 105.4C405.9 92.88 426.1 92.88 438.6 105.4H438.6z\"><\/path><\/svg><\/span><span class=\"uagb-icon-list__label\">\u5e2e\u52a9\u5728\u56fd\u9645\u5e02\u573a\u5efa\u7acb\u6218\u7565\u4e1a\u52a1\u5173\u7cfb<\/span><\/div>\n\n\n\n<div class=\"wp-block-uagb-icon-list-child uagb-block-c4d5189a\"><span class=\"uagb-icon-list__source-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M438.6 105.4C451.1 117.9 451.1 138.1 438.6 150.6L182.6 406.6C170.1 419.1 149.9 419.1 137.4 406.6L9.372 278.6C-3.124 266.1-3.124 245.9 9.372 233.4C21.87 220.9 42.13 220.9 54.63 233.4L159.1 338.7L393.4 105.4C405.9 92.88 426.1 92.88 438.6 105.4H438.6z\"><\/path><\/svg><\/span><span class=\"uagb-icon-list__label\">\u5229\u7528\u6b63\u786e\u7684\u8d38\u6613\u548c\u6295\u8d44\u65b9\u5f0f\uff0c\u5e2e\u52a9\u60a8\u6240\u5728\u5730\u533a\/\u9886\u5730\u7684\u4f01\u4e1a\u501f\u52a9\u5916\u8d38\u548c\u8de8\u5883\u6295\u8d44\u9879\u76ee\u52a0\u901f\u53d1\u5c55<\/span><\/div>\n\n\n\n<div class=\"wp-block-uagb-icon-list-child uagb-block-b1bfb453\"><span class=\"uagb-icon-list__source-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M438.6 105.4C451.1 117.9 451.1 138.1 438.6 150.6L182.6 406.6C170.1 419.1 149.9 419.1 137.4 406.6L9.372 278.6C-3.124 266.1-3.124 245.9 9.372 233.4C21.87 220.9 42.13 220.9 54.63 233.4L159.1 338.7L393.4 105.4C405.9 92.88 426.1 92.88 438.6 105.4H438.6z\"><\/path><\/svg><\/span><span class=\"uagb-icon-list__label\">\u63d0\u4f9b\u4ee5\u7ed3\u679c\u4e3a\u5bfc\u5411\u7684\u8d38\u6613\u4fc3\u8fdb\u89e3\u51b3\u65b9\u6848\uff0c\u5e2e\u52a9\u6211\u4eec\u7684\u5ba2\u6237\u53d1\u73b0\u6709\u5229\u53ef\u56fe\u7684\u673a\u4f1a\uff0c\u5e76\u901a\u8fc7\u6295\u8d44\u4e8e\u6211\u4eec\u72ec\u6709\u7684\u8d38\u6613\u548c\u6295\u8d44\u9879\u76ee\u52a0\u901f\u4e1a\u52a1\u589e\u957f\u3002<\/span><\/div>\n\n\n\n<div class=\"wp-block-uagb-icon-list-child uagb-block-53f5fb63\"><span class=\"uagb-icon-list__source-wrap\"><svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 448 512\"><path d=\"M438.6 105.4C451.1 117.9 451.1 138.1 438.6 150.6L182.6 406.6C170.1 419.1 149.9 419.1 137.4 406.6L9.372 278.6C-3.124 266.1-3.124 245.9 9.372 233.4C21.87 220.9 42.13 220.9 54.63 233.4L159.1 338.7L393.4 105.4C405.9 92.88 426.1 92.88 438.6 105.4H438.6z\"><\/path><\/svg><\/span><span class=\"uagb-icon-list__label\">\u5141\u8bb8\u4f9b\u5e94\u5546\u548c\u6295\u8d44\u8005\u5229\u7528\u6211\u4eec\u7684\u7efc\u5408\u8d44\u6e90\uff0c\u4ed6\u4eec\u53ef\u4ee5\u6839\u636e\u81ea\u5df1\u7684\u5177\u4f53\u9700\u6c42\u548c\u4e1a\u52a1\u76ee\u6807\u6709\u9009\u62e9\u5730\u5229\u7528\u8fd9\u4e9b\u8d44\u6e90<\/span><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-7d6271a6\"><p class=\"uagb-heading-text\">Accord Global Trade \u81f4\u529b\u4e8e\u4e3a\u51fa\u53e3\u5546\u3001\u8fdb\u53e3\u5546\u548c\u6295\u8d44\u8005\u63d0\u4f9b\u8d38\u6613\u548c\u6295\u8d44\u4ea4\u6613\u5404\u65b9\u9762\u7684\u8054\u7cfb\u3002\u8fd9\u4f7f\u6211\u4eec\u516c\u53f8\u6210\u4e3a\u7f3a\u4e4f\u6280\u80fd\u7684\u516c\u53f8\u548c\u5e0c\u671b\u62d3\u5c55\u56fd\u5916\u5e02\u573a\u7684\u516c\u53f8\u7684\u53ef\u884c\u9009\u62e9\u3002<\/p><\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-container ic-product-services-wrapper uagb-block-1fa6aee9 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-0cd02049\"><h2 class=\"uagb-heading-text\">\u6211\u4eec\u5982\u4f55\u4e3a\u60a8\u63d0\u4f9b\u5e2e\u52a9<\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-15f800a4\"><p class=\"uagb-heading-text\">\u6211\u4eec\u4e3a\u56fd\u9645\u5e02\u573a\u4e0a\u7684\u8fdb\u53e3\u5546\u548c\u51fa\u53e3\u5546\u63d0\u4f9b\u4ea7\u54c1\u548c\u670d\u52a1\uff0c\u5c06\u5ba2\u6237\u4e0e\u4e16\u754c\u5404\u5730\u7684\u5e02\u573a\u8054\u7cfb\u8d77\u6765\u3002<\/p><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-92515837 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-content-justification-left is-layout-constrained wp-container-core-column-is-layout-0246d3f3 wp-block-column-is-layout-constrained\" style=\"padding-top:0;padding-bottom:0\">\n<div class=\"wp-block-cover alignfull ic-help-wrapper\" style=\"margin-top:0;padding-top:0vw;padding-right:0vw;padding-bottom:0vw;padding-left:0vw;min-height:365px;aspect-ratio:unset;\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-0 has-background-dim\" style=\"background-color:#2c3066\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"2160\" height=\"1064\" class=\"wp-block-cover__image-background wp-image-463\" alt=\"\" src=\"https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2024\/01\/competitive-advantages-banner-1.jpg\" style=\"object-position:50% 50%\" data-object-fit=\"cover\" data-object-position=\"50% 50%\" srcset=\"https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2024\/01\/competitive-advantages-banner-1.jpg 2160w, https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2024\/01\/competitive-advantages-banner-1-300x148.jpg 300w, https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2024\/01\/competitive-advantages-banner-1-1024x504.jpg 1024w, https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2024\/01\/competitive-advantages-banner-1-768x378.jpg 768w, https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2024\/01\/competitive-advantages-banner-1-1536x757.jpg 1536w, https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2024\/01\/competitive-advantages-banner-1-2048x1009.jpg 2048w, https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2024\/01\/competitive-advantages-banner-1-18x9.jpg 18w\" sizes=\"auto, (max-width: 2160px) 100vw, 2160px\" \/><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-94f42e7f\"><h2 class=\"uagb-heading-text\">\u63d0\u51fa\u9500\u552e\u8981\u7ea6<\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-62798e90 ic-shape\"><p class=\"uagb-heading-text\">\u6210\u4e3a\u51fa\u53e3\u5546<\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-b44e2020\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap\">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-bdede035 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"https:\/\/staging.accordglobaltrade.com\/zh\/offer-to-sell\/\" rel=\"follow noopener\" target=\"_self\"><div class=\"uagb-button__link\">\u7acb\u5373\u62a5\u4ef7<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"padding-top:0;padding-right:0;padding-bottom:0;padding-left:0\">\n<div class=\"wp-block-cover alignfull ic-help-wrapper\" style=\"margin-top:0;padding-top:0vw;padding-right:0vw;padding-bottom:0vw;padding-left:0vw;min-height:365px;aspect-ratio:unset;\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-0 has-background-dim\" style=\"background-color:#2c3066\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"2160\" height=\"1117\" class=\"wp-block-cover__image-background wp-image-466\" alt=\"\" src=\"https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2024\/01\/partnership-banner-1.jpg\" style=\"object-position:50% 50%\" data-object-fit=\"cover\" data-object-position=\"50% 50%\" srcset=\"https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2024\/01\/partnership-banner-1.jpg 2160w, https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2024\/01\/partnership-banner-1-300x155.jpg 300w, https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2024\/01\/partnership-banner-1-1024x530.jpg 1024w, https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2024\/01\/partnership-banner-1-768x397.jpg 768w, https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2024\/01\/partnership-banner-1-1536x794.jpg 1536w, https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2024\/01\/partnership-banner-1-2048x1059.jpg 2048w, https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2024\/01\/partnership-banner-1-18x9.jpg 18w\" sizes=\"auto, (max-width: 2160px) 100vw, 2160px\" \/><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-694562ab\"><h2 class=\"uagb-heading-text\">\u7533\u8bf7\u62a5\u4ef7<\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-be16258a ic-shape\"><p class=\"uagb-heading-text\">\u6210\u4e3a\u8fdb\u53e3\u5546<\/p><\/div>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-btn__default-btn uagb-btn-tablet__default-btn uagb-btn-mobile__default-btn uagb-block-abdda5ee\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap\">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-f26a3928 wp-block-button\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater wp-block-button__link\" aria-label=\"\" href=\"https:\/\/staging.accordglobaltrade.com\/request-for-quote\/\" rel=\"follow noopener\" target=\"_self\"><div class=\"uagb-button__link\">\u7acb\u5373\u7533\u8bf7<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Competitive Advantages Access to International Markets Accord Global Trade has competitive advantages over other companies by being one of the few companies that provide exceptional and customized solutions to both exporters and importers. Our highly qualified trade and investment experts provide market visibility and business intelligence in a world where regulatory, natural, and geopolitical shifts [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-31","page","type-page","status-publish","hentry"],"spectra_custom_meta":{"_edit_lock":["1711526247:1"],"_edit_last":["1"],"_uagb_previous_block_counts":["a:90:{s:21:\"uagb\/advanced-heading\";i:13;s:15:\"uagb\/blockquote\";i:0;s:12:\"uagb\/buttons\";i:2;s:18:\"uagb\/buttons-child\";i:2;s:19:\"uagb\/call-to-action\";i:0;s:15:\"uagb\/cf7-styler\";i:0;s:11:\"uagb\/column\";i:0;s:12:\"uagb\/columns\";i:0;s:14:\"uagb\/container\";i:7;s:21:\"uagb\/content-timeline\";i:0;s:27:\"uagb\/content-timeline-child\";i:0;s:14:\"uagb\/countdown\";i:0;s:12:\"uagb\/counter\";i:0;s:8:\"uagb\/faq\";i:0;s:14:\"uagb\/faq-child\";i:0;s:10:\"uagb\/forms\";i:0;s:17:\"uagb\/forms-accept\";i:0;s:19:\"uagb\/forms-checkbox\";i:0;s:15:\"uagb\/forms-date\";i:0;s:16:\"uagb\/forms-email\";i:0;s:17:\"uagb\/forms-hidden\";i:0;s:15:\"uagb\/forms-name\";i:0;s:16:\"uagb\/forms-phone\";i:0;s:16:\"uagb\/forms-radio\";i:0;s:17:\"uagb\/forms-select\";i:0;s:19:\"uagb\/forms-textarea\";i:0;s:17:\"uagb\/forms-toggle\";i:0;s:14:\"uagb\/forms-url\";i:0;s:14:\"uagb\/gf-styler\";i:0;s:15:\"uagb\/google-map\";i:0;s:11:\"uagb\/how-to\";i:0;s:16:\"uagb\/how-to-step\";i:0;s:9:\"uagb\/icon\";i:0;s:14:\"uagb\/icon-list\";i:1;s:20:\"uagb\/icon-list-child\";i:16;s:10:\"uagb\/image\";i:0;s:18:\"uagb\/image-gallery\";i:0;s:13:\"uagb\/info-box\";i:0;s:18:\"uagb\/inline-notice\";i:0;s:11:\"uagb\/lottie\";i:0;s:21:\"uagb\/marketing-button\";i:0;s:10:\"uagb\/modal\";i:0;s:18:\"uagb\/popup-builder\";i:0;s:16:\"uagb\/post-button\";i:0;s:18:\"uagb\/post-carousel\";i:0;s:17:\"uagb\/post-excerpt\";i:0;s:14:\"uagb\/post-grid\";i:0;s:15:\"uagb\/post-image\";i:0;s:17:\"uagb\/post-masonry\";i:0;s:14:\"uagb\/post-meta\";i:0;s:18:\"uagb\/post-taxonomy\";i:0;s:18:\"uagb\/post-timeline\";i:0;s:15:\"uagb\/post-title\";i:0;s:20:\"uagb\/restaurant-menu\";i:0;s:26:\"uagb\/restaurant-menu-child\";i:0;s:11:\"uagb\/review\";i:0;s:12:\"uagb\/section\";i:0;s:14:\"uagb\/separator\";i:0;s:11:\"uagb\/slider\";i:0;s:17:\"uagb\/slider-child\";i:0;s:17:\"uagb\/social-share\";i:0;s:23:\"uagb\/social-share-child\";i:0;s:16:\"uagb\/star-rating\";i:0;s:23:\"uagb\/sure-cart-checkout\";i:0;s:22:\"uagb\/sure-cart-product\";i:0;s:15:\"uagb\/sure-forms\";i:0;s:22:\"uagb\/table-of-contents\";i:0;s:9:\"uagb\/tabs\";i:0;s:15:\"uagb\/tabs-child\";i:0;s:18:\"uagb\/taxonomy-list\";i:0;s:9:\"uagb\/team\";i:0;s:16:\"uagb\/testimonial\";i:0;s:14:\"uagb\/wp-search\";i:0;s:19:\"uagb\/instagram-feed\";i:0;s:10:\"uagb\/login\";i:0;s:17:\"uagb\/loop-builder\";i:0;s:18:\"uagb\/loop-category\";i:0;s:20:\"uagb\/loop-pagination\";i:0;s:15:\"uagb\/loop-reset\";i:0;s:16:\"uagb\/loop-search\";i:0;s:14:\"uagb\/loop-sort\";i:0;s:17:\"uagb\/loop-wrapper\";i:0;s:13:\"uagb\/register\";i:0;s:19:\"uagb\/register-email\";i:0;s:24:\"uagb\/register-first-name\";i:0;s:23:\"uagb\/register-last-name\";i:0;s:22:\"uagb\/register-password\";i:0;s:30:\"uagb\/register-reenter-password\";i:0;s:19:\"uagb\/register-terms\";i:0;s:22:\"uagb\/register-username\";i:0;}"],"_uag_css_file_name":["uag-css-31.css"],"_uag_js_file_name":["uag-js-31.js"],"_uagb_last_spectra_edit":["1776993643"],"_uag_page_assets":["a:9:{s:3:\"css\";s:74384:\".wp-block-uagb-container{display:flex;position:relative;box-sizing:border-box;transition-property:box-shadow;transition-duration:.2s;transition-timing-function:ease}.wp-block-uagb-container .spectra-container-link-overlay{bottom:0;left:0;position:absolute;right:0;top:0;z-index:10}.wp-block-uagb-container.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:flex;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}.wp-block-uagb-container .wp-block-uagb-blockquote,.wp-block-uagb-container .wp-block-spectra-pro-login,.wp-block-uagb-container .wp-block-spectra-pro-register{margin:unset}.wp-block-uagb-container .uagb-container__video-wrap{height:100%;width:100%;top:0;left:0;position:absolute;overflow:hidden;-webkit-transition:opacity 1s;-o-transition:opacity 1s;transition:opacity 1s}.wp-block-uagb-container .uagb-container__video-wrap video{max-width:100%;width:100%;height:100%;margin:0;line-height:1;border:none;display:inline-block;vertical-align:baseline;-o-object-fit:cover;object-fit:cover;background-size:cover}.wp-block-uagb-container.uagb-layout-grid{display:grid;width:100%}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap{display:inherit;width:inherit}.wp-block-uagb-container.uagb-layout-grid>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.uagb-is-root-container>.wp-block-uagb-container{max-width:unset !important;width:unset !important}.wp-block-uagb-container.uagb-layout-grid.alignwide.uagb-is-root-container{margin-left:auto;margin-right:auto}.wp-block-uagb-container.uagb-layout-grid.alignfull.uagb-is-root-container .uagb-container-inner-blocks-wrap{display:inherit;position:relative;box-sizing:border-box;margin-left:auto !important;margin-right:auto !important}body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-info-box),body .wp-block-uagb-container>.uagb-container-inner-blocks-wrap,body .wp-block-uagb-container>*:not(.wp-block-uagb-container):not(.wp-block-uagb-column):not(.wp-block-uagb-container):not(.wp-block-uagb-section):not(.uagb-container__shape):not(.uagb-container__video-wrap):not(.wp-block-spectra-pro-register):not(.wp-block-spectra-pro-login):not(.uagb-slider-container):not(.spectra-container-link-overlay):not(.spectra-image-gallery__control-lightbox):not(.wp-block-uagb-lottie):not(.uagb-faq__outer-wrap){min-width:unset !important;width:100%;position:relative}body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>.wp-block-uagb-container ol,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap>ul,body .ast-container .wp-block-uagb-container>.uagb-container-inner-blocks-wrap ol{max-width:-webkit-fill-available;margin-block-start:0;margin-block-end:0;margin-left:20px}.ast-plain-container .editor-styles-wrapper .block-editor-block-list__layout.is-root-container .uagb-is-root-container.wp-block-uagb-container.alignwide{margin-left:auto;margin-right:auto}.uagb-container__shape{overflow:hidden;position:absolute;left:0;width:100%;line-height:0;direction:ltr}.uagb-container__shape-top{top:-3px}.uagb-container__shape-bottom{bottom:-3px}.uagb-container__shape.uagb-container__invert.uagb-container__shape-bottom,.uagb-container__shape.uagb-container__invert.uagb-container__shape-top{-webkit-transform:rotate(180deg);-ms-transform:rotate(180deg);transform:rotate(180deg)}.uagb-container__shape.uagb-container__shape-flip svg{transform:translateX(-50%) rotateY(180deg)}.uagb-container__shape svg{display:block;width:-webkit-calc(100% + 1.3px);width:calc(100% + 1.3px);position:relative;left:50%;-webkit-transform:translateX(-50%);-ms-transform:translateX(-50%);transform:translateX(-50%)}.uagb-container__shape .uagb-container__shape-fill{-webkit-transform-origin:center;-ms-transform-origin:center;transform-origin:center;-webkit-transform:rotateY(0deg);transform:rotateY(0deg)}.uagb-container__shape.uagb-container__shape-above-content{z-index:9;pointer-events:none}.nv-single-page-wrap .nv-content-wrap.entry-content .wp-block-uagb-container.alignfull{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw)}@media only screen and (max-width: 767px){.wp-block-uagb-container .wp-block-uagb-advanced-heading{width:-webkit-fill-available}}.wp-block-uagb-image--align-none{justify-content:center}.wp-block-uagb-advanced-heading h1,.wp-block-uagb-advanced-heading h2,.wp-block-uagb-advanced-heading h3,.wp-block-uagb-advanced-heading h4,.wp-block-uagb-advanced-heading h5,.wp-block-uagb-advanced-heading h6,.wp-block-uagb-advanced-heading p,.wp-block-uagb-advanced-heading div{word-break:break-word}.wp-block-uagb-advanced-heading .uagb-heading-text{margin:0}.wp-block-uagb-advanced-heading .uagb-desc-text{margin:0}.wp-block-uagb-advanced-heading .uagb-separator{font-size:0;border-top-style:solid;display:inline-block;margin:0 0 10px 0}.wp-block-uagb-advanced-heading .uagb-highlight{color:#f78a0c;border:0;transition:all .3s ease}.uag-highlight-toolbar{border-left:0;border-top:0;border-bottom:0;border-radius:0;border-right-color:#1e1e1e}.uag-highlight-toolbar .components-button{border-radius:0;outline:none}.uag-highlight-toolbar .components-button.is-primary{color:#fff}.uagb-icon-list__wrap{display:flex;align-items:flex-start;justify-content:flex-start}.wp-block-uagb-icon-list-child{padding:0;transition:all .2s;display:inline-flex;color:#3a3a3a;align-items:center;text-decoration:none;box-shadow:none}.wp-block-uagb-icon-list-child span.uagb-icon-list__source-wrap{display:block;align-items:center}.uagb-icon-list__source-wrap svg{display:block}.uagb-icon-list__source-image{width:40px}.uagb-icon-list__outer-wrap .uagb-icon-list__content-wrap{color:#3a3a3a;display:flex;align-items:center}.wp-block-uagb-icon-list-child{position:relative}.wp-block-uagb-icon-list-child>a{position:absolute;top:0;left:0;width:100%;height:100%}img.uagb-icon-list__source-image{max-width:unset}.wp-block-uagb-icon-list-child .uagb-icon-list__label{word-break:break-word}.uagb-buttons__outer-wrap .uagb-buttons__wrap{display:inline-flex;width:100%}.uagb-buttons__outer-wrap.uagb-btn__small-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__small-btn .uagb-buttons-repeater.ast-outline-button{padding:5px 10px}.uagb-buttons__outer-wrap.uagb-btn__medium-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__medium-btn .uagb-buttons-repeater.ast-outline-button{padding:12px 24px}.uagb-buttons__outer-wrap.uagb-btn__large-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__large-btn .uagb-buttons-repeater.ast-outline-button{padding:20px 30px}.uagb-buttons__outer-wrap.uagb-btn__extralarge-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn__extralarge-btn .uagb-buttons-repeater.ast-outline-button{padding:30px 65px}@media(max-width: 976px){.uagb-buttons__outer-wrap.uagb-btn-tablet__small-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__small-btn .uagb-buttons-repeater.ast-outline-button{padding:5px 10px}.uagb-buttons__outer-wrap.uagb-btn-tablet__medium-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__medium-btn .uagb-buttons-repeater.ast-outline-button{padding:12px 24px}.uagb-buttons__outer-wrap.uagb-btn-tablet__large-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__large-btn .uagb-buttons-repeater.ast-outline-button{padding:20px 30px}.uagb-buttons__outer-wrap.uagb-btn-tablet__extralarge-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-tablet__extralarge-btn .uagb-buttons-repeater.ast-outline-button{padding:30px 65px}}@media(max-width: 767px){.uagb-buttons__outer-wrap.uagb-btn-mobile__small-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__small-btn .uagb-buttons-repeater.ast-outline-button{padding:5px 10px}.uagb-buttons__outer-wrap.uagb-btn-mobile__medium-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__medium-btn .uagb-buttons-repeater.ast-outline-button{padding:12px 24px}.uagb-buttons__outer-wrap.uagb-btn-mobile__large-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__large-btn .uagb-buttons-repeater.ast-outline-button{padding:20px 30px}.uagb-buttons__outer-wrap.uagb-btn-mobile__extralarge-btn .uagb-buttons-repeater.wp-block-button__link:not(.is-style-outline),.uagb-buttons__outer-wrap.uagb-btn-mobile__extralarge-btn .uagb-buttons-repeater.ast-outline-button{padding:30px 65px}}.uagb-buttons__outer-wrap .uagb-buttons-repeater{display:flex;justify-content:center;align-items:center;transition:box-shadow .2s ease}.uagb-buttons__outer-wrap .uagb-buttons-repeater a.uagb-button__link{display:flex;justify-content:center}.uagb-buttons__outer-wrap .uagb-buttons-repeater .uagb-button__icon{font-size:inherit;display:flex;align-items:center}.uagb-buttons__outer-wrap .uagb-buttons-repeater .uagb-button__icon svg{fill:currentColor;width:inherit;height:inherit}.wp-block-uagb-container.uagb-block-a015d3fa .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-a015d3fa .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-a015d3fa .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-a015d3fa .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-a015d3fa .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-a015d3fa{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a015d3fa > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1170px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-a015d3fa{min-height: 476px;box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;background-repeat: no-repeat;background-position: 50% 50%;background-size: cover;background-attachment: scroll;background-image: url(https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2024\/01\/competitive-advantages-banner.jpg);background-clip: padding-box;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-advanced-heading.uagb-block-ee0f8e68.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-1);}.wp-block-uagb-advanced-heading.uagb-block-ee0f8e68.wp-block-uagb-advanced-heading {text-align: center;margin-top: 100px;margin-right: 0px;margin-bottom: 7px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-ee0f8e68.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-ee0f8e68.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ee0f8e68.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ee0f8e68.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-ee0f8e68 .uagb-heading-text{font-family: \"Poppins\";font-weight: 500;font-size: 45px;line-height: 58px;}.wp-block-uagb-container.uagb-block-7857a908 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-7857a908 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-7857a908 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-7857a908 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-7857a908 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7857a908{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7857a908 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1170px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 70px;}.wp-block-uagb-container.uagb-block-7857a908{box-shadow: 0px 0px   #00000070 ;padding-top: 100px;padding-bottom: 70px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: #f9f9f9;row-gap: 0px;column-gap: 70px;}.wp-block-uagb-container.uagb-block-e6c4ffc9 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-e6c4ffc9 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-e6c4ffc9 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-e6c4ffc9 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-e6c4ffc9 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e6c4ffc9{max-width: 38%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e6c4ffc9 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1170px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-e6c4ffc9{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-advanced-heading.uagb-block-9eff9916.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-2);}.wp-block-uagb-advanced-heading.uagb-block-9eff9916.wp-block-uagb-advanced-heading {margin-top: 0px;margin-right: 0px;margin-bottom: 16px;margin-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-9eff9916.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-9eff9916.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-9eff9916.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-9eff9916.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-9eff9916 .uagb-heading-text{font-family: \"Poppins\";font-weight: 500;font-size: 26px;line-height: 34px;}.wp-block-uagb-advanced-heading.uagb-block-36ffe861.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-3);}.wp-block-uagb-advanced-heading.uagb-block-36ffe861.wp-block-uagb-advanced-heading {margin-top: 0em;margin-right: 0em;margin-bottom: 1.75em;margin-left: 0em;}.wp-block-uagb-advanced-heading.uagb-block-36ffe861.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-36ffe861.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-36ffe861.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-36ffe861.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-36ffe861 .uagb-heading-text{font-family: \"Poppins\";text-transform: none;font-weight: 400;font-size: 14px;line-height: 26px;}.wp-block-uagb-advanced-heading.uagb-block-a3509b53.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-3);}.wp-block-uagb-advanced-heading.uagb-block-a3509b53.wp-block-uagb-advanced-heading {margin-top: 0em;margin-right: 0em;margin-bottom: 1.75em;margin-left: 0em;}.wp-block-uagb-advanced-heading.uagb-block-a3509b53.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-a3509b53.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a3509b53.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a3509b53.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-a3509b53 .uagb-heading-text{font-family: \"Poppins\";text-transform: none;font-weight: 400;font-size: 14px;line-height: 26px;}.wp-block-uagb-advanced-heading.uagb-block-6cfbd83f.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-3);}.wp-block-uagb-advanced-heading.uagb-block-6cfbd83f.wp-block-uagb-advanced-heading {margin-top: 0em;margin-right: 0em;margin-bottom: 1.75em;margin-left: 0em;}.wp-block-uagb-advanced-heading.uagb-block-6cfbd83f.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-6cfbd83f.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-6cfbd83f.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-6cfbd83f.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-6cfbd83f .uagb-heading-text{font-family: \"Poppins\";text-transform: none;font-weight: 400;font-size: 14px;line-height: 26px;}.wp-block-uagb-container.uagb-block-9fc3be8e .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-9fc3be8e .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-9fc3be8e .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-9fc3be8e .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-9fc3be8e .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9fc3be8e{max-width: 65%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9fc3be8e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1170px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-9fc3be8e{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-59342b4b .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-59342b4b .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-59342b4b .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-59342b4b .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-59342b4b .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-59342b4b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-59342b4b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1170px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: row;align-items: flex-start;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 70px;}.wp-block-uagb-container.uagb-block-59342b4b{box-shadow: 0px 0px   #00000070 ;padding-top: 80px;padding-bottom: 80px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: var(--ast-global-color-1);row-gap: 0px;column-gap: 70px;}.wp-block-uagb-container.uagb-block-24abe809 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-24abe809 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-24abe809 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-24abe809 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-24abe809 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-24abe809{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-24abe809 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1170px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-24abe809{box-shadow: 0px 0px   #00000070 ;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;overflow: visible;order: initial;border-color: inherit;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-advanced-heading.uagb-block-0aa75fdc.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-2);}.wp-block-uagb-advanced-heading.uagb-block-0aa75fdc.wp-block-uagb-advanced-heading {margin-top: 0px;margin-right: 0px;margin-bottom: 30px;margin-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-0aa75fdc.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-0aa75fdc.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-0aa75fdc.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-0aa75fdc.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-0aa75fdc .uagb-heading-text{font-family: \"Poppins\";font-weight: 500;font-size: 26px;line-height: 34px;}.wp-block-uagb-icon-list.uagb-block-49bb9b74 .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-49bb9b74 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;color: #1e73be;fill: #1e73be;}.wp-block-uagb-icon-list.uagb-block-49bb9b74 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{border-color: #0170B9;padding: 0px;border-radius: 100px;border-width: 0px;align-self: flex-start;}.wp-block-uagb-icon-list.uagb-block-49bb9b74 .wp-block-uagb-icon-list-child .uagb-icon-list__label{font-size: 14px;font-family: \"Poppins\";text-decoration: !important;font-weight: 400;line-height: 24px;color: var(--ast-global-color-3);}.wp-block-uagb-icon-list.uagb-block-49bb9b74 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;margin-top: 0em;margin-right: 0em;margin-bottom: 0em;margin-left: 0em;padding-top: 0px;padding-right: 50px;padding-bottom: 0px;padding-left: 50px;}.wp-block-uagb-icon-list.uagb-block-49bb9b74 .uagb-icon-list__label{text-align: left;}.wp-block-uagb-icon-list.uagb-block-49bb9b74 .wp-block-uagb-icon-list-child{font-family: \"Poppins\";text-decoration: !important;font-weight: 400;font-size: 14px;line-height: 24px;}.wp-block-uagb-icon-list.uagb-block-49bb9b74.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 25px;}.wp-block-uagb-icon-list.uagb-block-49bb9b74 .uagb-icon-list__source-wrap{margin-right: 8px;}.uagb-block-c00bbf14.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-c00bbf14.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-43b973c0.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{fill: #1e73be !important;color: #1e73be !important;}.uagb-block-43b973c0.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-43b973c0.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-718d1bc4.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{fill: #1e73be !important;color: #1e73be !important;}.uagb-block-718d1bc4.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-718d1bc4.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-de00e7f3.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{fill: #1e73be !important;color: #1e73be !important;}.uagb-block-de00e7f3.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-de00e7f3.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-7927f8a6.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{fill: #1e73be !important;color: #1e73be !important;}.uagb-block-7927f8a6.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-7927f8a6.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-2145a42c.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{fill: #1e73be !important;color: #1e73be !important;}.uagb-block-2145a42c.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-2145a42c.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-1f396213.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{fill: #1e73be !important;color: #1e73be !important;}.uagb-block-1f396213.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-1f396213.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-b5a69f0e.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{fill: #1e73be !important;color: #1e73be !important;}.uagb-block-b5a69f0e.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-b5a69f0e.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-7f0ab4c8.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{fill: #1e73be !important;color: #1e73be !important;}.uagb-block-7f0ab4c8.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-7f0ab4c8.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-c0c764ee.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{fill: #1e73be !important;color: #1e73be !important;}.uagb-block-c0c764ee.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-c0c764ee.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-afa76cb7.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{fill: #1e73be !important;color: #1e73be !important;}.uagb-block-afa76cb7.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-afa76cb7.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-553988af.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{fill: #1e73be !important;color: #1e73be !important;}.uagb-block-553988af.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-553988af.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-32b44efe.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{fill: #1e73be !important;color: #1e73be !important;}.uagb-block-32b44efe.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-32b44efe.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-c4d5189a.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{fill: #1e73be !important;color: #1e73be !important;}.uagb-block-c4d5189a.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-c4d5189a.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-b1bfb453.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{fill: #1e73be !important;color: #1e73be !important;}.uagb-block-b1bfb453.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-b1bfb453.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-53f5fb63.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{fill: #1e73be !important;color: #1e73be !important;}.uagb-block-53f5fb63.wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.uagb-block-53f5fb63.wp-block-uagb-icon-list-child:hover .uagb-icon-list__source-wrap{background:  !important;border-color:  !important;}.wp-block-uagb-advanced-heading.uagb-block-7d6271a6.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-3);}.wp-block-uagb-advanced-heading.uagb-block-7d6271a6.wp-block-uagb-advanced-heading {margin-top: 0em;margin-right: 0em;margin-bottom: 1.75em;margin-left: 0em;}.wp-block-uagb-advanced-heading.uagb-block-7d6271a6.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-7d6271a6.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-7d6271a6.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-7d6271a6.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-7d6271a6 .uagb-heading-text{font-family: \"Poppins\";text-transform: none;font-weight: 400;font-size: 14px;line-height: 26px;}.wp-block-uagb-container.uagb-block-1fa6aee9 .uagb-container__shape-top svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-1fa6aee9 .uagb-container__shape.uagb-container__shape-top .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-1fa6aee9 .uagb-container__shape-bottom svg{width: calc( 100% + 1.3px );}.wp-block-uagb-container.uagb-block-1fa6aee9 .uagb-container__shape.uagb-container__shape-bottom .uagb-container__shape-fill{fill: rgba(51,51,51,1);}.wp-block-uagb-container.uagb-block-1fa6aee9 .uagb-container__video-wrap video{opacity: 1;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1fa6aee9{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1fa6aee9 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1170px);max-width: var(--inner-content-custom-width);width: 100%;flex-direction: column;align-items: center;justify-content: center;flex-wrap: nowrap;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-1fa6aee9{box-shadow: 0px 0px   #00000070 ;padding-top: 85px;padding-bottom: 85px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;overflow: visible;order: initial;border-color: inherit;background-color: #f2f2f2;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-advanced-heading.uagb-block-0cd02049.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-2);}.wp-block-uagb-advanced-heading.uagb-block-0cd02049.wp-block-uagb-advanced-heading {text-align: center;}.wp-block-uagb-advanced-heading.uagb-block-0cd02049.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-0cd02049.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-0cd02049.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-0cd02049.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-0cd02049 .uagb-heading-text{font-family: \"Poppins\";font-weight: 500;font-size: 32px;line-height: 42px;}.wp-block-uagb-advanced-heading.uagb-block-15f800a4.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-3);}.wp-block-uagb-advanced-heading.uagb-block-15f800a4.wp-block-uagb-advanced-heading {text-align: center;margin-top: 30px;margin-right: 0px;margin-bottom: 70px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-15f800a4.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-15f800a4.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-15f800a4.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-15f800a4.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-15f800a4 .uagb-heading-text{font-family: \"Poppins\";font-weight: 400;font-size: 14px;line-height: 26px;}.wp-block-uagb-advanced-heading.uagb-block-94f42e7f.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-1);}.wp-block-uagb-advanced-heading.uagb-block-94f42e7f.wp-block-uagb-advanced-heading {text-align: center;margin-top: 0em;margin-right: 0em;margin-bottom: 0.4em;margin-left: 0em;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-94f42e7f.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-94f42e7f.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-94f42e7f.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-94f42e7f.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-94f42e7f .uagb-heading-text{font-family: \"Poppins\";font-weight: 500;font-size: 32px;line-height: 42px;}.wp-block-uagb-advanced-heading.uagb-block-62798e90.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-1);}.wp-block-uagb-advanced-heading.uagb-block-62798e90.wp-block-uagb-advanced-heading {text-align: center;margin-top: 48px;margin-right: 0px;margin-bottom: 48px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-62798e90.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-62798e90.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-62798e90.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-62798e90.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-62798e90 .uagb-heading-text{font-family: \"Poppins\";font-weight: 500;font-size: 16px;line-height: 21px;}.uagb-block-b44e2020.wp-block-uagb-buttons.uagb-buttons__outer-wrap .uagb-buttons__wrap {gap: 10px;}.uagb-block-b44e2020.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-b44e2020 .uagb-buttons-repeater:not(.wp-block-button__link){font-family: \"Poppins\";font-weight: 500;font-size: 0.9em;line-height: 1.3em;letter-spacing: 0.1em;padding-top: 1.2em;padding-bottom: 1.2em;padding-left: 2.8em;padding-right: 2.8em;}.uagb-block-b44e2020 .uagb-button__wrapper .uagb-buttons-repeater.wp-block-button__link{font-family: \"Poppins\";font-weight: 500;font-size: 0.9em;line-height: 1.3em;letter-spacing: 0.1em;padding-top: 1.2em;padding-bottom: 1.2em;padding-left: 2.8em;padding-right: 2.8em;}.uagb-block-b44e2020 .uagb-button__wrapper .uagb-buttons-repeater.ast-outline-button{font-family: \"Poppins\";font-weight: 500;font-size: 0.9em;line-height: 1.3em;letter-spacing: 0.1em;padding-top: 1.2em;padding-bottom: 1.2em;padding-left: 2.8em;padding-right: 2.8em;}.uagb-block-b44e2020 .uagb-button__wrapper{margin-top: 0px;margin-bottom: 0px;margin-left: 0px;margin-right: 0px;}.wp-block-uagb-buttons .uagb-block-bdede035 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-bdede035 .uagb-buttons-repeater .uagb-button__icon > svg{width: 15px;height: 15px;}.wp-block-uagb-buttons .uagb-block-bdede035 .uagb-buttons-repeater .uagb-button__icon-position-after{margin-left: 8px;}.wp-block-uagb-buttons .uagb-block-bdede035 .uagb-buttons-repeater .uagb-button__icon-position-before{margin-right: 8px;}.wp-block-uagb-advanced-heading.uagb-block-694562ab.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-1);}.wp-block-uagb-advanced-heading.uagb-block-694562ab.wp-block-uagb-advanced-heading {text-align: center;margin-top: 0em;margin-right: 0em;margin-bottom: 0.4em;margin-left: 0em;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-694562ab.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-694562ab.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-694562ab.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-694562ab.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-694562ab .uagb-heading-text{font-family: \"Poppins\";font-weight: 500;font-size: 32px;line-height: 42px;}.wp-block-uagb-advanced-heading.uagb-block-be16258a.wp-block-uagb-advanced-heading .uagb-heading-text{color: var(--ast-global-color-1);}.wp-block-uagb-advanced-heading.uagb-block-be16258a.wp-block-uagb-advanced-heading {text-align: center;margin-top: 48px;margin-right: 0px;margin-bottom: 48px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-be16258a.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-be16258a.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-be16258a.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-be16258a.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-be16258a .uagb-heading-text{font-family: \"Poppins\";font-weight: 500;font-size: 16px;line-height: 21px;}.uagb-block-abdda5ee.wp-block-uagb-buttons.uagb-buttons__outer-wrap .uagb-buttons__wrap {gap: 10px;}.uagb-block-abdda5ee.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-abdda5ee .uagb-buttons-repeater:not(.wp-block-button__link){font-family: \"Poppins\";font-weight: 500;font-size: 0.9em;line-height: 1.3em;letter-spacing: 0.1em;padding-top: 1.2em;padding-bottom: 1.2em;padding-left: 2.8em;padding-right: 2.8em;}.uagb-block-abdda5ee .uagb-button__wrapper .uagb-buttons-repeater.wp-block-button__link{font-family: \"Poppins\";font-weight: 500;font-size: 0.9em;line-height: 1.3em;letter-spacing: 0.1em;padding-top: 1.2em;padding-bottom: 1.2em;padding-left: 2.8em;padding-right: 2.8em;}.uagb-block-abdda5ee .uagb-button__wrapper .uagb-buttons-repeater.ast-outline-button{font-family: \"Poppins\";font-weight: 500;font-size: 0.9em;line-height: 1.3em;letter-spacing: 0.1em;padding-top: 1.2em;padding-bottom: 1.2em;padding-left: 2.8em;padding-right: 2.8em;}.wp-block-uagb-buttons .uagb-block-f26a3928 .uagb-button__wrapper  .uagb-buttons-repeater.wp-block-button__link{box-shadow: 0px 0px 0 #00000026;}.wp-block-uagb-buttons .uagb-block-f26a3928 .uagb-buttons-repeater .uagb-button__icon > svg{width: 15px;height: 15px;}.wp-block-uagb-buttons .uagb-block-f26a3928 .uagb-buttons-repeater .uagb-button__icon-position-after{margin-left: 8px;}.wp-block-uagb-buttons .uagb-block-f26a3928 .uagb-buttons-repeater .uagb-button__icon-position-before{margin-right: 8px;}@media only screen and (max-width: 976px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-a015d3fa{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a015d3fa > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-a015d3fa{min-height: 350px;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-image: url(https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2024\/01\/competitive-advantages-banner.jpg);background-clip: padding-box;}.wp-block-uagb-advanced-heading.uagb-block-ee0f8e68 .uagb-heading-text{font-size: 25px;line-height: 35px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7857a908{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7857a908 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;column-gap: 30px;}.wp-block-uagb-container.uagb-block-7857a908{padding-top: 60px;padding-bottom: 60px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: #f9f9f9;column-gap: 30px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e6c4ffc9{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e6c4ffc9 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-e6c4ffc9{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-advanced-heading.uagb-block-9eff9916 .uagb-heading-text{font-size: 22px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9fc3be8e{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9fc3be8e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-9fc3be8e{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-59342b4b{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-59342b4b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;column-gap: 30px;}.wp-block-uagb-container.uagb-block-59342b4b{padding-top: 60px;padding-bottom: 60px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: var(--ast-global-color-1);column-gap: 30px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-24abe809{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-24abe809 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-container.uagb-block-24abe809{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;row-gap: 0px;column-gap: 0px;}.wp-block-uagb-advanced-heading.uagb-block-0aa75fdc .uagb-heading-text{font-size: 22px;}.wp-block-uagb-icon-list.uagb-block-49bb9b74 .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-49bb9b74 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-49bb9b74 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap {padding: 0px;border-width: 0px;align-self: flex-start;}.wp-block-uagb-icon-list.uagb-block-49bb9b74 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;}.wp-block-uagb-icon-list.uagb-block-49bb9b74.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 25px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1fa6aee9{width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1fa6aee9 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 1024px);max-width: var(--inner-content-custom-width);width: 100%;}.wp-block-uagb-container.uagb-block-1fa6aee9{padding-top: 85px;padding-bottom: 85px;padding-left: 0px;padding-right: 0px;margin-top:  !important;margin-bottom:  !important;order: initial;background-color: #f2f2f2;}.uagb-block-b44e2020.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-b44e2020.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.uagb-block-abdda5ee.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-abdda5ee.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}}@media only screen and (max-width: 767px) {.wp-block-uagb-container.uagb-is-root-container .uagb-block-a015d3fa{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-a015d3fa > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-a015d3fa{min-height: 320px;padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-image: url(https:\/\/staging.accordglobaltrade.com\/wp-content\/uploads\/2024\/01\/competitive-advantages-banner.jpg);background-clip: padding-box;}.wp-block-uagb-advanced-heading.uagb-block-ee0f8e68 .uagb-heading-text{font-size: 20px;line-height: 25px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-7857a908{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-7857a908 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 30px;column-gap: 40px;}.wp-block-uagb-container.uagb-block-7857a908{padding-top: 40px;padding-bottom: 40px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 30px;column-gap: 40px;order: initial;background-color: #f9f9f9;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-e6c4ffc9{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-e6c4ffc9 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-e6c4ffc9{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;flex-wrap: wrap;}.wp-block-uagb-advanced-heading.uagb-block-9eff9916.wp-block-uagb-advanced-heading {padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 15px;margin-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-9eff9916 .uagb-heading-text{font-size: 22px;line-height: 30px;}.wp-block-uagb-advanced-heading.uagb-block-36ffe861.wp-block-uagb-advanced-heading {margin-top: 0px;margin-right: 0px;margin-bottom: 10px;margin-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-36ffe861 .uagb-heading-text{font-size: 14px;line-height: 26px;}.wp-block-uagb-advanced-heading.uagb-block-a3509b53.wp-block-uagb-advanced-heading {margin-top: 0px;margin-right: 0px;margin-bottom: 10px;margin-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-6cfbd83f.wp-block-uagb-advanced-heading {margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-9fc3be8e{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-9fc3be8e > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-9fc3be8e{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;flex-wrap: wrap;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-59342b4b{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-59342b4b > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;row-gap: 30px;column-gap: 40px;}.wp-block-uagb-container.uagb-block-59342b4b{padding-top: 40px;padding-bottom: 40px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;row-gap: 30px;column-gap: 40px;order: initial;background-color: var(--ast-global-color-1);}.wp-block-uagb-container.uagb-is-root-container .uagb-block-24abe809{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-24abe809 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-24abe809{padding-top: 0px;padding-bottom: 0px;padding-left: 0px;padding-right: 0px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;flex-wrap: wrap;}.wp-block-uagb-advanced-heading.uagb-block-0aa75fdc.wp-block-uagb-advanced-heading {padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 0px;margin-right: 0px;margin-bottom: 15px;margin-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-0aa75fdc .uagb-heading-text{font-size: 22px;}.wp-block-uagb-icon-list.uagb-block-49bb9b74 .uagb-icon-list__source-image{width: 16px;}.wp-block-uagb-icon-list.uagb-block-49bb9b74 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap svg{width: 16px;height: 16px;font-size: 16px;}.wp-block-uagb-icon-list.uagb-block-49bb9b74 .wp-block-uagb-icon-list-child .uagb-icon-list__source-wrap{padding: 0px;border-width: 0px;align-self: flex-start;}.wp-block-uagb-icon-list.uagb-block-49bb9b74 .uagb-icon-list__wrap{display: flex;flex-direction: column;justify-content: center;-webkit-box-pack: center;-ms-flex-pack: center;-webkit-box-align: flex-start;-ms-flex-align: flex-start;align-items: flex-start;margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;}.wp-block-uagb-icon-list.uagb-block-49bb9b74.wp-block-uagb-icon-list .wp-block-uagb-icon-list-child{margin-left: 0;margin-right: 0;margin-bottom: 25px;}.wp-block-uagb-advanced-heading.uagb-block-7d6271a6.wp-block-uagb-advanced-heading {margin-top: 0px;margin-right: 0px;margin-bottom: 0px;margin-left: 0px;}.wp-block-uagb-container.uagb-is-root-container .uagb-block-1fa6aee9{max-width: 100%;width: 100%;}.wp-block-uagb-container.uagb-is-root-container.alignfull.uagb-block-1fa6aee9 > .uagb-container-inner-blocks-wrap{--inner-content-custom-width: min( 100%, 767px);max-width: var(--inner-content-custom-width);width: 100%;flex-wrap: wrap;}.wp-block-uagb-container.uagb-block-1fa6aee9{padding-top: 40px;padding-bottom: 40px;padding-left: 20px;padding-right: 20px;margin-top: 0px !important;margin-bottom: 0px !important;margin-left: 0px;margin-right: 0px;order: initial;background-color: #f2f2f2;}.wp-block-uagb-advanced-heading.uagb-block-0cd02049 .uagb-heading-text{font-size: 22px;line-height: 30px;}.wp-block-uagb-advanced-heading.uagb-block-15f800a4.wp-block-uagb-advanced-heading {padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 20px;margin-right: 0px;margin-bottom: 30px;margin-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-15f800a4 .uagb-heading-text{font-size: 14px;line-height: 26px;}.wp-block-uagb-advanced-heading.uagb-block-94f42e7f .uagb-heading-text{font-size: 22px;line-height: 30px;}.wp-block-uagb-advanced-heading.uagb-block-62798e90.wp-block-uagb-advanced-heading {padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 30px;margin-right: 0px;margin-bottom: 30px;margin-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-62798e90 .uagb-heading-text{font-size: 16px;line-height: 26px;}.uagb-block-b44e2020.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-b44e2020.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}.wp-block-uagb-advanced-heading.uagb-block-694562ab .uagb-heading-text{font-size: 22px;line-height: 30px;}.wp-block-uagb-advanced-heading.uagb-block-be16258a.wp-block-uagb-advanced-heading {padding-top: 0px;padding-right: 0px;padding-bottom: 0px;padding-left: 0px;margin-top: 30px;margin-right: 0px;margin-bottom: 30px;margin-left: 0px;}.wp-block-uagb-advanced-heading.uagb-block-be16258a .uagb-heading-text{font-size: 16px;line-height: 26px;}.uagb-block-abdda5ee.uagb-buttons__outer-wrap .uagb-buttons__wrap {justify-content: center;align-items: center;}.uagb-block-abdda5ee.uagb-buttons__outer-wrap .uagb-buttons__wrap .wp-block-button{width: auto;}}.uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media(max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media(max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}.wp-block-uagb-image{display:flex}.wp-block-uagb-image__figure{position:relative;display:flex;flex-direction:column;max-width:100%;height:auto;margin:0}.wp-block-uagb-image__figure img{height:auto;display:flex;max-width:100%;transition:box-shadow .2s ease}.wp-block-uagb-image__figure>a{display:inline-block}.wp-block-uagb-image__figure figcaption{text-align:center;margin-top:.5em;margin-bottom:1em}.wp-block-uagb-image .components-placeholder.block-editor-media-placeholder .components-placeholder__instructions{align-self:center}.wp-block-uagb-image--align-left{text-align:left}.wp-block-uagb-image--align-right{text-align:right}.wp-block-uagb-image--align-center{text-align:center}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw);max-width:100vw;width:100vw;height:auto}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure img{height:auto;width:100% !important}.wp-block-uagb-image--align-wide .wp-block-uagb-image__figure img{height:auto;width:100%}.wp-block-uagb-image--layout-overlay__color-wrapper{position:absolute;left:0;top:0;right:0;bottom:0;opacity:.2;background:rgba(0,0,0,.5);transition:opacity .35s ease-in-out}.wp-block-uagb-image--layout-overlay-link{position:absolute;left:0;right:0;bottom:0;top:0}.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity:1}.wp-block-uagb-image--layout-overlay__inner{position:absolute;left:15px;right:15px;bottom:15px;top:15px;display:flex;align-items:center;justify-content:center;flex-direction:column;border-color:#fff;transition:.35s ease-in-out}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.top-center,.wp-block-uagb-image--layout-overlay__inner.top-right{justify-content:flex-start}.wp-block-uagb-image--layout-overlay__inner.bottom-left,.wp-block-uagb-image--layout-overlay__inner.bottom-center,.wp-block-uagb-image--layout-overlay__inner.bottom-right{justify-content:flex-end}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.center-left,.wp-block-uagb-image--layout-overlay__inner.bottom-left{align-items:flex-start}.wp-block-uagb-image--layout-overlay__inner.top-right,.wp-block-uagb-image--layout-overlay__inner.center-right,.wp-block-uagb-image--layout-overlay__inner.bottom-right{align-items:flex-end}.wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{color:#fff;transition:transform .35s,opacity .35s ease-in-out;transform:translate3d(0, 24px, 0);margin:0;line-height:1em}.wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width:30%;border-top-width:2px;border-top-color:#fff;border-top-style:solid;margin-bottom:10px;opacity:0;transition:transform .4s,opacity .4s ease-in-out;transform:translate3d(0, 30px, 0)}.wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity:0;overflow:visible;color:#fff;transition:transform .45s,opacity .45s ease-in-out;transform:translate3d(0, 35px, 0)}.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-heading,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-separator,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-caption{opacity:1;transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1.05)}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{width:calc(100% + 40px) !important;max-width:none !important;transform:translate3d(-40px, 0, 0);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-grayscale img{filter:grayscale(0%);transition:.35s ease-in-out}.wp-block-uagb-image--effect-grayscale:hover img{filter:grayscale(100%)}.wp-block-uagb-image--effect-blur img{filter:blur(0);transition:.35s ease-in-out}.wp-block-uagb-image--effect-blur:hover img{filter:blur(3px)}.uagb-block-8ddb406d.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-8ddb406d.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-8ddb406d.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-8ddb406d.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-8ddb406d.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-8ddb406d.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-8ddb406d.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-8ddb406d.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-8ddb406d.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-8ddb406d.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-8ddb406d.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-8ddb406d.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-8ddb406d.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-8ddb406d.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-8ddb406d.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}@media only screen and (max-width: 976px) {.uagb-block-8ddb406d.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}@media only screen and (max-width: 767px) {.uagb-block-8ddb406d.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}.wp-block-uagb-advanced-heading.uagb-block-35454055.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-35454055.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-35454055.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-35454055.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-1bc1662a.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-1bc1662a.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-1bc1662a.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-1bc1662a.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-86fe7c65.wp-block-uagb-advanced-heading .uagb-desc-text{margin-bottom: 15px;}.wp-block-uagb-advanced-heading.uagb-block-86fe7c65.wp-block-uagb-advanced-heading .uagb-highlight{font-style: normal;font-weight: Default;background: #007cba;color: #fff;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-86fe7c65.wp-block-uagb-advanced-heading .uagb-highlight::-moz-selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.wp-block-uagb-advanced-heading.uagb-block-86fe7c65.wp-block-uagb-advanced-heading .uagb-highlight::selection{color: #fff;background: #007cba;-webkit-text-fill-color: #fff;}.uagb-block-5eb5d2b8.wp-block-uagb-image{text-align: center;justify-content: center;align-self: center;}.uagb-block-5eb5d2b8 .wp-block-uagb-image__figure{align-items: center;}.uagb-block-5eb5d2b8.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-5eb5d2b8.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-5eb5d2b8.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-5eb5d2b8.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-5eb5d2b8.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-5eb5d2b8.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-5eb5d2b8.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-5eb5d2b8.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-5eb5d2b8.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-5eb5d2b8.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-5eb5d2b8.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 150px;height: auto;}.uagb-block-5eb5d2b8.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-5eb5d2b8.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-5eb5d2b8.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-5eb5d2b8.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}@media only screen and (max-width: 976px) {.uagb-block-5eb5d2b8.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 150px;height: auto;}}@media only screen and (max-width: 767px) {.uagb-block-5eb5d2b8.wp-block-uagb-image .wp-block-uagb-image__figure img{width: 150px;height: auto;}}.uagb-block-02bc7fcb.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-02bc7fcb.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-02bc7fcb.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-02bc7fcb.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-02bc7fcb.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-02bc7fcb.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-02bc7fcb.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-02bc7fcb.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-02bc7fcb.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-02bc7fcb.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-02bc7fcb.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-02bc7fcb.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-02bc7fcb.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-02bc7fcb.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-02bc7fcb.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}@media only screen and (max-width: 976px) {.uagb-block-02bc7fcb.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}@media only screen and (max-width: 767px) {.uagb-block-02bc7fcb.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}\";s:2:\"js\";s:260:\"document.addEventListener(\"DOMContentLoaded\", function(){ window.addEventListener( 'load', function() {\n\tUAGBButtonChild.init( '.uagb-block-bdede035' );\n});\nwindow.addEventListener( 'load', function() {\n\tUAGBButtonChild.init( '.uagb-block-f26a3928' );\n});\n });\";s:18:\"current_block_list\";a:22:{i:0;s:14:\"uagb\/container\";i:1;s:21:\"uagb\/advanced-heading\";i:2;s:20:\"bcn\/breadcrumb-trail\";i:4;s:10:\"core\/image\";i:5;s:14:\"uagb\/icon-list\";i:6;s:20:\"uagb\/icon-list-child\";i:7;s:12:\"core\/columns\";i:8;s:11:\"core\/column\";i:9;s:10:\"core\/cover\";i:10;s:12:\"uagb\/buttons\";i:11;s:18:\"uagb\/buttons-child\";i:12;s:10:\"core\/group\";i:13;s:12:\"core\/heading\";i:14;s:15:\"core\/categories\";i:15;s:10:\"uagb\/image\";i:16;s:14:\"core\/paragraph\";i:17;s:17:\"core\/latest-posts\";i:18;s:17:\"core\/widget-group\";i:19;s:11:\"core\/search\";i:20;s:14:\"core\/tag-cloud\";i:21;s:17:\"core\/social-links\";i:22;s:16:\"core\/social-link\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";i:1788309791;s:6:\"gfonts\";a:1:{s:7:\"Poppins\";a:2:{s:10:\"fontfamily\";s:7:\"Poppins\";s:12:\"fontvariants\";a:2:{i:0;s:3:\"500\";i:1;s:3:\"400\";}}}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false,"ultp_layout_landscape_large":false,"ultp_layout_landscape":false,"ultp_layout_portrait":false,"ultp_layout_square":false},"uagb_author_info":{"display_name":"trades_admin","author_link":"https:\/\/staging.accordglobaltrade.com\/zh\/author\/trades_admin\/"},"uagb_comment_info":0,"uagb_excerpt":"Competitive Advantages Access to International Markets Accord Global Trade has competitive advantages over other companies by being one of the few companies that provide exceptional and customized solutions to both exporters and importers. Our highly qualified trade and investment experts provide market visibility and business intelligence in a world where regulatory, natural, and geopolitical shifts&hellip;","_links":{"self":[{"href":"https:\/\/staging.accordglobaltrade.com\/zh\/wp-json\/wp\/v2\/pages\/31","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.accordglobaltrade.com\/zh\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/staging.accordglobaltrade.com\/zh\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/staging.accordglobaltrade.com\/zh\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/staging.accordglobaltrade.com\/zh\/wp-json\/wp\/v2\/comments?post=31"}],"version-history":[{"count":48,"href":"https:\/\/staging.accordglobaltrade.com\/zh\/wp-json\/wp\/v2\/pages\/31\/revisions"}],"predecessor-version":[{"id":2153,"href":"https:\/\/staging.accordglobaltrade.com\/zh\/wp-json\/wp\/v2\/pages\/31\/revisions\/2153"}],"wp:attachment":[{"href":"https:\/\/staging.accordglobaltrade.com\/zh\/wp-json\/wp\/v2\/media?parent=31"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}